{"id":57327,"date":"2024-10-31T15:04:09","date_gmt":"2024-10-31T14:04:09","guid":{"rendered":"https:\/\/www.km77.com\/revista\/?p=57327"},"modified":"2024-10-31T15:04:12","modified_gmt":"2024-10-31T14:04:12","slug":"km77-con-las-victimas-y-afectados-por-las-riadas","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/","title":{"rendered":"km77 con las v\u00edctimas y afectados por las riadas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tras los sucesos, las cifras y la devastaci\u00f3n conocida ayer y hoy,  el objetivo con el que nos levantamos cada ma\u00f1ana cambia de foco. Nuestra actividad diaria de informar de coches lo mejor que sabemos pasa a un segundo plano y es obligatorio que pensemos en nuestros vecinos de toda la costa mediterr\u00e1nea. \u00bfPodemos hacer algo? \u00bfPuede km77 movilizar a sus lectores para que desviemos todos nuestras fuerzas y miradas para echar una mano?<br><br>En las imagenes hemos visto coches reales barridos como si fueran miniaturas de juguete. Amontonados unos sobre otros como si su peso fuera inexistente. Solo por esas im\u00e1genes de coches ya tendr\u00edamos algo que poder hacer. <br><br>No s\u00e9 exactamente qu\u00e9, pero al menos expresar nuestra cercan\u00eda. Lo urgente es rescatar a todos los desaparecidos y ayudar a las familias destrozadas por el dolor de las p\u00e9rdidas. Tambi\u00e9n, ayudar con la solidaridad. Dar refugio a quien lo necesite, a quien se haya quedado sin nada. \u00bfPodemos hacer algo? Por poco que podamos hacer, estamos aqu\u00ed, para movilizarnos nosotros y para movilizar a muchos de nuestros lectores, que seguro que muchos estamos dispuestos a colaborar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Toda la sociedad golpeada<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No podemos olvidarnos de las personas afectadas (muchas, seguro, ser\u00e1n lectoras de km77 y eso nos implica con una responsabilidd todav\u00eda mayor). Pero no se trata de nuestra responsabilidad como empresa, sino de nuestra responsabilidad como ciudadanos, la de todos, en una sociedad golpeada brutalmente.<br><br>Un d\u00eda as\u00ed me gustar\u00eda tener una varita m\u00e1gica, pero no la tenemos nadie. Nos gusta pensar que el Estado se har\u00e1 cargo, pero el Estado no es omnipotente y requiere de todos los ciudadanos, que tambi\u00e9n somos Estado, para ganar fuerza.<br><br>Estamos aqu\u00ed como empresa y como ciudadanos. Las carreteras cortadas de Valencia y de otras provincias afectadas son las carreteras que hemos recorrido miles de veces para probar los coches cuyos resultados publicamos. Los ciudadanos afectados sois nuestros vecinos. Estamos con vosotros y queremos estar con vosotros. Lo estamos con el pensamiento y si podemos ayudar con la presencia y los actos, decidnos c\u00f3mo hacerlo por favor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Atentos a las necesidades<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hemos hablado con Cruz Roja y nos han dicho que no necesitan m\u00e1s conductores con veh\u00edculos 4&#215;4. Si los necesitaran, nos avisar\u00e1n.  Tenemos m\u00e1s facilidad para movilizar conductores y coches que para recoger barro y para hacer otras tareas que nos resultan m\u00e1s dif\u00edcil de gestionar. Pero si fuera posible el Teletransporte que titula esta p\u00e1gina, estoy seguro de que muchos ciudadanos de toda Espa\u00f1a estar\u00edamos ayudando a quitar barro, enseres y a limpiar casas.<br><br>S\u00e9 que no sirve de mucho, pero estoy seguro de que el coraz\u00f3n y el pensamiento de muchos est\u00e1 con todos los damnificados. Mucho \u00e1nimo. Desde aqu\u00ed, env\u00edo todo mi cari\u00f1o y un abrazo.<br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras los sucesos, las cifras y la devastaci\u00f3n conocida ayer y hoy, el objetivo con el que nos levantamos cada ma\u00f1ana cambia de foco. Nuestra actividad diaria de informar de coches lo mejor que sabemos pasa a un segundo plano y es obligatorio que pensemos en nuestros vecinos de toda la costa mediterr\u00e1nea. \u00bfPodemos hacer [&hellip;]<\/p>\n","protected":false},"author":72,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3915],"tags":[],"class_list":["post-57327","post","type-post","status-publish","format-standard","hentry","category-teletransporte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>km77 con las v\u00edctimas y afectados por las riadas - Revista km77<\/title>\n<meta name=\"description\" content=\"Hoy, el objetivo diario cambia. Todos los ciudadanos estamos afectados por la tragedia y pendientes de la costa mediterr\u00e1nea. Un abrazo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"km77 con las v\u00edctimas y afectados por las riadas - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Hoy, el objetivo diario cambia. Todos los ciudadanos estamos afectados por la tragedia y pendientes de la costa mediterr\u00e1nea. Un abrazo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-31T14:04:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-31T14:04:12+00:00\" \/>\n<meta name=\"author\" content=\"Javier Molt\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deportes1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Molt\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/km77-con-las-victimas-y-afectados-por-las-riadas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/km77-con-las-victimas-y-afectados-por-las-riadas\\\/\"},\"author\":{\"name\":\"Javier Molt\u00f3\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/2f0611a1b3c7d2a2c81a9428505a25db\"},\"headline\":\"km77 con las v\u00edctimas y afectados por las riadas\",\"datePublished\":\"2024-10-31T14:04:09+00:00\",\"dateModified\":\"2024-10-31T14:04:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/km77-con-las-victimas-y-afectados-por-las-riadas\\\/\"},\"wordCount\":495,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"articleSection\":[\"Teletransporte\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/km77-con-las-victimas-y-afectados-por-las-riadas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/km77-con-las-victimas-y-afectados-por-las-riadas\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/km77-con-las-victimas-y-afectados-por-las-riadas\\\/\",\"name\":\"km77 con las v\u00edctimas y afectados por las riadas - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"datePublished\":\"2024-10-31T14:04:09+00:00\",\"dateModified\":\"2024-10-31T14:04:12+00:00\",\"description\":\"Hoy, el objetivo diario cambia. Todos los ciudadanos estamos afectados por la tragedia y pendientes de la costa mediterr\u00e1nea. Un abrazo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/km77-con-las-victimas-y-afectados-por-las-riadas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/km77-con-las-victimas-y-afectados-por-las-riadas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/km77-con-las-victimas-y-afectados-por-las-riadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teletransporte\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"km77 con las v\u00edctimas y afectados por las riadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Noticias y opiniones en km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/2f0611a1b3c7d2a2c81a9428505a25db\",\"name\":\"Javier Molt\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g\",\"caption\":\"Javier Molt\u00f3\"},\"description\":\"Empec\u00e9 a trabajar como periodista probador de coches en 1985, en la revista AutoHebdo. Despu\u00e9s trabaj\u00e9 en Coche Actual y Motor16. Desde 1994 a 1999 inform\u00e9 de asuntos econ\u00f3micos tanto en Madrid como en Londres, donde trabaj\u00e9 en Bloomberg. En 1999 fund\u00e9 km77.com, empresa con la que sigo empe\u00f1ado en el objetivo de dar la mejor informaci\u00f3n de coches de la que somos capaces.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/Deportes1\"],\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/teletransporte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"km77 con las v\u00edctimas y afectados por las riadas - Revista km77","description":"Hoy, el objetivo diario cambia. Todos los ciudadanos estamos afectados por la tragedia y pendientes de la costa mediterr\u00e1nea. Un abrazo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/","og_locale":"es_ES","og_type":"article","og_title":"km77 con las v\u00edctimas y afectados por las riadas - Revista km77","og_description":"Hoy, el objetivo diario cambia. Todos los ciudadanos estamos afectados por la tragedia y pendientes de la costa mediterr\u00e1nea. Un abrazo.","og_url":"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/","og_site_name":"Revista km77","article_published_time":"2024-10-31T14:04:09+00:00","article_modified_time":"2024-10-31T14:04:12+00:00","author":"Javier Molt\u00f3","twitter_card":"summary_large_image","twitter_creator":"@Deportes1","twitter_misc":{"Escrito por":"Javier Molt\u00f3","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/"},"author":{"name":"Javier Molt\u00f3","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/2f0611a1b3c7d2a2c81a9428505a25db"},"headline":"km77 con las v\u00edctimas y afectados por las riadas","datePublished":"2024-10-31T14:04:09+00:00","dateModified":"2024-10-31T14:04:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/"},"wordCount":495,"commentCount":3,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"articleSection":["Teletransporte"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/","url":"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/","name":"km77 con las v\u00edctimas y afectados por las riadas - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"datePublished":"2024-10-31T14:04:09+00:00","dateModified":"2024-10-31T14:04:12+00:00","description":"Hoy, el objetivo diario cambia. Todos los ciudadanos estamos afectados por la tragedia y pendientes de la costa mediterr\u00e1nea. Un abrazo.","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/teletransporte\/km77-con-las-victimas-y-afectados-por-las-riadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Teletransporte","item":"https:\/\/www.km77.com\/revista\/teletransporte\/"},{"@type":"ListItem","position":3,"name":"km77 con las v\u00edctimas y afectados por las riadas"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Noticias y opiniones en km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/2f0611a1b3c7d2a2c81a9428505a25db","name":"Javier Molt\u00f3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g","caption":"Javier Molt\u00f3"},"description":"Empec\u00e9 a trabajar como periodista probador de coches en 1985, en la revista AutoHebdo. Despu\u00e9s trabaj\u00e9 en Coche Actual y Motor16. Desde 1994 a 1999 inform\u00e9 de asuntos econ\u00f3micos tanto en Madrid como en Londres, donde trabaj\u00e9 en Bloomberg. En 1999 fund\u00e9 km77.com, empresa con la que sigo empe\u00f1ado en el objetivo de dar la mejor informaci\u00f3n de coches de la que somos capaces.","sameAs":["https:\/\/x.com\/Deportes1"],"url":"https:\/\/www.km77.com\/revista\/author\/teletransporte\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/57327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=57327"}],"version-history":[{"count":2,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/57327\/revisions"}],"predecessor-version":[{"id":57329,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/57327\/revisions\/57329"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=57327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=57327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=57327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}