{"id":57065,"date":"2024-12-19T17:52:21","date_gmt":"2024-12-19T16:52:21","guid":{"rendered":"https:\/\/www.km77.com\/revista\/?p=57065"},"modified":"2024-12-19T20:31:10","modified_gmt":"2024-12-19T19:31:10","slug":"consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/","title":{"rendered":"Consejos para comprar un coche de segunda mano (segunda parte)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Despu\u00e9s de <a href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano\/\">la primera parte<\/a>, donde explicamos algunas recomendaciones generales de compra as\u00ed como en qu\u00e9 aspectos revisar de la carrocer\u00eda, neum\u00e1ticos y frenos, seguimos con m\u00e1s puntos a tener en cuenta a la hora de comprar un coche usado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Circuito de refrigeraci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Llega el momento de revisar el <strong>motor y los componentes aleda\u00f1os<\/strong>. Lo primero puede ser, por ejemplo, el estado del l\u00edquido refrigerante. Debemos verificar que su nivel sea correcto seg\u00fan las marcas de m\u00e1ximo y m\u00ednimo que hay en el vaso de expansi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo ideal es que el pl\u00e1stico del vaso de expansi\u00f3n tenga un tono blanquecino y que <strong>deje ver con claridad el l\u00edquido<\/strong> que hay en su interior. As\u00ed es como deber\u00eda estar en un coche que tiene poco uso (e incluso con no tan poco uso pero s\u00ed bien mantenido). Si, por el contrario, el coche tiene mucho uso o falta de mantenimiento el vaso de expansi\u00f3n suele estar oscurecido y deja ver con dificultad el l\u00edquido que hay en su interior.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/07\/refrigerante-1024x683.jpg\" alt=\"Vaso de expansi\u00f3n del l\u00edquido refrigerante\" class=\"wp-image-56164\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/07\/refrigerante-1024x683.jpg 1024w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/07\/refrigerante-980x653.jpg 980w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/07\/refrigerante-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El l\u00edquido refrigerante ha de tener un color determinado (puede ser verde, rojo, azul, etc.) en funci\u00f3n de su composici\u00f3n. <strong>Es importante que no sea marr\u00f3n<\/strong> o incluso tenga restos de una textura parecida al barro. Eso es se\u00f1al de que algunos componentes del circuito de refrigeraci\u00f3n podr\u00edan estar oxidados o que en alg\u00fan punto se est\u00e1 mezclando refrigerante con aceite (indicio de una aver\u00eda importante). Para comprobar mejor el estado del refrigerante se puede <strong>abrir el vaso de expansi\u00f3n<\/strong> (siempre con el coche fr\u00edo) y extraer una peque\u00f1a muestra.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conductos del sistema de refrigeraci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los conductos del sistema de refrigeraci\u00f3n (que pueden ser manguitos de goma o tubos met\u00e1licos) tienen que estar en buen estado, <strong>sin grietas o indicios de que la goma est\u00e1 acusando el paso del tiempo<\/strong>. El sellado de todos debe ser perfecto, sin escapes de agua por peque\u00f1os que sean. Naturalmente, el coche no debe dejar ning\u00fan rastro de agua (ni aceite) en el suelo despu\u00e9s de estar aparcado durante un tiempo en el mismo sitio. Cada vez es m\u00e1s dif\u00edcil de comprobarlo porque la parte inferior del motor suele ir carenada para mejorar el coeficiente aerodin\u00e1mico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Estado superficial del motor<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El motor no ha de tener fugas de aceite: es conveniente <strong>utilizar una linterna para ver bien todos los recovecos<\/strong>. Es admisible, hasta cierto punto, que los coches que no sean seminuevos tengan alg\u00fan ligero rezume. Eso, en principio, no es muy preocupante. <strong>No es admisible que el aceite est\u00e9 cubriendo alguna pieza<\/strong> o incluso haya goteo, pues entonces no hay duda de que el coche requiere alguna reparaci\u00f3n (adem\u00e1s, esto suele ser calificado como falta grave en la ITV).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/full-10-1-1024x683.jpg\" alt=\"\" class=\"wp-image-57081\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/full-10-1-1024x683.jpg 1024w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/full-10-1-980x653.jpg 980w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/full-10-1-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><figcaption class=\"wp-element-caption\">Motor con 100 000 kil\u00f3metros<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Es conveniente revisar que el nivel de <strong>aceite est\u00e9 entre el m\u00e1ximo y el m\u00ednimo<\/strong>. Si est\u00e1 por debajo se puede deber a que el motor lo consume (y no se ha repuesto) o que hace mucho que no se cambia. Si hay varilla de nivel, tambi\u00e9n se puede comprobar el estado del aceite sacando una peque\u00f1a muestra. Si el motor es de gasolina y el aceite ha sido sustituido hace poco este deber\u00eda estar a\u00fan de color dorado. Por el contrario, en los motores Diesel, el aceite adquiere en pocos kil\u00f3metros un color negro por lo que no se puede saber si se sustituy\u00f3 recientemente. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/IMG_20180414_122822502-1-1024x768.jpg\" alt=\"\" class=\"wp-image-57082\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/IMG_20180414_122822502-1-980x735.jpg 980w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/IMG_20180414_122822502-1-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><figcaption class=\"wp-element-caption\">El aceite rezuma claramente desde la junta de la tapa superior del motor. <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el vano motor hay otras piezas susceptibles de chequear. Una de ellas son las <strong>correas<\/strong> (si est\u00e1n m\u00e1s o menos a la vista, lo cual no siempre ocurre) o tambi\u00e9n los <strong>mazos de cables<\/strong>. No obstante, no queremos entrar mucho en este apartado porque para encontrar posibles problemas y manipulaciones hace falta algo de experiencia y quiz\u00e1 se escape de la finalidad de este art\u00edculo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Revisi\u00f3n de la parte inferior de la carrocer\u00eda<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>parte inferior de la carrocer\u00eda<\/strong> (los bajos) da much\u00edsima informaci\u00f3n sobre el estado del veh\u00edculo. Por ello, es interesante llevar el coche a un box de mec\u00e1nica donde podamos alquilar un elevador durante unos minutos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"700\" height=\"444\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/007-2.jpg\" alt=\"\" class=\"wp-image-57070\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/007-2.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/007-2-480x304.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Con el coche elevado podremos volver a revisar y cerciorarnos de algunos aspectos que ya vimos en el apartado anterior: <strong>neum\u00e1ticos, frenos o estructura<\/strong>. Tambi\u00e9n podremos comprobar si hay alg\u00fan <strong>rasp\u00f3n o golpe en alguna parte<\/strong>, lo que da una idea del cuidado con el que se ha conducido y el tipo de v\u00edas que ha frecuentado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"700\" height=\"451\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/017.jpg\" alt=\"\" class=\"wp-image-57080\" style=\"width:823px;height:auto\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/017.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/017-480x309.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><figcaption class=\"wp-element-caption\">La parte baja del veh\u00edculo dice muchas cosas sobre su estado<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n podremos ver mucho mejor si hay <strong>fugas de aceite o valvulina<\/strong> (aceite de engranajes) por las partes inferiores del motor y caja de cambios. Lo ideal es que est\u00e9 todo seco, pero un coche con unos cuantos kil\u00f3metros encima que est\u00e9 completamente seco por debajo es como ver un unicornio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/010.jpg\" alt=\"\" class=\"wp-image-57072\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/010.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/010-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><figcaption class=\"wp-element-caption\">Este rezume de aceite est\u00e1 afectando a un contacto el\u00e9ctrico<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Se deben comprobar los <strong>fuelles de la transmisi\u00f3n<\/strong> que van junto a las ruedas (en el eje delantero en los coches de tracci\u00f3n delantera y, detr\u00e1s, en los trasera). Estas piezas de goma no deben tener grietas ni rajas porque ser\u00eda una v\u00eda de salida para la grasa que hay en su interior. Los amortiguadores tampoco deben tener manchas de aceite.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"700\" height=\"375\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/011-1.jpg\" alt=\"\" class=\"wp-image-57073\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/011-1.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/011-1-480x257.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><figcaption class=\"wp-element-caption\">El fuelle de goma est\u00e1, aparentemente, en buen estado<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Piezas oxidadas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los brazos de la suspensi\u00f3n, tuercas, bajos de la carrocer\u00eda y otras <strong>piezas aleda\u00f1as hechas de metal no deben de presentar mucho \u00f3xido ni corrosi\u00f3n<\/strong>. En este caso las condiciones de uso del coche son determinantes. Hay mucha diferencia entre los coches que est\u00e1n en un garaje cuando no se usan y los que est\u00e1n siempre en la calle. Pero son a\u00fan mayores entre <strong>los que est\u00e1n en un ambiente seco y los de zonas pr\u00f3ximas a la costa o en las monta\u00f1as<\/strong>. Una ligera corrosi\u00f3n superficial de tornillos o tubos de escape no es nada preocupante. Si la oxidaci\u00f3n es profunda, hay piezas importantes perforadas o, en el peor los casos, la estructura est\u00e1 afectada, es mejor descartar el coche porque suele acarrear reparaciones muy costosas y dif\u00edciles de llevar a cabo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"700\" height=\"422\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/014.jpg\" alt=\"\" class=\"wp-image-57077\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/014.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/014-480x289.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><figcaption class=\"wp-element-caption\">Los tubos de escape se oxidan con facilidad; eso en principio no es preocupante salvo que haya perforaci\u00f3n.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Los brazos de la suspensi\u00f3n y barras estabilizadoras est\u00e1n<strong> sujetos al chasis a trav\u00e9s de unos casquillos de goma.<\/strong> Es importante que no est\u00e9n rajados, cuarteados o que tengan alg\u00fan trozo desprendido, lo que podr\u00eda provocar ruidos durante la marcha.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"700\" height=\"292\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/012.jpg\" alt=\"\" class=\"wp-image-57075\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/012.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/012-480x200.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><figcaption class=\"wp-element-caption\">Este casquillo (que une uno de los brazos de la suspensi\u00f3n delantera al subchasis) no est\u00e1 agrietado ni rajado.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n es interesante comprobar que <strong>no hay holguras en los rodamientos de las ruedas, transmisiones, barras estabilizadoras<\/strong> e incluso los c\u00e1rdanes que trasladan la fuerza del motor a las ruedas. Esto se puede comprobar superficialmente haciendo fuerza con las manos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Motor en marcha<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lo ideal es que podamos arrancar el veh\u00edculo con el motor fr\u00edo. El motor se ha de poner en marcha sin ruidos raros. Justo en ese momento, no debe tirar una bocanada humo por el tubo de escape (salvo que sea un Diesel antiguo). En los <strong>coches de gasolina con catalizador<\/strong> es normal que el olor que salga del escape sea muy intenso y penetrante durante los primeros minutos de funcionamiento. Despu\u00e9s de un tiempo de uso, el olor deber\u00eda ser mucho m\u00e1s suave, lo que indica que el catalizador est\u00e1 realizando su funci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"743\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/honda.jpg\" alt=\"\" class=\"wp-image-57086\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/honda.jpg 1024w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/honda-980x711.jpg 980w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/honda-480x348.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Prueba de conducci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En la prueba de conducci\u00f3n nos debemos fijar que <strong>la suspensi\u00f3n no produzca ruidos al pasar por los baches<\/strong>, algo que se aprecia mejor yendo despacio que deprisa. En las bandas de limitaci\u00f3n de velocidad tampoco debe haber chirridos o golpes secos: estos pueden ser la causa de que los<strong> casquillos o <em>silentblocks<\/em> que sujetan los elementos de la suspensi\u00f3n al chasis est\u00e1n estropeados<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El coche debe ir recto al soltar el volante, tanto al acelerar como al frenar. Y no tiene que haber <strong>vibraciones en la direcci\u00f3n en ning\u00fan caso, as\u00ed como tampoco holguras<\/strong>. El tacto del freno debe ser suave y el pedal no debe vibrar. Tampoco tiene que haber ruidos durante la frenada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El coche debe salir desde parado de forma limpia sin tirones. Si dispone de caja manual todas las marchas deben entrar con suavidad y la palanca <strong>no debe volver por s\u00ed misma al punto muerto al acelerar o cuando se aprovecha la retenci\u00f3n del motor para reducir la velocidad<\/strong>. Esto se puede probar bien en un tramo de carretera con una pendiente larga y acusada.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"762\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/bmw-2.jpg\" alt=\"\" class=\"wp-image-57083\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/bmw-2.jpg 1024w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/bmw-2-980x729.jpg 980w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/bmw-2-480x357.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Si la prueba de conducci\u00f3n es suficientemente larga podremos observar c\u00f3mo funciona el sistema de refrigeraci\u00f3n. <strong>La aguja que indica la temperatura (si la hay) debe quedarse m\u00e1s o menos fija en el punto correcto (sobre los 90 grados)<\/strong> y no debe acercarse a la zona roja en ning\u00fan caso porque antes ha de actuar el electroventilador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante o despu\u00e9s de la prueba de conducci\u00f3n tambi\u00e9n es interesante <strong>probar el correcto funcionamiento de las luces, limpiaparabrisas, elevalunas, espejos retrovisores el\u00e9ctricos, aire acondicionado y, en general, de todo el equipamiento del que disponga el coche<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Otros consejos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que ya tengamos casi decidido el coche que deseamos comprar, es recomendable <strong>adquirir un informe de tr\u00e1fico<\/strong> donde podemos \u00abdescubrir el n\u00famero de propietarios, historial de cargas y embargos, posibles incidentes, ITVs, entre m\u00e1s detalles\u00bb o informes tipo Carfax.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfY si no tengo tiempo ni ganas de revisar un coche?<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/003.jpg\" alt=\"\" class=\"wp-image-57068\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/003.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/003-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para quien no tenga ese tiempo o esas ganas, dispone de varias alternativas a todo lo que hemos comentado anteriormente. Est\u00e1n a continuaci\u00f3n y no son excluyentes:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Pedir al vendedor que el coche <strong>pase la ITV antes de adquirirlo<\/strong>. <\/li>\n\n\n\n<li><strong>Pagar una revisi\u00f3n en un taller mec\u00e1nico<\/strong>. Esto tiene un coste superior al de pasar la ITV, pero revisar\u00e1n m\u00e1s puntos. El mec\u00e1nico nos podr\u00e1 dar una valoraci\u00f3n m\u00e1s precisa del estado del coche, por sus conocimientos y porque tiene herramientas espec\u00edficas de diagnosis.<\/li>\n\n\n\n<li>Adquirir un <strong>servicio de peritaje profesional<\/strong> que emite un informe sobre el estado del veh\u00edculo en funci\u00f3n de diversas pruebas y valoraciones.<br><\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"700\" height=\"404\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/003-1.jpg\" alt=\"\" class=\"wp-image-57069\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/003-1.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/09\/003-1-480x277.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Coche procedente de renting (de empresa y particulares) o alquiler \u00bfs\u00ed o no?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En la actualidad los coches procedentes de renting abundan en los portales de anuncios de compra y venta, y en ocasiones son f\u00e1ciles de detectar. El principal punto para rechazarlos es que <strong>probablemente no reciban el mismo trato que un coche comprado con el dinero de quien lo conduce<\/strong>. Esto es especialmente evidente si son <strong>coches que se han usado para trabajar, <\/strong>que normalmente reciben uso intensivo. El principal punto a favor para adquirirlo es que <strong>probablemente hayan pasado todas sus revisiones en un servicio oficial<\/strong> y el libro de mantenimiento est\u00e9 sellado. Tampoco hay que conceder demasiado valor a esto ya que la mayor parte de los particulares tambi\u00e9n llevan el veh\u00edculo a las revisiones durante los primeros a\u00f1os de vida (para que no se anule la garant\u00eda).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n hay que tener en cuenta<strong> en qu\u00e9 tipo de establecimiento adquirimos un coche procedente de flota<\/strong>. Si lo hacemos directamente a un concesionario oficial probablemente tengamos una garant\u00eda directa de la marca. Si lo compramos en un establecimiento multimarca, las operaciones en garant\u00eda se realizan, por lo general, en talleres generalistas concertados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Coche procedente de particular<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es una opci\u00f3n muy a tener en cuenta.  Tendremos <strong>m\u00e1s informaci\u00f3n de primera mano<\/strong> sobre el uso que ha tenido el veh\u00edculo. Tambi\u00e9n tendremos mayor capacidad de negociaci\u00f3n, ya que los precios entre particulares no suelen ser fijos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo negativo de comprar a un particular es que generalmente l<strong>os coches no est\u00e1n limpios, maquillados o preparados<\/strong> como los que proceden de establecimientos profesionales. Adem\u00e1s, probablemente nos tendremos que ocupar del proceso que implica cambiar de titular un veh\u00edculo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusiones<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta aqu\u00ed llegan algunas de las comprobaciones que se pueden llevar a cabo a la hora de comprar un coche. Obviamente no est\u00e1n todas, pero s\u00ed<strong> las principales que puede hacer un particular con un poco de tiempo y ganas<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El principal objetivo de una revisi\u00f3n como la que hemos expuesto aqu\u00ed es tener la m\u00e1xima informaci\u00f3n posible sobre un coche para hacer una buena compra. Pero hay que tener presente que <strong>no se trata de un proceso infalible<\/strong>. En ocasiones<strong> es complicado saber si alguna pieza est\u00e1 al final de su vida \u00fatil<\/strong> o si dar\u00e1 un problema en los pr\u00f3ximos meses. Un coche est\u00e1 compuesto por miles de piezas sujetas a deterioro y muchas de ellas requerir\u00e1n una reparaci\u00f3n sin previo aviso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somos conscientes de que probablemente nos hayamos dejado muchas cosas por decir. T\u00fa, <strong>\u00bfqu\u00e9 otras cosas tienes en cuenta y compruebas a la hora de comprar un coche usado?<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de la primera parte, donde explicamos algunas recomendaciones generales de compra as\u00ed como en qu\u00e9 aspectos revisar de la carrocer\u00eda, neum\u00e1ticos y frenos, seguimos con m\u00e1s puntos a tener en cuenta a la hora de comprar un coche usado. Circuito de refrigeraci\u00f3n Llega el momento de revisar el motor y los componentes aleda\u00f1os. Lo [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":57807,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3912],"tags":[13486,8444,13488],"class_list":["post-57065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-engendro-mecanico","tag-compra-coche-usado","tag-consejos","tag-cosas-que-mirar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>consejos compra coche usado<\/title>\n<meta name=\"description\" content=\"Consejos para comprar un coche de segunda mano. En qu\u00e9 fijarse a la hora de elegir un coche usado para hacer una buena adquisici\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"consejos compra coche usado\" \/>\n<meta property=\"og:description\" content=\"Consejos para comprar un coche de segunda mano. En qu\u00e9 fijarse a la hora de elegir un coche usado para hacer una buena adquisici\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-19T16:52:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-19T19:31:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/12\/compra-coche.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"761\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"E. Calle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"E. Calle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/\"},\"author\":{\"name\":\"E. Calle\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/d528ee8d860e406999292e1a36af3bb4\"},\"headline\":\"Consejos para comprar un coche de segunda mano (segunda parte)\",\"datePublished\":\"2024-12-19T16:52:21+00:00\",\"dateModified\":\"2024-12-19T19:31:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/\"},\"wordCount\":2261,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/compra-coche.jpg\",\"keywords\":[\"compra coche usado\",\"Consejos\",\"cosas que mirar\"],\"articleSection\":[\"Engendro Mec\u00e1nico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/\",\"name\":\"consejos compra coche usado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/compra-coche.jpg\",\"datePublished\":\"2024-12-19T16:52:21+00:00\",\"dateModified\":\"2024-12-19T19:31:10+00:00\",\"description\":\"Consejos para comprar un coche de segunda mano. En qu\u00e9 fijarse a la hora de elegir un coche usado para hacer una buena adquisici\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/compra-coche.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/compra-coche.jpg\",\"width\":1200,\"height\":761},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engendro Mec\u00e1nico\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Consejos para comprar un coche de segunda mano (segunda parte)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Noticias y opiniones en km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/d528ee8d860e406999292e1a36af3bb4\",\"name\":\"E. Calle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c902416ced08c25106c4d20a06d79f8e11185c5ce49b0554be653ac67fbb7ec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c902416ced08c25106c4d20a06d79f8e11185c5ce49b0554be653ac67fbb7ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c902416ced08c25106c4d20a06d79f8e11185c5ce49b0554be653ac67fbb7ec?s=96&d=mm&r=g\",\"caption\":\"E. Calle\"},\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/enrique-calle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"consejos compra coche usado","description":"Consejos para comprar un coche de segunda mano. En qu\u00e9 fijarse a la hora de elegir un coche usado para hacer una buena adquisici\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/","og_locale":"es_ES","og_type":"article","og_title":"consejos compra coche usado","og_description":"Consejos para comprar un coche de segunda mano. En qu\u00e9 fijarse a la hora de elegir un coche usado para hacer una buena adquisici\u00f3n.","og_url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/","og_site_name":"Revista km77","article_published_time":"2024-12-19T16:52:21+00:00","article_modified_time":"2024-12-19T19:31:10+00:00","og_image":[{"width":1200,"height":761,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/12\/compra-coche.jpg","type":"image\/jpeg"}],"author":"E. Calle","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"E. Calle","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/"},"author":{"name":"E. Calle","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/d528ee8d860e406999292e1a36af3bb4"},"headline":"Consejos para comprar un coche de segunda mano (segunda parte)","datePublished":"2024-12-19T16:52:21+00:00","dateModified":"2024-12-19T19:31:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/"},"wordCount":2261,"commentCount":4,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/12\/compra-coche.jpg","keywords":["compra coche usado","Consejos","cosas que mirar"],"articleSection":["Engendro Mec\u00e1nico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/","url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/","name":"consejos compra coche usado","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/12\/compra-coche.jpg","datePublished":"2024-12-19T16:52:21+00:00","dateModified":"2024-12-19T19:31:10+00:00","description":"Consejos para comprar un coche de segunda mano. En qu\u00e9 fijarse a la hora de elegir un coche usado para hacer una buena adquisici\u00f3n.","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/12\/compra-coche.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2024\/12\/compra-coche.jpg","width":1200,"height":761},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/consejos-para-comprar-un-coche-de-segunda-mano-segunda-parte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Engendro Mec\u00e1nico","item":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/"},{"@type":"ListItem","position":3,"name":"Consejos para comprar un coche de segunda mano (segunda parte)"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Noticias y opiniones en km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/d528ee8d860e406999292e1a36af3bb4","name":"E. Calle","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7c902416ced08c25106c4d20a06d79f8e11185c5ce49b0554be653ac67fbb7ec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c902416ced08c25106c4d20a06d79f8e11185c5ce49b0554be653ac67fbb7ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c902416ced08c25106c4d20a06d79f8e11185c5ce49b0554be653ac67fbb7ec?s=96&d=mm&r=g","caption":"E. Calle"},"url":"https:\/\/www.km77.com\/revista\/author\/enrique-calle\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/57065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=57065"}],"version-history":[{"count":12,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/57065\/revisions"}],"predecessor-version":[{"id":57806,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/57065\/revisions\/57806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/57807"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=57065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=57065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=57065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}