{"id":5511,"date":"2014-10-07T14:19:12","date_gmt":"2014-10-07T12:19:12","guid":{"rendered":"http:\/\/blogs.km77.com\/engendromecanico\/?p=5511"},"modified":"2021-03-31T19:57:01","modified_gmt":"2021-03-31T17:57:01","slug":"bmw-driving-experience-de-la-mano-de-bridgestone","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/","title":{"rendered":"BMW Driving Experience de la mano de Bridgestone"},"content":{"rendered":"<p>El pasado mes de septiembre Bridgestone nos invit\u00f3\u00a0a participar en una jornada BMW Driving Experience. Los primeros p\u00e1rrafos de esta entrada est\u00e1n dedicados a Bridgestone y, el resto, a describir las actividades que hicimos durante la jornada de conducci\u00f3n, acompa\u00f1ado de algunos v\u00eddeos.<br \/>\nBridgestone es una compa\u00f1\u00eda especializada en la fabricaci\u00f3n de neum\u00e1ticos, pero cuya actividad industrial abarca tambi\u00e9n otros sectores, como por ejemplo las pelotas de golf, la fabricaci\u00f3n de mangueras y cintas transportadoras o la construcci\u00f3n de maquinaria de precisi\u00f3n para la creaci\u00f3n de c\u00e9lulas fotovoltaicas.<br \/>\nLa compa\u00f1\u00eda la fund\u00f3 el japon\u00e9s Shojiro Ishibashi en 1931. La traducci\u00f3n literal del apellido Ishibashi es \u00abpiedra puente\u00bb, en ingl\u00e9s \u00abstone bridge\u00bb. Shojiro Ishibashi invirti\u00f3 el orden de las palabras de la traducci\u00f3n inglesa y las uni\u00f3 porque el resultado, \u00abbridgestone\u00bb, le sonaba mejor.<br \/>\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-5520\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-1.jpg\" alt=\"blog-1\" width=\"700\" height=\"394\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-1.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-1-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><!--more--><br \/>\nEn Espa\u00f1a hay tres plantas de Bridgestone dedicadas a los neum\u00e1ticos. Est\u00e1n en Bilbao, Burgos y Puente San Miguel (Cantabria). La de Bilbao est\u00e1 especializada en neum\u00e1ticos para camiones y autobuses. La de Burgos fue la primera f\u00e1brica de neum\u00e1ticos Birdgestone en Europa. Se abri\u00f3 en 1990 y est\u00e1 especializada en turismos y camionetas. Por \u00faltimo, la de Puente San Miguel fabrica neum\u00e1ticos para camionetas, todoterrenos, camiones ligeros y veh\u00edculos agr\u00edcolas. En total, estas plantas dan trabajo a m\u00e1s de 3000 personas.<br \/>\nLos cursos de conducci\u00f3n BMW Driving Experience se organizan en varias partes del mundo y habitualmente est\u00e1n abiertos a cualquier persona que los pague (no hace falta tener un BMW). Los hay de muchos tipos: en circuito, en circuito y s\u00f3lo con modelos M, pruebas con todoterrenos, solo con MINI, cursos para aprender a controlar el derrape, etc. El que nosotros hicimos tuvo lugar en un antiguo aer\u00f3dromo de Maisach (al noroeste de M\u00fanich) e inclu\u00eda las pruebas y los veh\u00edculos que a continuaci\u00f3n os relato en orden cronol\u00f3gico.<br \/>\n<strong>1. BMW 225d Coup\u00e9<\/strong> (motor Diesel de 218 CV). Con \u00e9l estuve rodando en el circuito, guiado por un instructor que iba en otro coche igual y siempre en primera posici\u00f3n. El asfalto estaba h\u00famedo y hab\u00eda charcos, pero el instructor marc\u00f3 un ritmo alto, as\u00ed que fue un placer disfrutar de la sensaci\u00f3n de llevar el coche a los l\u00edmites de adherencia de los neum\u00e1ticos, unos Bridgestone Potenza S001 en medida 225\/45 R17. No s\u00e9 si llevaba la suspensi\u00f3n de serie o alguna de las que hay disponibles en opci\u00f3n. La sensaci\u00f3n que me dej\u00f3 este 225d Coup\u00e9 fue la de un coche de respuesta r\u00e1pida y precisa a las \u00f3rdenes del volante, estable en los cambios r\u00e1pidos de apoyo y suave en la transici\u00f3n hacia el sobreviraje (aunque \u00e9ste nunca lleg\u00f3 a ser grande porque el control de estabilidad lo imped\u00eda).<br \/>\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-5515\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-2.jpg\" alt=\"blog-2\" width=\"700\" height=\"394\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-2.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-2-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\n<strong>2. BMW M235i Coup\u00e9<\/strong> (motor de gasolina de 326 CV). Misma carrocer\u00eda que antes, pero con un motor de gasolina mucho m\u00e1s potente, un escape del que emanaba un sonido grave y elevado y una suspensi\u00f3n m\u00e1s dura. Los neum\u00e1ticos en esta ocasi\u00f3n tambi\u00e9n eran unos Bridgestone Potenza S001, pero en medida 225\/40 R18 delante y 245\/35 R18 detr\u00e1s. Con este modelo hice una prueba de slalon cronometrada. Se part\u00eda de un punto, se hac\u00eda el slalon en un sentido, media vuelta, slalon en sentido contrario y frenada a fondo en un espacio delimitado por conos. Tirar un cono penalizaba con 5 segundos, no importaba en qu\u00e9 parte del recorrido fuera. No me acuerdo de los tiempos, pero s\u00e9 que no fui primero, ni segundo, ni tercero (cuando est\u00e1s fuera del podio ya da igual el puesto).<br \/>\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-5516\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-3.jpg\" alt=\"blog-3\" width=\"700\" height=\"394\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-3.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-3-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\n<strong>3. BMW X5 xDrive40d<\/strong> (motor Diesel de 313 CV). Los neum\u00e1ticos eran unos Bridgestone Dueler H\/P en medida 255\/50 R19. Esta prueba se compon\u00eda de tres ejercicios. El primero consist\u00eda en subir y bajar por unas rampas met\u00e1licas de tal forma que al pasar sobre ellas una de las ruedas quedara patinara o quedara en el aire y as\u00ed poder observar el funcionamiento del sistema xDrive enviando par a las ruedas con tracci\u00f3n. En el segundo ejercicio se sub\u00eda una rampa en cuyo lado izquierdo hab\u00eda una serie de rodillos que hac\u00eda que las ruedas de ese lado no tuvieran tracci\u00f3n y, por tanto, no pudieran ayudar a subirla. El tercer ejercicio se trataba de mantener el coche en equilibrio sobre un balanc\u00edn. En el siguiente v\u00eddeo pod\u00e9is ver algunas escenas de estos tres ejercicios.<br \/>\n<iframe width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/W2-n5Va46m8?feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><br \/>\n<strong>4. BMW 430d Coup\u00e9<\/strong> (motor Diesel de 258 CV). Los neum\u00e1ticos que llevaban las unidades que probamos eran Bridgestone Potenza S001 en medida 225\/45 R18 y de tipo Runflat, es decir, unos neum\u00e1ticos que tienen capacidad para rodar sin presi\u00f3n durante unos 200 kil\u00f3metros a una velocidad m\u00e1xima de 80 km\/h. Algunas unidades ten\u00edan las ruedas hinchadas a las presiones correctas y a otras se les hab\u00eda quitado 1 bar en la rueda delantera izquierda. El objetivo era tratar de percibir las diferencias en las reacciones del coche ante una maniobra de esquiva bajo fuerte frenada desde 60 km\/h y sobre asfalto mojado.<br \/>\n<iframe width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/O4EUy2eFD_A?feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><br \/>\nLas unidades con los neum\u00e1ticos en buenas condiciones respond\u00edan con un poco m\u00e1s de inmediatez y precisi\u00f3n al volante, se dejaban guiar mejor, pero la sensaci\u00f3n de control en ambos casos era buena y el ejercicio de esquiva se superaba en ambos casos con facilidad.<br \/>\n<strong>5. BMW M4<\/strong> (motor de gasolina de 431 CV). Llegaba el momento que todos est\u00e1bamos esperando, conducir el M4 en circuito, con total libertad para sentir la aceleraci\u00f3n que da su motor de seis cilindros turbo y para poner a prueba los Bridgestone Potenza RE050 que llevaba (255\/35 R19 delante y 285\/35 R19 detr\u00e1s). Compart\u00edamos la pista con los 225d Coup\u00e9 de los que habl\u00e9 en el punto 1, pero ellos comenzaban en la contrarrecta del circuito, as\u00ed que lo \u00fanico que pod\u00eda suceder es que pasadas unas vueltas los adelant\u00e1semos\u2026 \u00a1Al final nos pasaron ellos a nosotros! Ya os lo dije, el instructor de los 225d Coup\u00e9 iba r\u00e1pido. Eso, unido a que el gu\u00eda de los M4 parec\u00eda no tener ganas de fiesta, termin\u00f3 en una horrible humillaci\u00f3n cuando \u00e9ste nos comunic\u00f3 por radio que nos apart\u00e1semos a la derecha para dejar pasar los Serie 2.<br \/>\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-5517\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-4.jpg\" alt=\"blog-4\" width=\"700\" height=\"394\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-4.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-4-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\n<strong>6. BMW 330d<\/strong> (motor Diesel de 258 CV). Para m\u00ed el mejor momento del d\u00eda junto con la primera actividad. Los organizadores del curso hab\u00edan delimitado una circunferencia con conos y hab\u00edan mojado el asfalto. Hab\u00eda que hacer que el coche sobrevirase y mantenerlo en ese estado el m\u00e1ximo tiempo posible dosificando el gas y el contravolante. As\u00ed que, 20 km\/h, cambio en posici\u00f3n manual, primera marcha insertada, control de estabilidad desconectado, gas a fondo, contravolante a destiempo y\u2026 trompo. \u00abHay que hacer el contravolante m\u00e1s r\u00e1pido\u00bb, me dijo el instructor por la radio. Le hice caso y c\u00f3mo cambi\u00f3 la cosa. \u00a1Qu\u00e9 gozo! Se me pas\u00f3 el tiempo s\u00faper r\u00e1pido, quer\u00eda m\u00e1s, m\u00e1s, m\u00e1s.<br \/>\n<iframe width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/p3DQv3ElhUc?feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: right\"><strong>Brazuka<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado mes de septiembre Bridgestone nos invit\u00f3\u00a0a participar en una jornada BMW Driving Experience. Los primeros p\u00e1rrafos de esta entrada est\u00e1n dedicados a Bridgestone y, el resto, a describir las actividades que hicimos durante la jornada de conducci\u00f3n, acompa\u00f1ado de algunos v\u00eddeos. Bridgestone es una compa\u00f1\u00eda especializada en la fabricaci\u00f3n de neum\u00e1ticos, pero cuya [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":5515,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3912],"tags":[5,6933,6929,6934,6935,98,6936,6937,7856,22,38,7907,7893,7889,3082,7799],"class_list":["post-5511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-engendro-mecanico","tag-bmw","tag-bmw-225d-coupe","tag-bmw-driving-experience","tag-bmw-m235i-coupe","tag-bmw-x5-xdrive40d","tag-bridgestone","tag-bridgestone-dueler-hp","tag-bridgestone-potenza-s001","tag-conduccion","tag-general","tag-neumaticos","tag-presentaciones","tag-slalom","tag-videos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BMW Driving Experience de la mano de Bridgestone - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BMW Driving Experience de la mano de Bridgestone - Revista km77\" \/>\n<meta property=\"og:description\" content=\"El pasado mes de septiembre Bridgestone nos invit\u00f3\u00a0a participar en una jornada BMW Driving Experience. Los primeros p\u00e1rrafos de esta entrada est\u00e1n dedicados a Bridgestone y, el resto, a describir las actividades que hicimos durante la jornada de conducci\u00f3n, acompa\u00f1ado de algunos v\u00eddeos. Bridgestone es una compa\u00f1\u00eda especializada en la fabricaci\u00f3n de neum\u00e1ticos, pero cuya [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-07T12:19:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T17:57:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Celedonio y Cogolludo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Celedonio y Cogolludo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/\"},\"author\":{\"name\":\"Celedonio y Cogolludo\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/a7115fd8d0381d5ef55688376f7fbfe2\"},\"headline\":\"BMW Driving Experience de la mano de Bridgestone\",\"datePublished\":\"2014-10-07T12:19:12+00:00\",\"dateModified\":\"2021-03-31T17:57:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/\"},\"wordCount\":1258,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/blog-2.jpg\",\"keywords\":[\"BMW\",\"BMW 225d Coup\u00e9\",\"bmw driving experience\",\"BMW M235i Coup\u00e9\",\"BMW X5 xDrive40d\",\"Bridgestone\",\"Bridgestone Dueler H\\\/P\",\"Bridgestone Potenza S001\",\"Conducci\u00f3n\",\"General\",\"Neum\u00e1ticos\",\"neum\u00e1ticos\",\"Presentaciones\",\"Slalom\",\"videos\",\"V\u00eddeos\"],\"articleSection\":[\"Engendro Mec\u00e1nico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/\",\"name\":\"BMW Driving Experience de la mano de Bridgestone - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/blog-2.jpg\",\"datePublished\":\"2014-10-07T12:19:12+00:00\",\"dateModified\":\"2021-03-31T17:57:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/blog-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/blog-2.jpg\",\"width\":700,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/bmw-driving-experience-de-la-mano-de-bridgestone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engendro Mec\u00e1nico\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BMW Driving Experience de la mano de Bridgestone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Noticias y opiniones en km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/a7115fd8d0381d5ef55688376f7fbfe2\",\"name\":\"Celedonio y Cogolludo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g\",\"caption\":\"Celedonio y Cogolludo\"},\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/celedoniycogolludo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BMW Driving Experience de la mano de Bridgestone - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/","og_locale":"es_ES","og_type":"article","og_title":"BMW Driving Experience de la mano de Bridgestone - Revista km77","og_description":"El pasado mes de septiembre Bridgestone nos invit\u00f3\u00a0a participar en una jornada BMW Driving Experience. Los primeros p\u00e1rrafos de esta entrada est\u00e1n dedicados a Bridgestone y, el resto, a describir las actividades que hicimos durante la jornada de conducci\u00f3n, acompa\u00f1ado de algunos v\u00eddeos. Bridgestone es una compa\u00f1\u00eda especializada en la fabricaci\u00f3n de neum\u00e1ticos, pero cuya [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/","og_site_name":"Revista km77","article_published_time":"2014-10-07T12:19:12+00:00","article_modified_time":"2021-03-31T17:57:01+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-2.jpg","type":"image\/jpeg"}],"author":"Celedonio y Cogolludo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Celedonio y Cogolludo","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/"},"author":{"name":"Celedonio y Cogolludo","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/a7115fd8d0381d5ef55688376f7fbfe2"},"headline":"BMW Driving Experience de la mano de Bridgestone","datePublished":"2014-10-07T12:19:12+00:00","dateModified":"2021-03-31T17:57:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/"},"wordCount":1258,"commentCount":2,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-2.jpg","keywords":["BMW","BMW 225d Coup\u00e9","bmw driving experience","BMW M235i Coup\u00e9","BMW X5 xDrive40d","Bridgestone","Bridgestone Dueler H\/P","Bridgestone Potenza S001","Conducci\u00f3n","General","Neum\u00e1ticos","neum\u00e1ticos","Presentaciones","Slalom","videos","V\u00eddeos"],"articleSection":["Engendro Mec\u00e1nico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/","url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/","name":"BMW Driving Experience de la mano de Bridgestone - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-2.jpg","datePublished":"2014-10-07T12:19:12+00:00","dateModified":"2021-03-31T17:57:01+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-2.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/10\/blog-2.jpg","width":700,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/bmw-driving-experience-de-la-mano-de-bridgestone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Engendro Mec\u00e1nico","item":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/"},{"@type":"ListItem","position":3,"name":"BMW Driving Experience de la mano de Bridgestone"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Noticias y opiniones en km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/a7115fd8d0381d5ef55688376f7fbfe2","name":"Celedonio y Cogolludo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g","caption":"Celedonio y Cogolludo"},"url":"https:\/\/www.km77.com\/revista\/author\/celedoniycogolludo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/5511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=5511"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/5511\/revisions"}],"predecessor-version":[{"id":42087,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/5511\/revisions\/42087"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/5515"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=5511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=5511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=5511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}