{"id":54684,"date":"2023-08-08T16:20:16","date_gmt":"2023-08-08T14:20:16","guid":{"rendered":"https:\/\/www.km77.com\/revista\/?p=54684"},"modified":"2023-08-08T16:20:20","modified_gmt":"2023-08-08T14:20:20","slug":"el-imperio-de-la-basura","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/","title":{"rendered":"El imperio de la basura"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Amigas y amigos,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Espero que me lean desde un pa\u00eds lejano. Playa o monta\u00f1a, disfrutando de unas merecidas vacaciones. Si no es as\u00ed, y les ha tocado quedarse levantando el pa\u00eds, que tengan un buen aire acondicionado y buena salud para gozarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yo estoy en lo segundo (en casa, con el puto aire acondicionado), aunque me resfr\u00edo cada diez minutos, as\u00ed que no s\u00e9 si puedo presumir de buena salud. Eso s\u00ed, prefiero resfriarme que sufrir las inclemencias del sudor. Seguro que es por mi avanzada edad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fin, como siempre se han producido una tonelada de estrenos, cada uno peor que el anterior. Estamos en verano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En mi pr\u00f3ximo post hablar\u00e9 de Megalodon 2. Ya les adelanto que estoy totalmente a favor de este artefacto, porque me lo pas\u00e9 pipa con la primera entrega y he gozado tambi\u00e9n la segunda. Es verano y en verano me deshago de mis neuronas y disfruto de cualquier pel\u00edcula en las que haya monstruos, tipos recios que nunca sonr\u00eden y tramas que parecen escritas por un ornitorrinco ebrio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero hoy hablar\u00e9 de algo que me ha molestado profundamente y que es la cima de un fen\u00f3meno que hemos ido contemplando con cierta condescendencia durante los \u00faltimos a\u00f1os y que ahora se nos ha sentado en los hombros y se niega a bajar de all\u00ed: el documental de Mario Biondo en Netflix y la maldita expansi\u00f3n del g\u00e9nero (antes subg\u00e9nero) conocido como true crime. Una expansi\u00f3n imparable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No me voy a perder ahora en los detalles, el que desee saber m\u00e1s solo tiene que buscar en Google: hace unos a\u00f1os encontraron al marido de Raquel S\u00e1nchez Silva, Mario Biondo, muerto en su casa. La hip\u00f3tesis de la polic\u00eda siempre fue que el tipo se hab\u00eda suicidado. Luego salieron detalles de que el hombre hab\u00eda estado practicando un juego sexual, y como es f\u00e1cil de imaginar, la prensa amarilla se puso las botas. Solo faltaba que la familia de Biondo se convenciera de que en realidad a \u00e9l le hab\u00edan matado. No solo eso: alguien les convenci\u00f3 de que Sanch\u00e9z Silva hab\u00eda sido directa responsable del asesinato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les ahorro la visi\u00f3n del documental porque les quiero. Solo les dir\u00e9 que es pedestre, barato, confuso y totalmente irrelevante. No aporta nada, no investiga nada, no explica ni una sola cosa que no supi\u00e9ramos o que no tenga el m\u00ednimo inter\u00e9s. Las entrevistas est\u00e1n mal realizadas, no hay ninguna tesis que no sea cargar contra la familia de Biondo y hay un absurdo protagonismo del ex representante de la actriz, que se entiende perfectamente una vez se comprueba que este se\u00f1or es en realidad el productor de este \u2018documental\u2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El problema no es solo que este sea un producto fallido sin otra misi\u00f3n que la de seguir perpetuando el morbo, ni siquiera que sea tan obvio que se ha construido exclusivamente para ganar dinero. El aut\u00e9ntico problema es que Netflix emita una cosa tan horrorosa sin pens\u00e1rselo dos veces. Y aqu\u00ed llegamos a la madre del cordero: bajo el ala del true-crime ya cabe cualquier cosa. Empezamos con docus cojonudos que buscaban pistas, recovecos o nuevos enfoques en casos realmente interesantes y hemos acabado d\u00e1ndole seis episodios a la se\u00f1ora mayor que cay\u00f3 por la escalera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hemos pasado de cosas que nos ten\u00edan enganchados a la tele a mierdas que nos parecer\u00edan indignas en un reloj, pero -por supuesto- la m\u00e1quina no deja de funcionar:&nbsp; la gente sigue consumi\u00e9ndolo y ellos siguen haci\u00e9ndolo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como rezaba el dicho: \u2018love makes the world go\u2019 round\u2026 love for the money\u2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les dejo con esa reflexi\u00f3n, por si desearan darle un par de vueltas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y en un par de d\u00edas: la tercera temporada de Solo asesinatos en el edificio. Algo bueno para variar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abrazos,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TGR<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amigas y amigos, Espero que me lean desde un pa\u00eds lejano. Playa o monta\u00f1a, disfrutando de unas merecidas vacaciones. Si no es as\u00ed, y les ha tocado quedarse levantando el pa\u00eds, que tengan un buen aire acondicionado y buena salud para gozarlo. Yo estoy en lo segundo (en casa, con el puto aire acondicionado), aunque [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":54685,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3909],"tags":[],"class_list":["post-54684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine-cuatro-ruedas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El imperio de la basura - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El imperio de la basura - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Amigas y amigos, Espero que me lean desde un pa\u00eds lejano. Playa o monta\u00f1a, disfrutando de unas merecidas vacaciones. Si no es as\u00ed, y les ha tocado quedarse levantando el pa\u00eds, que tengan un buen aire acondicionado y buena salud para gozarlo. Yo estoy en lo segundo (en casa, con el puto aire acondicionado), aunque [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-08T14:20:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-08T14:20:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2023\/08\/biondo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Toni Garc\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toni Garc\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/\"},\"author\":{\"name\":\"Toni Garc\u00eda\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/db291b06b78e5fe336ada62bee862008\"},\"headline\":\"El imperio de la basura\",\"datePublished\":\"2023-08-08T14:20:16+00:00\",\"dateModified\":\"2023-08-08T14:20:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/\"},\"wordCount\":672,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/biondo.jpeg\",\"articleSection\":[\"Cine a las Cuatro Ruedas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/\",\"name\":\"El imperio de la basura - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/biondo.jpeg\",\"datePublished\":\"2023-08-08T14:20:16+00:00\",\"dateModified\":\"2023-08-08T14:20:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/biondo.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/biondo.jpeg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/el-imperio-de-la-basura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cine a las Cuatro Ruedas\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El imperio de la basura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Noticias y opiniones en km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/db291b06b78e5fe336ada62bee862008\",\"name\":\"Toni Garc\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/claqueta-cine-1-150x150.jpg\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/claqueta-cine-1-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/claqueta-cine-1-150x150.jpg\",\"caption\":\"Toni Garc\u00eda\"},\"description\":\"Cine a las cuatro ruedas es un blog dedicado al s\u00e9ptimo arte que empez\u00f3 tratando de mezclar cine y coches, como eso no funcion\u00f3 decidimos dejarlo solo en lo del cine. Eso s\u00ed, de cuando en cuando sacamos alg\u00fan coche.\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/cinecuatroruedas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El imperio de la basura - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/","og_locale":"es_ES","og_type":"article","og_title":"El imperio de la basura - Revista km77","og_description":"Amigas y amigos, Espero que me lean desde un pa\u00eds lejano. Playa o monta\u00f1a, disfrutando de unas merecidas vacaciones. Si no es as\u00ed, y les ha tocado quedarse levantando el pa\u00eds, que tengan un buen aire acondicionado y buena salud para gozarlo. Yo estoy en lo segundo (en casa, con el puto aire acondicionado), aunque [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/","og_site_name":"Revista km77","article_published_time":"2023-08-08T14:20:16+00:00","article_modified_time":"2023-08-08T14:20:20+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2023\/08\/biondo.jpeg","type":"image\/jpeg"}],"author":"Toni Garc\u00eda","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Toni Garc\u00eda","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/"},"author":{"name":"Toni Garc\u00eda","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/db291b06b78e5fe336ada62bee862008"},"headline":"El imperio de la basura","datePublished":"2023-08-08T14:20:16+00:00","dateModified":"2023-08-08T14:20:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/"},"wordCount":672,"commentCount":5,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2023\/08\/biondo.jpeg","articleSection":["Cine a las Cuatro Ruedas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/","url":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/","name":"El imperio de la basura - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2023\/08\/biondo.jpeg","datePublished":"2023-08-08T14:20:16+00:00","dateModified":"2023-08-08T14:20:20+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2023\/08\/biondo.jpeg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2023\/08\/biondo.jpeg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/el-imperio-de-la-basura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Cine a las Cuatro Ruedas","item":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/"},{"@type":"ListItem","position":3,"name":"El imperio de la basura"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Noticias y opiniones en km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/db291b06b78e5fe336ada62bee862008","name":"Toni Garc\u00eda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/claqueta-cine-1-150x150.jpg","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/claqueta-cine-1-150x150.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/claqueta-cine-1-150x150.jpg","caption":"Toni Garc\u00eda"},"description":"Cine a las cuatro ruedas es un blog dedicado al s\u00e9ptimo arte que empez\u00f3 tratando de mezclar cine y coches, como eso no funcion\u00f3 decidimos dejarlo solo en lo del cine. Eso s\u00ed, de cuando en cuando sacamos alg\u00fan coche.","url":"https:\/\/www.km77.com\/revista\/author\/cinecuatroruedas\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/54684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=54684"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/54684\/revisions"}],"predecessor-version":[{"id":54686,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/54684\/revisions\/54686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/54685"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=54684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=54684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=54684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}