{"id":5234,"date":"2010-05-03T21:36:57","date_gmt":"2010-05-03T19:36:57","guid":{"rendered":"http:\/\/blogs.km77.com\/engendromecanico\/?p=5234"},"modified":"2021-03-31T20:13:03","modified_gmt":"2021-03-31T18:13:03","slug":"las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/","title":{"rendered":"Las ventas de coches nuevos suben un 39.3 % en abril de 2010!"},"content":{"rendered":"<p>Seg\u00fan datos de ANFAC y ANIACAM, en abril de 2010, las ventas totales de turismos y todoterrenos <strong>aumentaron un 39.3 % <\/strong>respecto a abril de 2009.<br \/>\nDurante\u00a0abril de 2010, se han matriculado un total de <strong>93.637 veh\u00edculos <\/strong>(turismos y todoterrenos). Respecto a los\u00a0cuatro primeros meses de 2009, <strong>las ventas acumuladas\u00a0aumentan un 43,2 %<\/strong>.<br \/>\nLas marcas m\u00e1s vendidas durante abril han sido\u00a0Peugeot (9.705 unidades), Citro\u00ebn (8.523) y SEAT (8.183). SEAT lidera el ranking anual con 34.312 matriculaciones, seguido por Citro\u00ebn (33.885) y Peugeot (33.646).<br \/>\nLos modelos m\u00e1s matriculados han sido el M\u00e9gane (3.855), el Ibiza (3.806) y el C4 (3.512). Estos mismos modelos copan el raking anual.<br \/>\nPara incentivar la compra de veh\u00edculos (nuevos y usados con menos de dos a\u00f1os) y la retirada de los coches m\u00e1s viejos, el Gobierno ha lanzado una serie de ayudas directas (<a href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/\/2837\/el-plan-2000e-de-ayudas-directas-en-la-compra-entra-en-vigor\/\" target=\"_blank\" rel=\"noopener\">Plan 2000E<\/a>), que est\u00e1n pr\u00e1cticamente agotadas.<br \/>\nEn la secci\u00f3n <a href=\"https:\/\/www.km77.com\/mercado\/espana\/2009\/pespana.asp\" target=\"_blank\" rel=\"noopener\">Mercado de km77.com<\/a> pueden observarse las ventas de Espa\u00f1a y Europa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan datos de ANFAC y ANIACAM, en abril de 2010, las ventas totales de turismos y todoterrenos aumentaron un 39.3 % respecto a abril de 2009. Durante\u00a0abril de 2010, se han matriculado un total de 93.637 veh\u00edculos (turismos y todoterrenos). Respecto a los\u00a0cuatro primeros meses de 2009, las ventas acumuladas\u00a0aumentan un 43,2 %. Las marcas [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3912],"tags":[340,4139,4673,7801,2361,4141],"class_list":["post-5234","post","type-post","status-publish","format-standard","hentry","category-engendro-mecanico","tag-anfac","tag-aniacam","tag-km77-com-plan-vive","tag-noticias","tag-plan-2000e","tag-ventas-coches-nuevos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las ventas de coches nuevos suben un 39.3 % en abril de 2010! - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las ventas de coches nuevos suben un 39.3 % en abril de 2010! - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan datos de ANFAC y ANIACAM, en abril de 2010, las ventas totales de turismos y todoterrenos aumentaron un 39.3 % respecto a abril de 2009. Durante\u00a0abril de 2010, se han matriculado un total de 93.637 veh\u00edculos (turismos y todoterrenos). Respecto a los\u00a0cuatro primeros meses de 2009, las ventas acumuladas\u00a0aumentan un 43,2 %. Las marcas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-03T19:36:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T18:13:03+00:00\" \/>\n<meta name=\"author\" content=\"Jose B.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose B.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\\\/\"},\"author\":{\"name\":\"Jose B.\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/12053b16b430aa76be628b78b0db40f1\"},\"headline\":\"Las ventas de coches nuevos suben un 39.3 % en abril de 2010!\",\"datePublished\":\"2010-05-03T19:36:57+00:00\",\"dateModified\":\"2021-03-31T18:13:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\\\/\"},\"wordCount\":168,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"keywords\":[\"Anfac\",\"ANIACAM\",\"km77.com Plan Vive\",\"Noticias\",\"Plan 2000E\",\"Ventas coches nuevos\"],\"articleSection\":[\"Engendro Mec\u00e1nico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\\\/\",\"name\":\"Las ventas de coches nuevos suben un 39.3 % en abril de 2010! - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"datePublished\":\"2010-05-03T19:36:57+00:00\",\"dateModified\":\"2021-03-31T18:13:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engendro Mec\u00e1nico\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Las ventas de coches nuevos suben un 39.3 % en abril de 2010!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Revista de km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/12053b16b430aa76be628b78b0db40f1\",\"name\":\"Jose B.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g\",\"caption\":\"Jose B.\"},\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/joseb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las ventas de coches nuevos suben un 39.3 % en abril de 2010! - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/","og_locale":"es_ES","og_type":"article","og_title":"Las ventas de coches nuevos suben un 39.3 % en abril de 2010! - Revista km77","og_description":"Seg\u00fan datos de ANFAC y ANIACAM, en abril de 2010, las ventas totales de turismos y todoterrenos aumentaron un 39.3 % respecto a abril de 2009. Durante\u00a0abril de 2010, se han matriculado un total de 93.637 veh\u00edculos (turismos y todoterrenos). Respecto a los\u00a0cuatro primeros meses de 2009, las ventas acumuladas\u00a0aumentan un 43,2 %. Las marcas [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/","og_site_name":"Revista km77","article_published_time":"2010-05-03T19:36:57+00:00","article_modified_time":"2021-03-31T18:13:03+00:00","author":"Jose B.","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jose B.","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/"},"author":{"name":"Jose B.","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/12053b16b430aa76be628b78b0db40f1"},"headline":"Las ventas de coches nuevos suben un 39.3 % en abril de 2010!","datePublished":"2010-05-03T19:36:57+00:00","dateModified":"2021-03-31T18:13:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/"},"wordCount":168,"commentCount":3,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"keywords":["Anfac","ANIACAM","km77.com Plan Vive","Noticias","Plan 2000E","Ventas coches nuevos"],"articleSection":["Engendro Mec\u00e1nico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/","url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/","name":"Las ventas de coches nuevos suben un 39.3 % en abril de 2010! - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"datePublished":"2010-05-03T19:36:57+00:00","dateModified":"2021-03-31T18:13:03+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-coches-nuevos-suben-un-39-3-en-abril-de-2010\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Engendro Mec\u00e1nico","item":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/"},{"@type":"ListItem","position":3,"name":"Las ventas de coches nuevos suben un 39.3 % en abril de 2010!"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Revista de km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/12053b16b430aa76be628b78b0db40f1","name":"Jose B.","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g","caption":"Jose B."},"url":"https:\/\/www.km77.com\/revista\/author\/joseb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/5234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=5234"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/5234\/revisions"}],"predecessor-version":[{"id":44834,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/5234\/revisions\/44834"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=5234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=5234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=5234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}