{"id":5169,"date":"2014-06-07T21:40:53","date_gmt":"2014-06-07T19:40:53","guid":{"rendered":"http:\/\/blogs.km77.com\/engendromecanico\/?p=5169"},"modified":"2021-03-31T19:58:22","modified_gmt":"2021-03-31T17:58:22","slug":"skoda-y-la-traccion-total","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/","title":{"rendered":"\u0160koda y la tracci\u00f3n total"},"content":{"rendered":"<p>\u0160koda nos ha invitado a unas pruebas con varios de sus modelos de tracci\u00f3n total (<a href=\"https:\/\/www.km77.com\/precios\/buscar?marcas=Skoda%2C+&amp;modelos=&amp;denominaciones=&amp;estado=1&amp;precioi=8000&amp;preciof=50000&amp;carroceria=1&amp;puertas=-1&amp;plazas=-1&amp;tamanyoi=2500&amp;tamanyof=5500&amp;volmaleteroi=100&amp;volmaleterof=1000&amp;tipocombustible=-1&amp;tipocambio=1&amp;tipotraccion=4&amp;cilindradai=800&amp;cilindradaf=6000&amp;potenciai=60&amp;potenciaf=1000&amp;ordenar=precio&amp;enviar=Buscar\" target=\"_blank\" rel=\"noopener\">listado<\/a> con todos los coches 4&#215;4 a la venta de este fabricante). Ha sido un evento interesante porque me ha permitido comparar modelos de tracci\u00f3n total y a un solo eje por las mismas superficies deslizantes (b\u00e1sicamente cemento pulido y abundantemente regado). En este tipo de circunstancias, siempre a baja velocidad, los modelos de tracci\u00f3n total son sensiblemente mejores. \u00bfPor qu\u00e9?.\u00a0Pues b\u00e1sicamente porque el conductor tiene m\u00e1s oportunidades de ir por donde quiere.<br \/>\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-5172\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda02.jpg\" alt=\"Skoda Superb Combi 4x4. Superfice deslizante\" width=\"800\" height=\"390\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda02.jpg 800w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda02-480x234.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><!--more--><br \/>\nLas pruebas consist\u00edan en un ejercicio de eslalon, otra en\u00a0la que hab\u00eda que describir una curva larga y una tercera en la que hab\u00eda que remontar una rampa. En las dos primeras, en los veh\u00edculos con un solo eje motor (el delantero), era muy f\u00e1cil acelerar m\u00e1s de la cuenta y, en consecuencia, las ruedas patinaban por la poca adherencia disponible. Eso hace que los coches tuvieran una gran facilidad para seguir recto en los giros, sin obedecer al conductor. Es decir, el subviraje aparec\u00eda muy pronto. Con los veh\u00edculos de tracci\u00f3n total no hab\u00eda que tener tanto cuidado con el pedal derecho porque la fuerza del motor se reparte entre cuatro ruedas (es m\u00e1s dif\u00edcil romper la adherencia), y hay m\u00e1s oportunidades de que el coche siga por donde se apunta con el volante. Lo anterior no quiere decir que los veh\u00edculos de tracci\u00f3n total\u00a0tengan una superioridad absoluta, pero s\u00ed ofrecen un plus de control que viene muy bien cuando la adherencia es tan baja (calculo que parecida a la de la nieve reci\u00e9n ca\u00edda).<br \/>\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-5170\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda04.jpg\" alt=\"Skoda Superb 4x4. Superficie deslizante\" width=\"800\" height=\"421\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda04.jpg 800w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda04-480x253.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><br \/>\n\u00bfQu\u00e9 pasaba en la prueba que consist\u00eda en subir la rampa?. Pues que la superioridad de los modelos de tracci\u00f3n total era mayor que en las pruebas de eslalon y de trazar una curva larga. Calculo que con los coches de tracci\u00f3n total se pod\u00eda progresar por la pendiente casi al doble de velocidad (a unos 25 km\/h) sin p\u00e9rdidas de tracci\u00f3n y acelerar con mucha m\u00e1s intensidad para afrontar la pendiente, que se comenzaba a coche parado.<br \/>\nHasta aqu\u00ed todo muy bien, pero me qued\u00e9 con ganas de probar qu\u00e9 diferencias hay entre los \u0160koda 4&#215;2 y 4&#215;4 cuando se baja una pendiente. A veces, cuando el firme est\u00e1 muy deslizante, las mayores complicaciones, o por lo menos los momentos m\u00e1s delicados, vienen en las bajadas.\u00a0Descender un puerto de monta\u00f1a con nieve reci\u00e9n ca\u00edda o hielo e inclinaciones superiores al 10%, puede ser inquietante.<br \/>\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-5171\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda03.jpg\" alt=\"Skoda Octavia Combi 4x4\" width=\"800\" height=\"499\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda03.jpg 800w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda03-480x299.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><br \/>\nMe pregunto si todos los sistemas de tracci\u00f3n total ofrecen el mismo rendimiento en esas circunstancias. Estoy casi seguro que no. Seg\u00fan me enter\u00e9 hablando con uno de los ingenieros responsables, el sistema de tracci\u00f3n total que utilizan los modelos de \u0160koda (el mismo de SEAT y Volkswagen, que recordemos es conectable autom\u00e1ticamente en funci\u00f3n de las necesidades mediante un embrague Haldex, y que, por lo tanto, carece de diferencial central) desembraga casi siempre el eje posterior en las fases de retenci\u00f3n con el objetivo de ahorrar combustible. Seg\u00fan me dijo, el \u00fanico momento (en fases de retenci\u00f3n) en que el eje posterior permanece conectado al delantero (y por lo tanto recibe la retenci\u00f3n que da el motor) es cuando se levanta bruscamente el pie del acelerador, pero solo ocurre durante unos instantes.<br \/>\n<img decoding=\"async\" class=\"aligncenter wp-image-5173 size-full\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda01.jpg\" alt=\"Skoda Octavia Combi 4x4\" width=\"800\" height=\"445\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda01.jpg 800w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda01-480x267.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><br \/>\nPor lo tanto, y en teor\u00eda, podr\u00eda haber alguna diferencia (a igualdad de todos los dem\u00e1s factores) entre bajar un puerto de monta\u00f1a helado con un coche equipado con un sistema de tracci\u00f3n total conectable de forma autom\u00e1tica \u2014que desconecte uno de los dos ejes en retenci\u00f3n\u2014 y con otro de tracci\u00f3n total permanente \u2014en el que todas las ruedas reciben la fuerza de retenci\u00f3n que da el motor.<br \/>\nHace ya unos meses conduje un Jeep Wrangler por los aleda\u00f1os de una pista de esqu\u00ed completamente nevada. Prob\u00e9 a bajar una pendiente (calculo podr\u00eda tener una inclinaci\u00f3n del 15 %) con un solo eje conectado \u2014el trasero\u2014 y con los dos conectados (en este coche, el conductor debe\u00a0elegir entre tracci\u00f3n total y 4&#215;4). En el segundo caso ten\u00eda mucho mejor control del veh\u00edculo, que progresaba poco a poco por la pendiente sin apenas perder tracci\u00f3n. Sin la tracci\u00f3n total conectada, y por lo tanto las ruedas posteriores como \u00fanicas encargadas de dar retenci\u00f3n, era tarea imposible bajar progresivamente la cuesta y el coche tend\u00eda a embalarse sin que yo pudiera hacer mucho. No digo que lo que ocurr\u00eda en este Wrangler pase en otros coches con tracci\u00f3n total detallados a lo largo de este texto, ni con otros muchos. Cada coche tiene sus peculiaridades y la tracci\u00f3n total del Wrangler no tiene nada que ver con la que tiene cualquier turismo actualmente en venta. Pero creo que es un aspecto a tener en cuenta y que conviene probar para hacer la mejor compra posible.<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: right\"><strong>Cogolludo<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0160koda nos ha invitado a unas pruebas con varios de sus modelos de tracci\u00f3n total (listado con todos los coches 4&#215;4 a la venta de este fabricante). Ha sido un evento interesante porque me ha permitido comparar modelos de tracci\u00f3n total y a un solo eje por las mismas superficies deslizantes (b\u00e1sicamente cemento pulido y [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":5170,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3912],"tags":[4685,7924,6740,6799,22,6800,6801,6802],"class_list":{"0":"post-5169","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-engendro-mecanico","8":"tag-4x4","10":"tag-asientos-ventilados-traseros","11":"tag-cemento-pulido","12":"tag-general","13":"tag-skoda-4x4","14":"tag-skoda-motricidad","15":"tag-skoda-traccion-total"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0160koda y la tracci\u00f3n total - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0160koda y la tracci\u00f3n total - Revista km77\" \/>\n<meta property=\"og:description\" content=\"\u0160koda nos ha invitado a unas pruebas con varios de sus modelos de tracci\u00f3n total (listado con todos los coches 4&#215;4 a la venta de este fabricante). Ha sido un evento interesante porque me ha permitido comparar modelos de tracci\u00f3n total y a un solo eje por las mismas superficies deslizantes (b\u00e1sicamente cemento pulido y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-07T19:40:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T17:58:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Celedonio y Cogolludo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Celedonio y Cogolludo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/\"},\"author\":{\"name\":\"Celedonio y Cogolludo\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/a7115fd8d0381d5ef55688376f7fbfe2\"},\"headline\":\"\u0160koda y la tracci\u00f3n total\",\"datePublished\":\"2014-06-07T19:40:53+00:00\",\"dateModified\":\"2021-03-31T17:58:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/\"},\"wordCount\":872,\"commentCount\":8,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/skoda04.jpg\",\"keywords\":[\"4x4\",\"4x4\",\"asientos ventilados traseros\",\"cemento pulido\",\"General\",\"skoda 4x4\",\"skoda motricidad\",\"skoda traccion total\"],\"articleSection\":[\"Engendro Mec\u00e1nico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/\",\"name\":\"\u0160koda y la tracci\u00f3n total - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/skoda04.jpg\",\"datePublished\":\"2014-06-07T19:40:53+00:00\",\"dateModified\":\"2021-03-31T17:58:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/skoda04.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/skoda04.jpg\",\"width\":800,\"height\":421},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/skoda-y-la-traccion-total\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engendro Mec\u00e1nico\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0160koda y la tracci\u00f3n total\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Revista de km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/a7115fd8d0381d5ef55688376f7fbfe2\",\"name\":\"Celedonio y Cogolludo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g\",\"caption\":\"Celedonio y Cogolludo\"},\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/celedoniycogolludo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0160koda y la tracci\u00f3n total - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/","og_locale":"es_ES","og_type":"article","og_title":"\u0160koda y la tracci\u00f3n total - Revista km77","og_description":"\u0160koda nos ha invitado a unas pruebas con varios de sus modelos de tracci\u00f3n total (listado con todos los coches 4&#215;4 a la venta de este fabricante). Ha sido un evento interesante porque me ha permitido comparar modelos de tracci\u00f3n total y a un solo eje por las mismas superficies deslizantes (b\u00e1sicamente cemento pulido y [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/","og_site_name":"Revista km77","article_published_time":"2014-06-07T19:40:53+00:00","article_modified_time":"2021-03-31T17:58:22+00:00","og_image":[{"width":800,"height":421,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda04.jpg","type":"image\/jpeg"}],"author":"Celedonio y Cogolludo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Celedonio y Cogolludo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/"},"author":{"name":"Celedonio y Cogolludo","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/a7115fd8d0381d5ef55688376f7fbfe2"},"headline":"\u0160koda y la tracci\u00f3n total","datePublished":"2014-06-07T19:40:53+00:00","dateModified":"2021-03-31T17:58:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/"},"wordCount":872,"commentCount":8,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda04.jpg","keywords":["4x4","4x4","asientos ventilados traseros","cemento pulido","General","skoda 4x4","skoda motricidad","skoda traccion total"],"articleSection":["Engendro Mec\u00e1nico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/","url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/","name":"\u0160koda y la tracci\u00f3n total - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda04.jpg","datePublished":"2014-06-07T19:40:53+00:00","dateModified":"2021-03-31T17:58:22+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda04.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/06\/skoda04.jpg","width":800,"height":421},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/skoda-y-la-traccion-total\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Engendro Mec\u00e1nico","item":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/"},{"@type":"ListItem","position":3,"name":"\u0160koda y la tracci\u00f3n total"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Revista de km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/a7115fd8d0381d5ef55688376f7fbfe2","name":"Celedonio y Cogolludo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g","caption":"Celedonio y Cogolludo"},"url":"https:\/\/www.km77.com\/revista\/author\/celedoniycogolludo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/5169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=5169"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/5169\/revisions"}],"predecessor-version":[{"id":42267,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/5169\/revisions\/42267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/5170"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=5169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=5169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=5169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}