{"id":38867,"date":"2013-07-08T12:29:19","date_gmt":"2013-07-08T10:29:19","guid":{"rendered":"http:\/\/blogs.km77.com\/pruebatucoche\/?p=653"},"modified":"2021-03-31T20:03:00","modified_gmt":"2021-03-31T18:03:00","slug":"mazda-323f-2001","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/","title":{"rendered":"Mazda 323f (2001)"},"content":{"rendered":"<p align=\"JUSTIFY\"><span style=\"color: #222222\">Les presento la prueba del Mazda 323f, el coche que conduzco habitualmente desde que obtuve el carn\u00e9 hace tres a\u00f1os. Se trata de un compacto de cinco puertas y 4,2 metros de longitud equipado con un motor turbo-diesel de dos litros de cilindrada y en acabado Exclusive (el m\u00e1s alto de gama). \u00c9sta unidad pertenece a la generaci\u00f3n que se vendi\u00f3 desde 1995 hasta 2001, a\u00f1o en el que sufri\u00f3 una renovaci\u00f3n con el cometido de alargar la vida comercial del producto hasta la llegada del Mazda 3 en 2004. Curiosamente, con este Mazda 323f la marca abandon\u00f3 la silueta cup\u00e9 con la que hab\u00eda comercializado el modelo hasta entonces, dando paso a la carrocer\u00eda de compacto convencional que ha permanecido hasta la actualidad.<\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #222222\"><span style=\"font-size: small\"><img decoding=\"async\" class=\"aligncenter\" alt=\"Mazda 323f (2001). Frontal\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSCN0048-3.jpg\" width=\"640\" height=\"480\" \/><!--more--><\/a><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-family: arial,sans-serif\"><span style=\"font-size: small\"><b><br \/>\nDise\u00f1o exterior e interior<\/b><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\">A pesar de su tama\u00f1o, la alargada l\u00ednea de las ventanillas y el estrecho pilar C provocan el efecto visual de encontrarnos ante un coche con carrocer\u00eda familiar, m\u00e1s grande de lo que en realidad es (o al menos eso es lo que me sugieren todos los que opinan sobre su est\u00e9tica). Como detalles diferenciadores del acabado Exclusive en el exterior nos encontramos con los faros antiniebla, los retrovisores y los tiradores de las puertas del color de la carrocer\u00eda y las llantas de aluminio pulido de quince pulgadas (todos ellos elementos de serie). En el interior nos reciben una tapicer\u00eda con un estampado muy de los noventa y un ambiente sobrio donde predomina el color negro. Hay pocos detalles que den vistosidad al interior, entre ellos, los tiradores interiores de las puertas cromados (los pedales que se observan en las fotograf\u00edas son un accesorio). El salpicadero y la instrumentaci\u00f3n presentan un dise\u00f1o sencillo, esta \u00faltima con la iluminaci\u00f3n verde, reforzando la imagen seria del interior.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\"><b><img decoding=\"async\" class=\"aligncenter size-full wp-image-659\" alt=\"Mazda 323f (2001). Vista lateral\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSCN0050.jpg\" width=\"640\" height=\"480\" \/><\/b><\/span><\/span><\/span><\/p>\n<p><strong><span style=\"color: #222222\">Habit\u00e1culo y equipamiento<\/span><\/strong><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\">El interior est\u00e1 repleto de pl\u00e1sticos duros y lisos, a excepci\u00f3n de la moldura que hay justo encima de la guantera, siendo el \u00fanico pl\u00e1stico acolchado del habit\u00e1culo. A pesar de ello, los materiales no tienen un tacto desagradable y han aguantado el paso del tiempo (12 a\u00f1os) en muy buen estado. Sorprende el buen ajuste de todas las piezas que componen el salpicadero, ya que no presentan holguras ni desajustes y dan sensaci\u00f3n de solidez al conjunto. Falla en algunos detalles como que ning\u00fan hueco para guardar objetos tiene fondo antideslizante, los parasoles no tienen iluminaci\u00f3n ni los botones de los elevalunas tampoco y, si os fij\u00e1is en la fotograf\u00eda de los pedales, se ven las entra\u00f1as del coche e incluso puedes meter el brazo por dentro a ambos lados de la consola por el hueco que queda al descubierto. Desconozco c\u00f3mo de corrientes eran estos defectos de calidad entre sus rivales, pero cosas como estas se echan en cara incluso a utilitarios hoy en d\u00eda. En cuanto a la iluminaci\u00f3n del habit\u00e1culo, disponemos de un \u00fanico plaf\u00f3n de luces, situado en medio del techo, con luces de lectura para los pasajeros traseros. La guantera y el maletero tambi\u00e9n est\u00e1n iluminados.<\/span><\/span><\/span><\/p>\n<p><a href=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC00994.jpg\" data-lbwps-width=\"640\" data-lbwps-height=\"425\" data-lbwps-srcsmall=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC00994-300x199.jpg\"><br \/>\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-654\" alt=\"Mazda 323f (2001). Salpicadero\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC00994.jpg\" width=\"640\" height=\"425\" \/><br \/>\n<\/a><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\">Los asientos ofrecen una sujeci\u00f3n lateral suficiente, aunque a los menos corpulentos puede parecerles que la parte alta del respaldo es algo ancha y recoge poco la espalda. El mullido es algo blando en la parte central tanto del respaldo como de la banqueta, y puede resultar algo inc\u00f3modo en viajes de m\u00e1s de una hora. La banqueta tiene una longitud correcta y la regulaci\u00f3n longitudinal del asiento es amplia. La regulaci\u00f3n en altura s\u00f3lo cambia la posici\u00f3n de la parte de la banqueta m\u00e1s cercana al respaldo, que pivota sobre el otro extremo de la banqueta. El volante se regula solamente en altura y, aunque es de pl\u00e1stico, tiene un tacto agradable. No es del todo f\u00e1cil encontrar una postura de conducci\u00f3n c\u00f3moda para todas las personas. Yo, que mido 1,85 metros, debo llevar las piernas bastante flexionadas si regulo el asiento para llegar al volante con comodidad. Esto me deja las rodillas demasiado cerca del propio volante y del salpicadero. Supongo que las personas de menor estatura no tendr\u00e1n el mismo problema.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-655\" alt=\"Mazda 323f (2001). Asientos delanteros\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC00997.jpg\" width=\"425\" height=\"640\" \/><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\">Una virtud que me sorprendi\u00f3 de este coche es su gran versatilidad y practicidad. El asiento del pasajero puede reclinarse dej\u00e1ndolo totalmente plano, lo que es muy \u00fatil para transportar objetos largos o si queremos usar el asiento como mesa, puesto que por detr\u00e1s est\u00e1 recubierto de una plancha lisa de pl\u00e1stico. Adem\u00e1s, los asientos traseros pueden desplazarse hacia delante para ganar maletero y sus respaldos pueden reclinarse hacia atr\u00e1s cual sill\u00f3n de relax por si queremos acomodarnos en la parte de atr\u00e1s. Por \u00faltimo, si queremos conseguir un fondo plano (obviando el escal\u00f3n que dejan los asientos al abatirlos) podemos levantar la banqueta de los asientos traseros, sacar los reposacabezas a los respaldos y abatirlos. Otro detalle pr\u00e1ctico es la presencia de perchas en las agarraderas de las plazas traseras. <\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\"><strong><strong><img decoding=\"async\" class=\"aligncenter\" alt=\"Mazda 323f (2001). Plazas traseras\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC01001.jpg\" width=\"640\" height=\"425\" \/><\/strong><\/strong><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\">Por lo que respecta al espacio disponible atr\u00e1s para los pasajeros, en una de las fotos se puede ver el espacio que queda para las rodillas para una persona de 1,75 metros despu\u00e9s de regular el asiento delantero para un conductor de 1,85 metros. El espacio para la cabeza atr\u00e1s es algo justo para las personas m\u00e1s altas debido a la peque\u00f1a ca\u00edda del techo, y la anchura para tres ocupantes es insuficiente para viajar con comodidad (sobre todo a la altura de los hombros). El maletero tiene 330 litros (un tama\u00f1o en la media del segmento) y sus formas son aprovechables.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-657\" alt=\"Mazda 323f (2001)\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC01010.jpg\" width=\"640\" height=\"425\" \/><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\"><br \/>\nEl equipamiento de seguridad en este acabado est\u00e1 formado por cuatro airbags y el ABS. Como carencias a destacar encontramos la falta de un tercer reposacabezas trasero y la presencia de frenos de tambor en el eje trasero. En cuanto al equipamiento de confort, son de serie el aire acondicionado, el cierre centralizado, los elevalunas el\u00e9ctricos delanteros con funci\u00f3n autom\u00e1tica para el del conductor, el ajuste en altura de los cinturones de seguridad delanteros y del asiento del conductor, la direcci\u00f3n asistida y poco m\u00e1s. Mi unidad lleva la preinstalaci\u00f3n de radio, y encima del espacio de la radio hay un hueco para depositar objetos y un reloj digital (en las unidades que equipan la radio de f\u00e1brica desaparece el reloj y el hueco portaobjetos).<\/span><\/span><\/span><\/p>\n<p><strong><span style=\"color: #222222\">Mec\u00e1nica y conducci\u00f3n<\/span><\/strong><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\">El motor que equipa mi Mazda 323f es un 2.0 litros diesel con 16 v\u00e1lvulas y turbo, que entrega una potencia de 90 CV y desarrolla un par m\u00e1ximo de 220 Nm a 1.800 rpm. Seg\u00fan datos oficiales, alcanza una velocidad m\u00e1xima de 178 km\/h y acelera de 0 a 100 km\/h en 12,2 segundos. Son cifras corrientes para un coche de esta potencia y peso. En conducci\u00f3n urbana, el motor no resulta agradable porque tiene muy poca fuerza a bajo r\u00e9gimen y le cuesta salir desde parado (y si tenemos el aire acondicionado encendido tenemos que estar muy pendientes de los pedales para que no haga el amago de calarse), adem\u00e1s de que resulta muy dif\u00edcil que no se produzcan tirones al circular en marchas cortas al m\u00ednimo gesto con el pie del acelerador. La entrega de potencia es poco lineal: por debajo de 1.900 rpm el motor tiene muy poca respuesta y, a partir de ah\u00ed, el motor empieza a empujar con fuerza entregando la potencia de forma brusca (supongo que por la entrada del turbo en acci\u00f3n), fuerza que se mantiene hasta pasadas las 4.000 rpm. Por ello, comparativamente es m\u00e1s agradable de utilizar en v\u00edas r\u00e1pidas. Los 90 CV de potencia son suficientes para mantener la velocidad m\u00e1xima permitida en autopistas sin necesidad de reducir marchas incluso cuando hay pendientes prolongadas.<\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\"><strong><img decoding=\"async\" class=\"aligncenter\" alt=\"Mazda 323f (2001). Vista exterior\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSCN0051.jpg\" width=\"640\" height=\"480\" \/><\/strong><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\">El motor no destaca por su suavidad de funcionamiento y su silencio de marcha, sino m\u00e1s bien al contrario. El traqueteo del motor a baja velocidad se aprecia con mucha claridad desde el habit\u00e1culo, sobre todo con el motor frio. En ciudad, es un motor ruidoso y que transmite bastantes vibraciones al volante y al cambio de marchas, y algo menos al asiento. En v\u00edas r\u00e1pidas, el ruido proveniente del motor se suaviza una vez ha alcanzado la temperatura \u00f3ptima y a velocidad sostenida. Es a partir de 130 km\/h de marcador cuando el ruido del motor y el aerodin\u00e1mico se vuelven algo molestos en viajes largos.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\">El cambio de marchas es de cinco velocidades y tiene un tacto que no me acaba de convencer. Parece como si los recorridos de la palanca no estuvieran definidos con claridad. No me refiero con ello a que sea f\u00e1cil equivocarse de marcha, pero tiene un guiado poco preciso que no permite cambiar de marchas con rapidez.<\/span><\/span><\/span><br \/>\n<span style=\"color: #222222\"><span style=\"font-size: small\">Me gusta mucho m\u00e1s el tacto de la direcci\u00f3n. Es directa, est\u00e1 poco asistida y transmite mucha informaci\u00f3n, para lo bueno y para lo malo. Para lo bueno porque sabes en todo momento si los neum\u00e1ticos pierden adherencia y, para lo malo, porque no filtra las irregularidades del asfalto, que se transmiten constantemente al volante en forma de peque\u00f1os movimientos par\u00e1sito. Me ha parecido que la estabilidad lineal del coche no es muy elevada, porque hay que ir haciendo peque\u00f1as correcciones con el volante constantemente para mantener la trayectoria. Tambi\u00e9n me ha parecido que el coche es sensible al viento lateral.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\">En cuanto al comportamiento en curva, la suspensi\u00f3n permite que la carrocer\u00eda balancee un poco, pero el coche sigue fielmente la trayectoria marcada por el volante. A pesar de que permita ciertas oscilaciones a la carrocer\u00eda, no se trata de una suspensi\u00f3n blanda y c\u00f3moda. No es una suspensi\u00f3n seca, porque no transmite golpes al habit\u00e1culo al pasar por baches, badenes o guardias tumbados, pero es inc\u00f3moda porque deja notar cualquier irregularidad que puedas encontrar en el asfalto. Puedes notar en el asiento todo lo que la suspensi\u00f3n se va encontrando seg\u00fan avanzas, por peque\u00f1o que sea (piedrecitas, peque\u00f1os bultos u ondulaciones en la carretera, juntas de dilataci\u00f3n, tapas de alcantarilla, etc.). A\u00fan as\u00ed, el coche transmite seguridad al trazar las curvas gracias a su comportamiento noble y predecible.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\">El consumo medio homologado del modelo en cuesti\u00f3n es de 5,1 l\/100 km. He medido el consumo real varias veces llenando el dep\u00f3sito y recorriendo todo lo que diera de s\u00ed hasta el pr\u00f3ximo llenado y he obtenido un consumo medio global de 5,8 l\/100 km, circulando la mayor\u00eda del tiempo a la velocidad legal permitida en cada tipo de v\u00eda. Mis trayectos habituales transcurren m\u00e1s por ciudad que por carretera, as\u00ed que alguien que haga m\u00e1s carretera puede conseguir sin mucha dificultad igualar el consumo medio homologado.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-size: small\">Por \u00faltimo os hablar\u00e9 de mi experiencia con la fiabilidad mec\u00e1nica del Mazda 323f. En los 175.000 kil\u00f3metros que ha recorrido el coche, ha sufrido dos aver\u00edas importantes. A los 150.000 kil\u00f3metros se averi\u00f3 el alternador y lo lleve a un servicio t\u00e9cnico oficial para que lo sustituyeran. Le montaron uno remanufacturado por 484\u20ac, que al cabo de poco m\u00e1s de 10.000 kil\u00f3metros se averi\u00f3 tambi\u00e9n. A los 157.000 kil\u00f3metros el coche empez\u00f3 a fallar al arrancar: en algunas ocasiones, cuando le daba al contacto, la luz de los calentadores diesel empezaba a parpadear en vez de quedarse fija unos segundos y luego apagarse. Cuando eso ocurr\u00eda, el coche no arrancaba. Result\u00f3 ser un problema con la bomba de inyecci\u00f3n, la cual tuvieron que desmontar y mandar a reparar. La reparaci\u00f3n me cost\u00f3 533\u20ac y me dijeron que hab\u00edan tenido que cambiar todos los componentes electr\u00f3nicos de la bomba porque fallaban. Y hasta ahora eso es todo (y esperemos que as\u00ed siga).<\/span><\/span><\/span><\/p>\n<p style=\"text-align: right\"><strong>Sergi<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les presento la prueba del Mazda 323f, el coche que conduzco habitualmente desde que obtuve el carn\u00e9 hace tres a\u00f1os. Se trata de un compacto de cinco puertas y 4,2 metros de longitud equipado con un motor turbo-diesel de dos litros de cilindrada y en acabado Exclusive (el m\u00e1s alto de gama). \u00c9sta unidad pertenece [&hellip;]<\/p>\n","protected":false},"author":70,"featured_media":38745,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3913],"tags":[11643,4807,11644,5029,11645,1188,22,1579,1922,31,3237,11646,11647,3497,2107,11648,11649,12806],"class_list":["post-38867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prueba-tu-coche","tag-alternador","tag-averias","tag-azul","tag-consumo-medio","tag-consumo-mixto","tag-espacio","tag-general","tag-interior","tag-maletero","tag-mazda","tag-mazda-3","tag-mazda-323f","tag-mazda-323f-de-2001","tag-mazda3","tag-motor","tag-motor-diesel","tag-plasticos","tag-prueba"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mazda 323f (2001) - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mazda 323f (2001) - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Les presento la prueba del Mazda 323f, el coche que conduzco habitualmente desde que obtuve el carn\u00e9 hace tres a\u00f1os. Se trata de un compacto de cinco puertas y 4,2 metros de longitud equipado con un motor turbo-diesel de dos litros de cilindrada y en acabado Exclusive (el m\u00e1s alto de gama). \u00c9sta unidad pertenece [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-08T10:29:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T18:03:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC00994.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prueba tu coche\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prueba tu coche\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/\"},\"author\":{\"name\":\"Prueba tu coche\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/b401763bf30ebddbe150fb3bff4d6b16\"},\"headline\":\"Mazda 323f (2001)\",\"datePublished\":\"2013-07-08T10:29:19+00:00\",\"dateModified\":\"2021-03-31T18:03:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/\"},\"wordCount\":2019,\"commentCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/DSC00994.jpg\",\"keywords\":[\"alternador\",\"averias\",\"azul\",\"consumo medio\",\"consumo mixto\",\"espacio\",\"General\",\"interior\",\"maletero\",\"Mazda\",\"Mazda 3\",\"mazda 323f\",\"mazda 323f de 2001\",\"Mazda3\",\"motor\",\"motor diesel\",\"plasticos\",\"prueba\"],\"articleSection\":[\"Prueba tu Coche\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/\",\"name\":\"Mazda 323f (2001) - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/DSC00994.jpg\",\"datePublished\":\"2013-07-08T10:29:19+00:00\",\"dateModified\":\"2021-03-31T18:03:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/DSC00994.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/DSC00994.jpg\",\"width\":640,\"height\":425},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/mazda-323f-2001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prueba tu Coche\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-tu-coche\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mazda 323f (2001)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Revista de km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/b401763bf30ebddbe150fb3bff4d6b16\",\"name\":\"Prueba tu coche\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea5d81aa426212294765add630fed7f98d3db08cb3b10e61c9f3ca0bd5d97bb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea5d81aa426212294765add630fed7f98d3db08cb3b10e61c9f3ca0bd5d97bb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea5d81aa426212294765add630fed7f98d3db08cb3b10e61c9f3ca0bd5d97bb8?s=96&d=mm&r=g\",\"caption\":\"Prueba tu coche\"},\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/pruebacoche\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mazda 323f (2001) - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/","og_locale":"es_ES","og_type":"article","og_title":"Mazda 323f (2001) - Revista km77","og_description":"Les presento la prueba del Mazda 323f, el coche que conduzco habitualmente desde que obtuve el carn\u00e9 hace tres a\u00f1os. Se trata de un compacto de cinco puertas y 4,2 metros de longitud equipado con un motor turbo-diesel de dos litros de cilindrada y en acabado Exclusive (el m\u00e1s alto de gama). \u00c9sta unidad pertenece [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/","og_site_name":"Revista km77","article_published_time":"2013-07-08T10:29:19+00:00","article_modified_time":"2021-03-31T18:03:00+00:00","og_image":[{"width":640,"height":425,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC00994.jpg","type":"image\/jpeg"}],"author":"Prueba tu coche","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Prueba tu coche","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/"},"author":{"name":"Prueba tu coche","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/b401763bf30ebddbe150fb3bff4d6b16"},"headline":"Mazda 323f (2001)","datePublished":"2013-07-08T10:29:19+00:00","dateModified":"2021-03-31T18:03:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/"},"wordCount":2019,"commentCount":14,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC00994.jpg","keywords":["alternador","averias","azul","consumo medio","consumo mixto","espacio","General","interior","maletero","Mazda","Mazda 3","mazda 323f","mazda 323f de 2001","Mazda3","motor","motor diesel","plasticos","prueba"],"articleSection":["Prueba tu Coche"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/","url":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/","name":"Mazda 323f (2001) - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC00994.jpg","datePublished":"2013-07-08T10:29:19+00:00","dateModified":"2021-03-31T18:03:00+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC00994.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/07\/DSC00994.jpg","width":640,"height":425},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/mazda-323f-2001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Prueba tu Coche","item":"https:\/\/www.km77.com\/revista\/prueba-tu-coche\/"},{"@type":"ListItem","position":3,"name":"Mazda 323f (2001)"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Revista de km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/b401763bf30ebddbe150fb3bff4d6b16","name":"Prueba tu coche","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ea5d81aa426212294765add630fed7f98d3db08cb3b10e61c9f3ca0bd5d97bb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea5d81aa426212294765add630fed7f98d3db08cb3b10e61c9f3ca0bd5d97bb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea5d81aa426212294765add630fed7f98d3db08cb3b10e61c9f3ca0bd5d97bb8?s=96&d=mm&r=g","caption":"Prueba tu coche"},"url":"https:\/\/www.km77.com\/revista\/author\/pruebacoche\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/38867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=38867"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/38867\/revisions"}],"predecessor-version":[{"id":42906,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/38867\/revisions\/42906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/38745"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=38867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=38867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=38867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}