{"id":38573,"date":"2013-08-28T12:36:37","date_gmt":"2013-08-28T10:36:37","guid":{"rendered":"http:\/\/blogs.km77.com\/prueba-renault-clio\/?p=485"},"modified":"2021-03-31T20:02:22","modified_gmt":"2021-03-31T18:02:22","slug":"visita-a-los-templos-de-la-automocion-parte-4-de-4","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/","title":{"rendered":"Visita a los templos de la automoci\u00f3n (Parte 4 de 4)"},"content":{"rendered":"<p>Por Lorenzo Serrano.<\/p>\n<p><!--[if gte mso 9]&gt;--><\/p>\n<p class=\"MsoNormal\">Todo viaje de placer tiene un principio y, desgraciadamente, un final. Tras ver en directo las 24 horas de Le Mans, objetivo prioritario del nuestro, tocaba emprender la vuelta a casa. Como coment\u00e9 en la <a href=\"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/2013\/08\/12\/visita-a-los-templos-de-la-automocion-parte-3-de-4\/\" target=\"_blank\" rel=\"noopener\">tercera entrega<\/a>, decidimos salir a la ma\u00f1ana siguiente, una buena idea si no hay prisa por volver. M\u00e1s vale esperar que verse involucrado como parte activa de una de las inmensas caravanas que hab\u00eda a la salida del circuito.<\/p>\n<p class=\"MsoNormal\"><img decoding=\"async\" class=\"aligncenter  wp-image-497\" alt=\"IMG_5236\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/IMG_5236-1.jpg\" width=\"320\" height=\"480\" \/><\/p>\n<p class=\"MsoNormal\">Viajamos primero a las afueras de Par\u00eds, lugar escogido por mi compa\u00f1ero de viaje para abandonarme. Restan poco m\u00e1s de 1700 km hasta Madrid, divididos nuevamente en dos etapas (<a href=\"https:\/\/www.google.es\/maps\/dir\/Le+Mans,+Francia\/Aeropuerto+de+Par%C3%ADs-Charles+de+Gaulle,+Roissy-en-France,+Francia\/Santander\/Madrid\/@44.402392,3.120117,5z\/data=!4m31!4m30!1m5!1m1!1s0x47e288d214f3aa31:0x69025d4c6a7de07f!2m2!1d0.19955599999999998!2d48.00611!1m5!1m1!1s0x47e63e038e4ccf5b:0x42be0982f5ba62c!2m2!1d2.547924!2d49.009691!1m10!1m1!1s0xd4949ae8a6bee71:0xd27cdc801682ba96!2m2!1d-3.80998!2d43.462306!3m4!1m2!1d-3.66246!2d42.472449!3s0xd45ff351dc0ef0f:0x29757866681900a1!1m5!1m1!1s0xd422997800a3c81:0xc436dec1618c2269!2m2!1d-3.7037899999999997!2d40.416775!3e0?hl=es&amp;dg=dbrw&amp;newdg=1\" target=\"_blank\" rel=\"noopener\">ver itinerario<\/a>).<\/p>\n<p class=\"MsoNormal\"><!--more-->La primera parte del viaje es hasta Santander, me toca justo el atardecer, momento en el que conducir el Clio se convirti\u00f3 en una aut\u00e9ntica pesadilla. Bueno, no ser\u00e9 tan dr\u00e1stico, en un infierno. El problema adem\u00e1s del gran aburrimiento \u2014que sufr\u00ed por culpa de las largas rectas de la autov\u00eda de peaje\u2014 eran los reflejos. Ya hab\u00edamos comentado en anteriores entradas del blog que los cromados del cuadro de instrumentos molestaban. Pero estos reflejos no son nada si los comparamos con los que hace la pantalla multimedia de 7&#8243;. Unos reflejos que me hicieron en momentos puntuales tener que poner la mano para poder mirar la carretera con garant\u00eda. En estas condiciones es imposible gestionar la m\u00fasica \u2014excepto subir o bajar el volumen y cambiar de canci\u00f3n\/emisora que se realiza utilizando el mando que hay detr\u00e1s del volante (<a href=\"https:\/\/www.km77.com\/fotos\/Renault\/Clio_2013\/Renault-Clio_2013-TCe_90_-pack_look_exterior_negro-Dynamique-Turismo-Interior-Mandos_columna_direccion-5_puertas-201306170009.html?modelId=2231&amp;modelVersionId=4425&amp;photoType=2&amp;order=2&amp;division=version&amp;galleryLimit=99&amp;galleryBackLimit=8\" target=\"_blank\" rel=\"noopener\">imagen<\/a>)\u2014, el navegador o los ajustes de la radio.<\/p>\n<p class=\"MsoNormal\"><img decoding=\"async\" class=\"aligncenter  wp-image-507\" alt=\"reflejos\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/reflejos-1-1024x683.jpg\" width=\"614\" height=\"409\" \/><\/p>\n<p class=\"MsoNormal\">Hemos viajado durante much\u00edsimos kil\u00f3metros con el control de velocidad conectado porque mantener el pie en el acelerador sin pisarlo a fondo es una tarea inc\u00f3moda \u2014por la posici\u00f3n del pedal\u2014. Su funcionamiento ha sido satisfactorio.<\/p>\n<p class=\"MsoNormal\">Atravesar la frontera supuso hacer una parada para repostar. Iba realizando un c\u00e1lculo aproximado de los kil\u00f3metros que restaban de combustible porque el ordenador del Clio no se <em>moja<\/em> a partir de una autonom\u00eda inferior a 60 km. Recorrimos 534 km, con el control de velocidad en 132 km\/h durante aproximadamente la mitad del trayecto. Seg\u00fan los datos del ordenador de viaje, la velocidad media fue de 115,8 km\/h y el consumo medio 6,8 l\/100 km.<\/p>\n<p class=\"MsoNormal\"><img decoding=\"async\" class=\"aligncenter  wp-image-500\" alt=\"IMG_5064\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/IMG_5064-1-1024x683.jpg\" width=\"614\" height=\"409\" \/><\/p>\n<p class=\"MsoNormal\">Entrar en Espa\u00f1a tambi\u00e9n fue motivo para volver a conectar el navegador. No hac\u00eda falta, pero yo lo conecto. La voz de las instrucciones es muy agradable, me hace compa\u00f1\u00eda. Ech\u00e9 en falta que no sea posible dar \u00f3rdenes por voz, si se viaja solo y no se desean perder puntos del carnet de conducir, hay que parar para introducir una direcci\u00f3n. En mi opini\u00f3n, no resulta f\u00e1cil encontrar el bot\u00f3n que permite parar las indicaciones del navegador, sobre todo si el conductor va conduciendo, aunque esta apreciaci\u00f3n no la comparten otros miembros de la redacci\u00f3n.<\/p>\n<p class=\"MsoNormal\">Aprovechando estas l\u00edneas, debo confesar que la conducta al volante de los franceses es ejemplar \u2014siempre hay excepciones\u2014. En autov\u00eda con tres o m\u00e1s carriles circulan siempre por el de la derecha, rara vez he tenido que utilizar el izquierdo en estas zonas para adelantar. La entrada en Espa\u00f1a fue aproximadamente a media noche, circulaban pocos coches, los suficientes para darme cuenta que eso no va con el conductor espa\u00f1ol \u2014siempre hay excepciones\u2014.<\/p>\n<p class=\"MsoNormal\">La segunda parte del viaje de vuelta a casa comienza con un hallazgo, las salidas de ventilaci\u00f3n centrales no se pueden regular hacia abajo, \u00a1comienzo a pasar calor!<\/p>\n<p class=\"MsoNormal\"><img decoding=\"async\" class=\"aligncenter  wp-image-502\" alt=\"IMG_5093\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/IMG_5093-1-1024x683.jpg\" width=\"614\" height=\"409\" \/><\/p>\n<p class=\"MsoNormal\">Este \u00faltimo trayecto me permiti\u00f3 realizar una conducci\u00f3n un poco m\u00e1s deportiva por la red de carreteras secundarias \u2014con aproximadamente 150 kg menos que en la ida\u2014. Es aqu\u00ed d\u00f3nde me doy cuenta que el tacto de la direcci\u00f3n el\u00e9ctrica \u2014con asistencia en funci\u00f3n de la velocidad\u2014 no me gusta. Es cierto que las hay mucho peores, pero no termina de ser todo lo precisa que deber\u00eda, o por lo menos, eso me parece. Sin embargo no tengo esa sensaci\u00f3n en autov\u00eda.<\/p>\n<p class=\"MsoNormal\">Aunque prefiero un veh\u00edculo con una suspensi\u00f3n m\u00e1s deportiva, la del Clio permite tener un paso por curva elevado\u00a0sin sacrificar el confort de los ocupantes ni poner en apuros al conductor, con reacciones muy limpias y sin sobresaltos. Incluso si el conductor entra en una curva un \u00abpoco pasado\u00bb, el Clio se comporta de una manera muy noble, sin brusquedades.<\/p>\n<p class=\"MsoNormal\"><img decoding=\"async\" class=\"aligncenter  wp-image-499\" alt=\"IMG_01\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/IMG_01-1-1024x683.jpg\" width=\"614\" height=\"409\" \/><\/p>\n<p class=\"MsoNormal\">Personalmente, si pensara adquirir un Renault Clio y tuviera pensado realizar viajes con \u00e9l, tengo claro que el motor 0.9 TCe no ser\u00eda el elegido. En autopista es cierto que se puede mantener un ritmo legal \u2014120\/130 km\/h\u2014 sin demasiadas complicaciones, es decir, siempre que circulemos por zonas llanas porque, en el momento que el terreno presente pendientes de cierto calibre, el Clio se viene abajo y deberemos recurrir a bajar una o dos velocidades.<\/p>\n<p class=\"MsoNormal\">Tampoco ser\u00eda el elegido si frecuentara carreteras de doble sentido. Para realizar un adelantamiento hay que planificarlo con mucho tiempo si se desea hacer de una manera muy segura. En el trayecto de Santander a Burgos por el Puerto del Escudo, nos encontramos con un conductor que aceleraba en las zonas donde se pod\u00eda adelantar hasta ponerse al l\u00edmite de la velocidad legal, fue muy complicado poder adelantarle.<\/p>\n<p class=\"MsoNormal\"><img decoding=\"async\" class=\"aligncenter  wp-image-503\" alt=\"IMG_5140\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/IMG_5140-1-1024x683.jpg\" width=\"614\" height=\"409\" \/><\/p>\n<p class=\"MsoNormal\">El \u00faltimo paso fue realizar una limpieza general. En el exterior, nos sorprendi\u00f3 lo dif\u00edcil que es despegar los mosquitos, incluso con el agua caliente. En el interior, ser\u00e1 imposible para el usuario mantener la zona central del salpicadero limpia durante unas horas, es un aut\u00e9ntico atrapapolvo.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><img decoding=\"async\" class=\"aligncenter  wp-image-498\" alt=\"102\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/102-1-1024x683.jpg\" width=\"614\" height=\"409\" \/><\/p>\n<p class=\"MsoNormal\">Llegamos a Madrid con 10 914 km. Es hora de entregar el #cliokm77 en la redacci\u00f3n con la satisfacci\u00f3n de haber cumplido todos nuestros objetivos. El verano que viene, si no hemos alcanzado el objetivo de los 120 000 km, nos inventaremos un nuevo viaje. Un saludo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Lorenzo Serrano. Todo viaje de placer tiene un principio y, desgraciadamente, un final. Tras ver en directo las 24 horas de Le Mans, objetivo prioritario del nuestro, tocaba emprender la vuelta a casa. Como coment\u00e9 en la tercera entrega, decidimos salir a la ma\u00f1ana siguiente, una buena idea si no hay prisa por volver. [&hellip;]<\/p>\n","protected":false},"author":69,"featured_media":38373,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3914],"tags":[791,12785,12786,12497,1748,4809,1803,12539,12540,10757,12797],"class_list":["post-38573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prueba-renault-clio","tag-clio","tag-fotos","tag-impresiones","tag-kilometros","tag-km77","tag-larga-duracion","tag-le-mans","tag-nurburgring-nordschleife","tag-pena-cabarga","tag-spa-francorchamps","tag-viajes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visita a los templos de la automoci\u00f3n (Parte 4 de 4) - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visita a los templos de la automoci\u00f3n (Parte 4 de 4) - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Por Lorenzo Serrano. Todo viaje de placer tiene un principio y, desgraciadamente, un final. Tras ver en directo las 24 horas de Le Mans, objetivo prioritario del nuestro, tocaba emprender la vuelta a casa. Como coment\u00e9 en la tercera entrega, decidimos salir a la ma\u00f1ana siguiente, una buena idea si no hay prisa por volver. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-28T10:36:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T18:02:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/IMG_5236-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"533\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"km77\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"km77\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/\"},\"author\":{\"name\":\"km77\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/600bb0574d2b74aa4ca28321eaba7189\"},\"headline\":\"Visita a los templos de la automoci\u00f3n (Parte 4 de 4)\",\"datePublished\":\"2013-08-28T10:36:37+00:00\",\"dateModified\":\"2021-03-31T18:02:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/\"},\"wordCount\":1003,\"commentCount\":23,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/IMG_5236-1.jpg\",\"keywords\":[\"Clio\",\"fotos\",\"impresiones\",\"kilometros\",\"KM77\",\"larga duracion\",\"Le Mans\",\"N\u00fcrburgring Nordschleife\",\"Pe\u00f1a Cabarga\",\"Spa-Francorchamps\",\"viajes\"],\"articleSection\":[\"Renault Clio. Prueba de 120.000 kil\u00f3metros\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/\",\"name\":\"Visita a los templos de la automoci\u00f3n (Parte 4 de 4) - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/IMG_5236-1.jpg\",\"datePublished\":\"2013-08-28T10:36:37+00:00\",\"dateModified\":\"2021-03-31T18:02:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/IMG_5236-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/IMG_5236-1.jpg\",\"width\":533,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/visita-a-los-templos-de-la-automocion-parte-4-de-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renault Clio. Prueba de 120.000 kil\u00f3metros\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/prueba-renault-clio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Visita a los templos de la automoci\u00f3n (Parte 4 de 4)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Revista de km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/600bb0574d2b74aa4ca28321eaba7189\",\"name\":\"km77\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afa5bbdbf5aa9c4be56a66809d084d5a0c00308c49c3b2792acb7d261ca6188?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afa5bbdbf5aa9c4be56a66809d084d5a0c00308c49c3b2792acb7d261ca6188?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4afa5bbdbf5aa9c4be56a66809d084d5a0c00308c49c3b2792acb7d261ca6188?s=96&d=mm&r=g\",\"caption\":\"km77\"},\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/prueba-renault-clio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visita a los templos de la automoci\u00f3n (Parte 4 de 4) - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/","og_locale":"es_ES","og_type":"article","og_title":"Visita a los templos de la automoci\u00f3n (Parte 4 de 4) - Revista km77","og_description":"Por Lorenzo Serrano. Todo viaje de placer tiene un principio y, desgraciadamente, un final. Tras ver en directo las 24 horas de Le Mans, objetivo prioritario del nuestro, tocaba emprender la vuelta a casa. Como coment\u00e9 en la tercera entrega, decidimos salir a la ma\u00f1ana siguiente, una buena idea si no hay prisa por volver. [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/","og_site_name":"Revista km77","article_published_time":"2013-08-28T10:36:37+00:00","article_modified_time":"2021-03-31T18:02:22+00:00","og_image":[{"width":533,"height":800,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/IMG_5236-1.jpg","type":"image\/jpeg"}],"author":"km77","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"km77","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/"},"author":{"name":"km77","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/600bb0574d2b74aa4ca28321eaba7189"},"headline":"Visita a los templos de la automoci\u00f3n (Parte 4 de 4)","datePublished":"2013-08-28T10:36:37+00:00","dateModified":"2021-03-31T18:02:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/"},"wordCount":1003,"commentCount":23,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/IMG_5236-1.jpg","keywords":["Clio","fotos","impresiones","kilometros","KM77","larga duracion","Le Mans","N\u00fcrburgring Nordschleife","Pe\u00f1a Cabarga","Spa-Francorchamps","viajes"],"articleSection":["Renault Clio. Prueba de 120.000 kil\u00f3metros"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/","url":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/","name":"Visita a los templos de la automoci\u00f3n (Parte 4 de 4) - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/IMG_5236-1.jpg","datePublished":"2013-08-28T10:36:37+00:00","dateModified":"2021-03-31T18:02:22+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/IMG_5236-1.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2013\/08\/IMG_5236-1.jpg","width":533,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/visita-a-los-templos-de-la-automocion-parte-4-de-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Renault Clio. Prueba de 120.000 kil\u00f3metros","item":"https:\/\/www.km77.com\/revista\/prueba-renault-clio\/"},{"@type":"ListItem","position":3,"name":"Visita a los templos de la automoci\u00f3n (Parte 4 de 4)"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Revista de km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/600bb0574d2b74aa4ca28321eaba7189","name":"km77","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4afa5bbdbf5aa9c4be56a66809d084d5a0c00308c49c3b2792acb7d261ca6188?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4afa5bbdbf5aa9c4be56a66809d084d5a0c00308c49c3b2792acb7d261ca6188?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4afa5bbdbf5aa9c4be56a66809d084d5a0c00308c49c3b2792acb7d261ca6188?s=96&d=mm&r=g","caption":"km77"},"url":"https:\/\/www.km77.com\/revista\/author\/prueba-renault-clio\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/38573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=38573"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/38573\/revisions"}],"predecessor-version":[{"id":42814,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/38573\/revisions\/42814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/38373"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=38573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=38573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=38573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}