{"id":36764,"date":"2017-08-21T17:59:22","date_gmt":"2017-08-21T15:59:22","guid":{"rendered":"http:\/\/blogs.km77.com\/cinecuatroruedas\/?p=14489"},"modified":"2021-03-31T19:49:55","modified_gmt":"2021-03-31T17:49:55","slug":"los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/","title":{"rendered":"Los terroristas y el conflicto interior (no, no hablo de cine)"},"content":{"rendered":"<p>En el momento en que empiezo a escribir estas l\u00edneas se produce la detenci\u00f3n del hijo de perra que el jueves pasado decidi\u00f3 convertir las Ramblas en un maldito infierno. Han tardado cuatro d\u00edas en cogerle (parece que le han disparado, no detenido) pero al final ha ca\u00eddo. Han sido cuatro d\u00edas de verg\u00fcenza nacional, con peri\u00f3dicos imprimiendo algunas de las porquer\u00edas m\u00e1s repulsivas jam\u00e1s vistas (incluyendo mentiras y m\u00e1s mentiras), webs ofreciendo \u2018galer\u00edas de v\u00edctimas\u2019 con un centenar de fotos, videos de los atropellos que empezaban con un anuncio (en el peri\u00f3dico antes conocido como \u2018El Pa\u00eds\u2019 era un anuncio de ron) y un mont\u00f3n de tipejos y tipejas lanz\u00e1ndose mierda a la cara, en nombre del bien com\u00fan, en uno de los espect\u00e1culos circenses m\u00e1s lamentables que recuerdo haber vivido en mi vida adulta.<\/p>\n<p>&nbsp;<\/p>\n<p>Ni siquiera voy a molestarme en hablar de las redes sociales, porque aquello es un vertedero en el que pronto van a encontrar nuevas especies de aves carro\u00f1eras.<\/p>\n<p>&nbsp;<\/p>\n<p>Como periodista y como barcelon\u00e9s, he sentido asco, miedo y verg\u00fcenza. A veces de una en una, a veces las tres cosas de golpe. Que alguien utilice a los muertos para imponer su propia agenda ya me parece triste, que sean montones los que hagan lo propio (y algunos lo reconozcan abiertamente y sin problemas) es alarmante. Le dan a uno ganas de irse a vivir a la Ant\u00e1rtida.<\/p>\n<p>&nbsp;<\/p>\n<p>Los barceloneses no somos especiales: nos unimos a los madrile\u00f1os, a los parisinos o a los londinenses, en tanto que v\u00edctimas del terrorismo islamista (hoy ve\u00eda a una se\u00f1ora con velo decir que no tenemos que llamarlo \u2018islamista\u2019 porque si es islamista no puede ser terrorismo. Repito: terrorismo islamista) y parece que \u2018culpables\u2019 de no haber sabido ver que una pandilla de ni\u00f1os estaban entrando en un grave proceso de psicopat\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p>Una de las cosas que m\u00e1s gracia me hacen es escuchar a todo ese grupo de expertos echar la culpa a la sociedad occidental de que unos tipos se hagan volar por los aires, te atropellen o te acuchillen. \u201c\u00bfQu\u00e9 hemos hecho mal?\u201d se repiten unos a otros como si fueran el Or\u00e1culo de Delfos. Pues yo nada, oiga, yo paseo a mi perro, escribo, tengo una relaci\u00f3n m\u00e1s o menos decente con mis vecinos (a veces aprieto el bot\u00f3n de \u2018subir\u2019 cuando les veo entrar por la puerta, pero es solo porque su conversaci\u00f3n es terrible) y procuro no discriminar a nadie. Sin embargo, resulta que cuando ellos te matan sin m\u00e1s, somos nosotros los que debemos hacer una profunda reflexi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Lo s\u00e9, me estoy haciendo muy mayor.<\/p>\n<p>&nbsp;<\/p>\n<p>El otro d\u00eda le\u00ed a una periodista que dec\u00eda que los actos de estos j\u00f3venes \u2018mujaidines\u2019 se debe a que \u2018sufren un gran conflicto interior\u2019. Pues nada, a la que alguien me moleste me lo cargar\u00e9 a cuchilladas y luego le dir\u00e9 al juez que es que sufro un gran conflicto interior.<\/p>\n<p>&nbsp;<\/p>\n<p>Por suerte, me he decidido a abandonar twitter, no tengo cuenta de Facebook y leo la prensa extranjera o miro la BBC. No por esnobismo, por pura higiene mental.<\/p>\n<p>&nbsp;<\/p>\n<p>No me apetece hablar hoy de cine, perd\u00f3nenme. Debo sufrir alg\u00fan conflicto interior.<\/p>\n<p>Intentar\u00e9 solucionarlo hoy y volver ma\u00f1ana con \u00e1nimo renovado.<\/p>\n<p>&nbsp;<\/p>\n<p>Abrazos\/as fuertes amigos y amigas. Seguimos vivos\/as, al menos por ahora.<\/p>\n<p>&nbsp;<\/p>\n<p>T.G.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el momento en que empiezo a escribir estas l\u00edneas se produce la detenci\u00f3n del hijo de perra que el jueves pasado decidi\u00f3 convertir las Ramblas en un maldito infierno. Han tardado cuatro d\u00edas en cogerle (parece que le han disparado, no detenido) pero al final ha ca\u00eddo. Han sido cuatro d\u00edas de verg\u00fcenza nacional, [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3909],"tags":[],"class_list":["post-36764","post","type-post","status-publish","format-standard","hentry","category-cine-cuatro-ruedas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los terroristas y el conflicto interior (no, no hablo de cine) - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los terroristas y el conflicto interior (no, no hablo de cine) - Revista km77\" \/>\n<meta property=\"og:description\" content=\"En el momento en que empiezo a escribir estas l\u00edneas se produce la detenci\u00f3n del hijo de perra que el jueves pasado decidi\u00f3 convertir las Ramblas en un maldito infierno. Han tardado cuatro d\u00edas en cogerle (parece que le han disparado, no detenido) pero al final ha ca\u00eddo. Han sido cuatro d\u00edas de verg\u00fcenza nacional, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-21T15:59:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T17:49:55+00:00\" \/>\n<meta name=\"author\" content=\"Toni Garc\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toni Garc\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\\\/\"},\"author\":{\"name\":\"Toni Garc\u00eda\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/db291b06b78e5fe336ada62bee862008\"},\"headline\":\"Los terroristas y el conflicto interior (no, no hablo de cine)\",\"datePublished\":\"2017-08-21T15:59:22+00:00\",\"dateModified\":\"2021-03-31T17:49:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\\\/\"},\"wordCount\":616,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"articleSection\":[\"Cine a las Cuatro Ruedas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\\\/\",\"name\":\"Los terroristas y el conflicto interior (no, no hablo de cine) - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"datePublished\":\"2017-08-21T15:59:22+00:00\",\"dateModified\":\"2021-03-31T17:49:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cine a las Cuatro Ruedas\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Los terroristas y el conflicto interior (no, no hablo de cine)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Noticias y opiniones en km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/db291b06b78e5fe336ada62bee862008\",\"name\":\"Toni Garc\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/claqueta-cine-1-150x150.jpg\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/claqueta-cine-1-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/claqueta-cine-1-150x150.jpg\",\"caption\":\"Toni Garc\u00eda\"},\"description\":\"Cine a las cuatro ruedas es un blog dedicado al s\u00e9ptimo arte que empez\u00f3 tratando de mezclar cine y coches, como eso no funcion\u00f3 decidimos dejarlo solo en lo del cine. Eso s\u00ed, de cuando en cuando sacamos alg\u00fan coche.\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/cinecuatroruedas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los terroristas y el conflicto interior (no, no hablo de cine) - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/","og_locale":"es_ES","og_type":"article","og_title":"Los terroristas y el conflicto interior (no, no hablo de cine) - Revista km77","og_description":"En el momento en que empiezo a escribir estas l\u00edneas se produce la detenci\u00f3n del hijo de perra que el jueves pasado decidi\u00f3 convertir las Ramblas en un maldito infierno. Han tardado cuatro d\u00edas en cogerle (parece que le han disparado, no detenido) pero al final ha ca\u00eddo. Han sido cuatro d\u00edas de verg\u00fcenza nacional, [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/","og_site_name":"Revista km77","article_published_time":"2017-08-21T15:59:22+00:00","article_modified_time":"2021-03-31T17:49:55+00:00","author":"Toni Garc\u00eda","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Toni Garc\u00eda","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/"},"author":{"name":"Toni Garc\u00eda","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/db291b06b78e5fe336ada62bee862008"},"headline":"Los terroristas y el conflicto interior (no, no hablo de cine)","datePublished":"2017-08-21T15:59:22+00:00","dateModified":"2021-03-31T17:49:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/"},"wordCount":616,"commentCount":7,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"articleSection":["Cine a las Cuatro Ruedas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/","url":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/","name":"Los terroristas y el conflicto interior (no, no hablo de cine) - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"datePublished":"2017-08-21T15:59:22+00:00","dateModified":"2021-03-31T17:49:55+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/los-terroristas-y-el-conflicto-interior-no-no-hablo-de-cine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Cine a las Cuatro Ruedas","item":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/"},{"@type":"ListItem","position":3,"name":"Los terroristas y el conflicto interior (no, no hablo de cine)"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Noticias y opiniones en km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/db291b06b78e5fe336ada62bee862008","name":"Toni Garc\u00eda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/claqueta-cine-1-150x150.jpg","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/claqueta-cine-1-150x150.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/claqueta-cine-1-150x150.jpg","caption":"Toni Garc\u00eda"},"description":"Cine a las cuatro ruedas es un blog dedicado al s\u00e9ptimo arte que empez\u00f3 tratando de mezclar cine y coches, como eso no funcion\u00f3 decidimos dejarlo solo en lo del cine. Eso s\u00ed, de cuando en cuando sacamos alg\u00fan coche.","url":"https:\/\/www.km77.com\/revista\/author\/cinecuatroruedas\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/36764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=36764"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/36764\/revisions"}],"predecessor-version":[{"id":41231,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/36764\/revisions\/41231"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=36764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=36764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=36764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}