{"id":36753,"date":"2016-04-04T13:17:07","date_gmt":"2016-04-04T11:17:07","guid":{"rendered":"http:\/\/blogs.km77.com\/cinecuatroruedas\/?p=1862"},"modified":"2021-03-31T19:53:05","modified_gmt":"2021-03-31T17:53:05","slug":"tanto-monta-monta-tanto","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/","title":{"rendered":"Tanto monta, monta tanto"},"content":{"rendered":"<p>Buenas se\u00f1oras y se\u00f1ores,<\/p>\n<p>C\u00f3mo est\u00e1n ustedes? Yo a punto de tirarme de un entresuelo. No s\u00e9 si lo de los entresuelos es algo puramente barcelon\u00e9s o si lo tienen tambi\u00e9n por las Espa\u00f1as. La \u00faltima vez que estuve en Madrid y dije que quer\u00eda tirarme de un entresuelo, me miraron c\u00f3mo diciendo: \u201c\u00bfDe qu\u00e9 cojones habla este t\u00edo?\u201d.<\/p>\n<p>En mi bloque hay entresuelo, principal y primero.<\/p>\n<p>Y hasta aqu\u00ed mi comentario socio-arquitect\u00f3nico de calidad.<\/p>\n<p>Hoy quiero hablarles de uno de los mejores documentales que estrenar\u00e1n este a\u00f1o para ese sector cada vez m\u00e1s minoritario que son los cin\u00e9filos. Yo me lo pas\u00e9 pipa vi\u00e9ndolo pero no tiene ning\u00fan m\u00e9rito, porque yo soy fan de los dos sujetos de los que se ocupa la pel\u00edcula: <em>Hitchcok\/Truffaut<\/em>.<\/p>\n<p><em>Hitchcock\/Truffaut<\/em> fue en su origen un libro. El primer libro de cine que me regalaron mis padres (perm\u00edtanme a\u00f1adir este apunte autobiogr\u00e1fico) en el que magn\u00edfico director franc\u00e9s entrevistaba largamente al no menos magn\u00edfico director brit\u00e1nico. Era un volumen, un tomo que rezumaba amor al s\u00e9ptimo arte; una conversaci\u00f3n insuperable entre dos tipos que adoraban el cine.<\/p>\n<p>Truffaut siempre fue uno de mis \u00eddolos, probablemente porque era el director de cine m\u00e1s improbable de la historia: un delincuente juvenil con fama de pendenciero que gastaba muy mala hostia y que lleg\u00f3 a la direcci\u00f3n de forma casi rocambolesca. Les aconsejo que busquen su historia , aunque sea para comprobar que aquella frase de \u201cla realidad es siempre m\u00e1s extra\u00f1a que la ficci\u00f3n\u201d es indudablemente cierta.<br \/>\nEl franc\u00e9s firm\u00f3 algunas joyas condenadas a perdurar: <em>Jules y Jim<\/em>, <em>Los 400 golpes<\/em>, <em>La noche americana<\/em> o <em>El peque\u00f1o salvaje<\/em>, adem\u00e1s de aparecer en <em>Encuentros en la tercera fase<\/em>, una de las pel\u00edculas clave de la ciencia-ficci\u00f3n moderna, dirigida por un admirador suyo, Steven Spielberg.<\/p>\n<p>De Hitchcock tampoco hay mucho qu\u00e9 decir, porque ya se ha dicho todo. Uno de los mayores genios de la historia del cine, realizador de filmes como <em>Psicosis<\/em>, <em>Rebeca<\/em>, <em>Encadenados<\/em>, <em>Con la muerte en los talones<\/em>, <em>Extra\u00f1os en un tren<\/em>, <em>V\u00e9rtigo<\/em>, <em>La soga<\/em>, <em>Los p\u00e1jaros<\/em>, <em>Atrapa a un ladr\u00f3n<\/em> o <em>La ventana indiscreta<\/em>. No he tenido que mirar google, son las que puedo recordar de memoria, porque hay pocos directores que me hayan fascinado tanto, cuyos mecanismos narrativos hayan sido tan importantes en el devenir del s\u00e9ptimo arte.<\/p>\n<p>El documental es una aut\u00e9ntica gozada, con algunos de los mejores directores del mundo hablando de c\u00f3mo ambos influyeron en generaciones enteras de cineastas. Esta montado con solvencia y transcurre con fluidez (traducci\u00f3n: no es jodidamente aburrido).<\/p>\n<p>Si son ustedes cin\u00e9filos, o les gustan los buenos documentales, o tienen inter\u00e9s en saber un poco m\u00e1s de lo que sucede entre bambalinas, esta es una apuesta segura.<\/p>\n<p>Tambi\u00e9n me lo pase bien (probablemente porque ven\u00eda de ver esa cosa llamada <em>Batman vs Superman<\/em>) con <em>Orgullo y prejuicio y zombis<\/em>, pero no se la voy a recomendar, que son ustedes unos\/as salvajes\/as y no quiero que encuentren mi cuerpo en alg\u00fan sendero poco transitado.<\/p>\n<p>La que s\u00ed les voy a recomendar es <em>Altamira<\/em>, la obra maestra absoluta e integral de Antonio Banderas interpretando al se\u00f1or que descubri\u00f3 las pinturas de las famosas cuevas. No s\u00e9 qu\u00e9 toma Banderas pero yo tambi\u00e9n lo quiero: no recuerdo su \u00faltima pel\u00edcula decente (ni yo, ni nadie) pero a\u00fan as\u00ed se las ingenia para seguir trabajando, y eso debe valer algo, \u00bfno?<\/p>\n<p><em>Altamira<\/em> es uno de los mayores disparates (vale, reconozco que intentaba enga\u00f1arles con lo de \u2018obra maestra absoluta e integral\u2019) que he visto en el s.XXI, con un Banderas absolutamente delirante, con los ojos m\u00e1s abiertos que un b\u00faho cocain\u00f3mano y soltando frases que parecen haber sido escritas por un menor adicto al LSD.<\/p>\n<p>Pero ah\u00ed le tienen, cobrando y estrenando en no s\u00e9 cu\u00e1ntas pantallas, para demostrar que hay algunos tipos con suerte y otros que ni la huelen.<\/p>\n<p>Voy a seguir bebiendo vino, a ver si as\u00ed logro entender algo.<\/p>\n<p>Sean buenos\/as, yo har\u00e9 lo que pueda.<\/p>\n<p>Abrazos\/as,<br \/>\nT.G.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas se\u00f1oras y se\u00f1ores, C\u00f3mo est\u00e1n ustedes? Yo a punto de tirarme de un entresuelo. No s\u00e9 si lo de los entresuelos es algo puramente barcelon\u00e9s o si lo tienen tambi\u00e9n por las Espa\u00f1as. La \u00faltima vez que estuve en Madrid y dije que quer\u00eda tirarme de un entresuelo, me miraron c\u00f3mo diciendo: \u201c\u00bfDe qu\u00e9 [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3909],"tags":[],"class_list":["post-36753","post","type-post","status-publish","format-standard","hentry","category-cine-cuatro-ruedas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tanto monta, monta tanto - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tanto monta, monta tanto - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Buenas se\u00f1oras y se\u00f1ores, C\u00f3mo est\u00e1n ustedes? Yo a punto de tirarme de un entresuelo. No s\u00e9 si lo de los entresuelos es algo puramente barcelon\u00e9s o si lo tienen tambi\u00e9n por las Espa\u00f1as. La \u00faltima vez que estuve en Madrid y dije que quer\u00eda tirarme de un entresuelo, me miraron c\u00f3mo diciendo: \u201c\u00bfDe qu\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-04T11:17:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T17:53:05+00:00\" \/>\n<meta name=\"author\" content=\"Toni Garc\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toni Garc\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/tanto-monta-monta-tanto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/tanto-monta-monta-tanto\\\/\"},\"author\":{\"name\":\"Toni Garc\u00eda\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/db291b06b78e5fe336ada62bee862008\"},\"headline\":\"Tanto monta, monta tanto\",\"datePublished\":\"2016-04-04T11:17:07+00:00\",\"dateModified\":\"2021-03-31T17:53:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/tanto-monta-monta-tanto\\\/\"},\"wordCount\":733,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"articleSection\":[\"Cine a las Cuatro Ruedas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/tanto-monta-monta-tanto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/tanto-monta-monta-tanto\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/tanto-monta-monta-tanto\\\/\",\"name\":\"Tanto monta, monta tanto - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"datePublished\":\"2016-04-04T11:17:07+00:00\",\"dateModified\":\"2021-03-31T17:53:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/tanto-monta-monta-tanto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/tanto-monta-monta-tanto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/tanto-monta-monta-tanto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cine a las Cuatro Ruedas\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/cine-cuatro-ruedas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tanto monta, monta tanto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Noticias y opiniones en km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/db291b06b78e5fe336ada62bee862008\",\"name\":\"Toni Garc\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/claqueta-cine-1-150x150.jpg\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/claqueta-cine-1-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/claqueta-cine-1-150x150.jpg\",\"caption\":\"Toni Garc\u00eda\"},\"description\":\"Cine a las cuatro ruedas es un blog dedicado al s\u00e9ptimo arte que empez\u00f3 tratando de mezclar cine y coches, como eso no funcion\u00f3 decidimos dejarlo solo en lo del cine. Eso s\u00ed, de cuando en cuando sacamos alg\u00fan coche.\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/cinecuatroruedas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tanto monta, monta tanto - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/","og_locale":"es_ES","og_type":"article","og_title":"Tanto monta, monta tanto - Revista km77","og_description":"Buenas se\u00f1oras y se\u00f1ores, C\u00f3mo est\u00e1n ustedes? Yo a punto de tirarme de un entresuelo. No s\u00e9 si lo de los entresuelos es algo puramente barcelon\u00e9s o si lo tienen tambi\u00e9n por las Espa\u00f1as. La \u00faltima vez que estuve en Madrid y dije que quer\u00eda tirarme de un entresuelo, me miraron c\u00f3mo diciendo: \u201c\u00bfDe qu\u00e9 [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/","og_site_name":"Revista km77","article_published_time":"2016-04-04T11:17:07+00:00","article_modified_time":"2021-03-31T17:53:05+00:00","author":"Toni Garc\u00eda","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Toni Garc\u00eda","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/"},"author":{"name":"Toni Garc\u00eda","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/db291b06b78e5fe336ada62bee862008"},"headline":"Tanto monta, monta tanto","datePublished":"2016-04-04T11:17:07+00:00","dateModified":"2021-03-31T17:53:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/"},"wordCount":733,"commentCount":5,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"articleSection":["Cine a las Cuatro Ruedas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/","url":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/","name":"Tanto monta, monta tanto - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"datePublished":"2016-04-04T11:17:07+00:00","dateModified":"2021-03-31T17:53:05+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/tanto-monta-monta-tanto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Cine a las Cuatro Ruedas","item":"https:\/\/www.km77.com\/revista\/cine-cuatro-ruedas\/"},{"@type":"ListItem","position":3,"name":"Tanto monta, monta tanto"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Noticias y opiniones en km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/db291b06b78e5fe336ada62bee862008","name":"Toni Garc\u00eda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/claqueta-cine-1-150x150.jpg","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/claqueta-cine-1-150x150.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/claqueta-cine-1-150x150.jpg","caption":"Toni Garc\u00eda"},"description":"Cine a las cuatro ruedas es un blog dedicado al s\u00e9ptimo arte que empez\u00f3 tratando de mezclar cine y coches, como eso no funcion\u00f3 decidimos dejarlo solo en lo del cine. Eso s\u00ed, de cuando en cuando sacamos alg\u00fan coche.","url":"https:\/\/www.km77.com\/revista\/author\/cinecuatroruedas\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/36753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=36753"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/36753\/revisions"}],"predecessor-version":[{"id":41557,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/36753\/revisions\/41557"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=36753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=36753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=36753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}