{"id":35340,"date":"2010-11-08T17:07:05","date_gmt":"2010-11-08T16:07:05","guid":{"rendered":"http:\/\/blogs.km77.com\/arturoandres\/?p=1297"},"modified":"2021-03-31T20:11:47","modified_gmt":"2021-03-31T18:11:47","slug":"prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/","title":{"rendered":"Prueba de consumo (29): Fiat 500 1.3D MultiJet II 95 CV"},"content":{"rendered":"<p>Por fin las aguas han vuelto, m\u00e1s o menos, a su cauce. Desde que se realiz\u00f3, con el <a href=\"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/420\/prueba-de-consumo-6-fiat-500-c-1-3d-multijet-ii-95-cv\/\" target=\"_blank\" rel=\"noopener\"><strong>Fiat 500 Convertible<\/strong><\/a>, la primera prueba de la \u00faltima y te\u00f3ricamente muy mejorada versi\u00f3n del peque\u00f1o turbodi\u00e9sel 1.3 del grupo <strong>Fiat<\/strong>, nos qued\u00f3 un resquemor respecto al resultado conseguido. El cual se acrecent\u00f3 cuando, semanas m\u00e1s tarde, el <strong>Opel Corsa ecoFlex<\/strong>, dotado de la misma mec\u00e1nica, consegu\u00eda un resultado mucho m\u00e1s brillante, y eso a pesar de ser, al menos te\u00f3ricamente, nada menos que 200 kilos m\u00e1s pesado. As\u00ed que, tal y como nos hab\u00edamos prometido a nosotros mismos y a los asiduos del blog, en cuanto ha habido ocasi\u00f3n hemos vuelto a realizar la prueba del peque\u00f1o Fiat, pero en esta ocasi\u00f3n a bordo de la carrocer\u00eda normal con techo fijo, y no con el de lona, por muy bien tirante que en apariencia quedase. Y a pesar tambi\u00e9n de las explicaciones de Fiat, que asegura que el Cx aerodin\u00e1mico es exactamente el mismo en las dos versiones. Tambi\u00e9n dicen que el peso es igual, cuando parece l\u00f3gico que el de techo de lona sea algo m\u00e1s pesado, al sustituir poco m\u00e1s de un metro cuadrado de chapa, con su guarnecido interior, por una doble o triple capa de lona, los refuerzos laterales y carriles para que \u00e9ste deslice, y el sistema el\u00e9ctrico, con motor y todo, para mandar la conversi\u00f3n.<\/p>\n<p>Pero el hecho es que los datos son suyos, y por lo tanto, la ficha t\u00e9cnica del <strong>500<\/strong> es id\u00e9ntica a la del 500-C, ya que tambi\u00e9n las cotas de la carrocer\u00eda se mantienen inamovibles. De modo que la habitual ficha t\u00e9cnica resumida sigue quedando as\u00ed:<\/p>\n<table style=\"height: 223px;\" border=\"1\" cellspacing=\"0\" cellpadding=\"4\" width=\"747\">\n<col width=\"256*\"><\/col>\n<tbody>\n<tr>\n<td width=\"100%\" valign=\"TOP\"><strong><span style=\"text-decoration: underline;\">Fiat 500 1.3D Multijet II<\/span>:<\/strong><\/p>\n<p><strong>Motor: 1.248 cc; 95 CV a 4.000 rpm; 20,4 m.kg a 1.500 rpm. <\/strong><\/p>\n<p><strong>Transmisi\u00f3n: Caja de cinco marchas, con 44,0 km\/h a 1.000 rpm en 5\u00aa. <\/strong><\/p>\n<p><strong>Neum\u00e1ticos: 195\/45-16. <\/strong><\/p>\n<p><strong>Cotas (longitud\/anchura\/altura): 3,55\/1,63\/1,49  metros. <\/strong><\/p>\n<p><strong>Peso (sin conductor, con dep\u00f3sito lleno): 980 kg. <\/strong><\/p>\n<p><strong>Velocidad  m\u00e1xima: 180 km\/h. <\/strong><\/p>\n<p><strong>Consumo extra-urbano: 3,3 l\/100 km. <\/strong><\/p>\n<p><strong>Emisi\u00f3n ponderada  de CO2: 104 g\/km.<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1307\" title=\"Fiat 500\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/files\/2010\/11\/070705_F_Fiat500_482.jpg\" alt=\"Fiat 500\" width=\"700\" height=\"459\" \/><\/p>\n<p>Recordemos, a efectos comparativos y para los tres coches que hemos probado con el mismo motor de 95 CV, que el Corsa ecoFlex tiraba de un desarrollo algo m\u00e1s largo en 5\u00aa, de 47,8 km\/h, a cambio de disfrutar de una mejor aerodin\u00e1mica, ya que su Cx de 0,30 le permite tener un producto final S.Cx de 0,64. Por su parte, el 500, en ambas versiones, presume de un Cx de 0,33; que podr\u00eda ser cierto, con suerte, para la versi\u00f3n que acabamos de probar con techo fijo, dando lugar a un S.Cx de entre 0,67 y 0,68; en cuanto al convertible, su Cx sin duda est\u00e1 entre 0,34 y 0,35, y su producto S.Cx, en cualquier caso, por encima de 0,70. O sea que el Corsa compensa sobradamente, gracias a su mejor aerodin\u00e1mica, a su desarrollo algo m\u00e1s largo y a sus neum\u00e1ticos 185\/55-15 de baja resistencia a la rodadura, el h\u00e1ndicap que le supone su mayor peso. Conviene recordar que el Fiat 500, en ninguna de sus dos variantes de techo, pretende ser un coche \u201ceco\u201d: lo \u00fanico que lleva es Start\/Stop, pero no tiene optimizaciones aerodin\u00e1micas, ni desarrollo largo, ni alternador inteligente ni neum\u00e1ticos especiales.<\/p>\n<p>Y tras de todas estas advertencias, aqu\u00ed tenemos el nuevo resultado obtenido por el <strong>Fiat 500 Multijet II<\/strong> de 95 CV, en la carrocer\u00eda que podr\u00edamos considerar como la m\u00e1s normal, y tambi\u00e9n m\u00e1s aerodin\u00e1mica:<\/p>\n<table style=\"height: 33px;\" border=\"1\" cellspacing=\"0\" cellpadding=\"4\" width=\"743\">\n<col width=\"256*\"><\/col>\n<tbody>\n<tr>\n<td width=\"100%\" valign=\"TOP\"><strong><span style=\"text-decoration: underline;\">Fiat 500-C M-Jet II<\/span>: <\/strong><\/p>\n<p><strong>Consumo: 5,62 l\/100 km. <\/strong><\/p>\n<p><strong>Promedio: 103,9 km\/h.<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1305\" title=\"Fiat 500\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/files\/2010\/11\/070705_F_Fiat500_442.jpg\" alt=\"Fiat 500\" width=\"700\" height=\"467\" \/><\/p>\n<p>Lo primero a rese\u00f1ar es que ambas unidades, el primer Convertible y el actual berlina, calzaban los neum\u00e1ticos opcionales de 195\/45-16, que algo deben perjudicar respecto a los de serie 185\/55-16, que son de la misma dimensi\u00f3n que los montados en el Corsa ecoFlex, si bien, en el caso de los Fiat, no son de baja resistencia a la rodadura. Y lo segundo a tener en cuenta es que ambos han realizado el recorrido en exactamente el mismo tiempo (4 horas y 51 minutos), por lo que la comparaci\u00f3n no puede estar m\u00e1s igualada. Y el resultado es significativo: recordando que el Convertible consumi\u00f3 a raz\u00f3n de 5,95 l\/100 km, la conclusi\u00f3n es que el cambio de techo supone un ahorro de nada menos que un tercio de litro cada 100 kil\u00f3metros; no est\u00e1 nada mal, y la cifra ya entra un poco m\u00e1s dentro de lo razonable.<\/p>\n<p>Vamos a considerarlo dentro de una panor\u00e1mica un poco m\u00e1s amplia que la simple comparaci\u00f3n con el Corsa ecoFlex, aunque \u00e9sta tiene la ventaja de que es con id\u00e9ntico motor. El resultado ahora conseguido es el mismo del Fiesta ECOnetic, si bien tardando nada menos que once minutos m\u00e1s, debido en parte a que no es lo mismo una cilindrada de 1,25 litros que una de 1,6 litros, por m\u00e1s que el par m\u00e1ximo de cat\u00e1logo sea aproximadamente igual. Pero sobre todo se debe a que la eficacia del comportamiento rutero est\u00e1 muy a favor del Fiesta, que consigui\u00f3 realizar el recorrido en 4 horas y 40 minutos, el mismo tiempo que a su vez logr\u00f3 el <strong>Peugeot 207<\/strong> \u201c99 gr\u201d, que por su parte consumi\u00f3 todav\u00eda mucho menos (5,17 l\/100 km), gracias a su muy bien afinada aerodin\u00e1mica. Un resultado en tiempo casi similar consigui\u00f3 el <strong>Citro\u00ebn DS-3<\/strong>, si bien a costa de un consumo superior incluso al del 500 y el Fiesta. Por su parte, el <strong>Toyota Yaris<\/strong>, que como el 500 no tiene apenas ninguna optimizaci\u00f3n especial de cara al consumo, no fue mucho m\u00e1s r\u00e1pido que el Fiat (s\u00f3lo tres minutos), pero su consumo casi igual\u00f3 al del 207, quedando en 5,19 l\/100 km. Lo cual confirma que, en los motores muy miniaturizados, la sofisticada culata doble \u00e1rbol de 16 v\u00e1lvulas no acaba de ser un argumento v\u00e1lido; esto lo comprobaremos, esperamos que dentro de no mucho, con alguna otra prueba del <strong>Renault<\/strong> 1.5-dCi que ya sometimos al recorrido impulsando a la berlina <strong>M\u00e9gane<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1303\" title=\"Fiat 500\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/files\/2010\/11\/070705_F_Fiat500_451.jpg\" alt=\"Fiat 500\" width=\"700\" height=\"463\" \/><\/p>\n<p>As\u00ed pues, ya tenemos m\u00e1s o menos bien centrado el rendimiento del Multijet II de 95 CV: sus prestaciones son notables para su cilindrada, y tira con fuerza desde menos de 1.500 rpm, pero no resulta especialmente econ\u00f3mico (aun si\u00e9ndole en valores absolutos) frente a otros competidores como el 1.4 de Toyota, el 1.5 de Renault y los 1.6 tanto de <strong>PSA<\/strong>\/<strong>Ford<\/strong> como del grupo <strong>VAG<\/strong>. Y por su parte el 500, pese a su tama\u00f1o y peso, no da m\u00e1s de s\u00ed debido a que la aerodin\u00e1mica de su redondeada carrocer\u00eda estropea lo que por tama\u00f1o y peso deber\u00eda salir ganando.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por fin las aguas han vuelto, m\u00e1s o menos, a su cauce. Desde que se realiz\u00f3, con el Fiat 500 Convertible, la primera prueba de la \u00faltima y te\u00f3ricamente muy mejorada versi\u00f3n del peque\u00f1o turbodi\u00e9sel 1.3 del grupo Fiat, nos qued\u00f3 un resquemor respecto al resultado conseguido. El cual se acrecent\u00f3 cuando, semanas m\u00e1s tarde, [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":1299,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3910],"tags":[4145,9410,1263,11385,9508,9509,20,3925,9398,9336,11379,2471,48,2975,6570],"class_list":["post-35340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curvas-enlazadas","tag-4145","tag-citroen-ds-3","tag-fiat","tag-fiat-pruebas-de-consumo","tag-fiat-500-convertible","tag-fiat-500-multijet-ii","tag-ford","tag-megane","tag-opel-corsa-ecoflex","tag-peugeot-207","tag-pruebas-de-consumo","tag-psa","tag-renault","tag-toyota-yaris","tag-vag"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prueba de consumo (29): Fiat 500 1.3D MultiJet II 95 CV - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prueba de consumo (29): Fiat 500 1.3D MultiJet II 95 CV - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Por fin las aguas han vuelto, m\u00e1s o menos, a su cauce. Desde que se realiz\u00f3, con el Fiat 500 Convertible, la primera prueba de la \u00faltima y te\u00f3ricamente muy mejorada versi\u00f3n del peque\u00f1o turbodi\u00e9sel 1.3 del grupo Fiat, nos qued\u00f3 un resquemor respecto al resultado conseguido. El cual se acrecent\u00f3 cuando, semanas m\u00e1s tarde, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2010-11-08T16:07:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T18:11:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/05\/024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"248\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A. de A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"A. de A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/\"},\"author\":{\"name\":\"A. de A.\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/9528542f10577efe637078df52f3a1ea\"},\"headline\":\"Prueba de consumo (29): Fiat 500 1.3D MultiJet II 95 CV\",\"datePublished\":\"2010-11-08T16:07:05+00:00\",\"dateModified\":\"2021-03-31T18:11:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/\"},\"wordCount\":1138,\"commentCount\":30,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/024.jpg\",\"keywords\":[\"500\",\"Citro\u00ebn DS-3\",\"Fiat\",\"Fiat\",\"Fiat 500 Convertible\",\"Fiat 500 Multijet II\",\"Ford\",\"megane\",\"Opel Corsa ecoFLEX\",\"Peugeot 207\",\"Pruebas de consumo\",\"PSA\",\"Renault\",\"Toyota Yaris\",\"VAG\"],\"articleSection\":[\"Curvas Enlazadas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/\",\"name\":\"Prueba de consumo (29): Fiat 500 1.3D MultiJet II 95 CV - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/024.jpg\",\"datePublished\":\"2010-11-08T16:07:05+00:00\",\"dateModified\":\"2021-03-31T18:11:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/024.jpg\",\"width\":700,\"height\":248},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curvas Enlazadas\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prueba de consumo (29): Fiat 500 1.3D MultiJet II 95 CV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Revista de km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/9528542f10577efe637078df52f3a1ea\",\"name\":\"A. de A.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/arturo_andres_curvasenlazadas-150x111.jpg\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/arturo_andres_curvasenlazadas-150x111.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/arturo_andres_curvasenlazadas-150x111.jpg\",\"caption\":\"A. de A.\"},\"description\":\"Probablemente el m\u00e1s veterano de los periodistas del motor que sigue \u201cactivamente activo\u201d. Al margen de divulgaci\u00f3n t\u00e9cnica, llevar algunos \u201cConsultorios del lector\u201d y otros temas variados, su especialidad -desde Navidades de 1965- viene siendo las pruebas de coches, centr\u00e1ndose muy espec\u00edficamente en el control del consumo. Para lo cual ha ido dejando \u201cen herencia\u201d en las diversas publicaciones en las que ha colaborado diversos recorridos fijos, que permitan la comparaci\u00f3n de resultados en igualdad de condiciones.\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/arturoandres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prueba de consumo (29): Fiat 500 1.3D MultiJet II 95 CV - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/","og_locale":"es_ES","og_type":"article","og_title":"Prueba de consumo (29): Fiat 500 1.3D MultiJet II 95 CV - Revista km77","og_description":"Por fin las aguas han vuelto, m\u00e1s o menos, a su cauce. Desde que se realiz\u00f3, con el Fiat 500 Convertible, la primera prueba de la \u00faltima y te\u00f3ricamente muy mejorada versi\u00f3n del peque\u00f1o turbodi\u00e9sel 1.3 del grupo Fiat, nos qued\u00f3 un resquemor respecto al resultado conseguido. El cual se acrecent\u00f3 cuando, semanas m\u00e1s tarde, [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/","og_site_name":"Revista km77","article_published_time":"2010-11-08T16:07:05+00:00","article_modified_time":"2021-03-31T18:11:47+00:00","og_image":[{"width":700,"height":248,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/05\/024.jpg","type":"image\/jpeg"}],"author":"A. de A.","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"A. de A.","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/"},"author":{"name":"A. de A.","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/9528542f10577efe637078df52f3a1ea"},"headline":"Prueba de consumo (29): Fiat 500 1.3D MultiJet II 95 CV","datePublished":"2010-11-08T16:07:05+00:00","dateModified":"2021-03-31T18:11:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/"},"wordCount":1138,"commentCount":30,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/05\/024.jpg","keywords":["500","Citro\u00ebn DS-3","Fiat","Fiat","Fiat 500 Convertible","Fiat 500 Multijet II","Ford","megane","Opel Corsa ecoFLEX","Peugeot 207","Pruebas de consumo","PSA","Renault","Toyota Yaris","VAG"],"articleSection":["Curvas Enlazadas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/","url":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/","name":"Prueba de consumo (29): Fiat 500 1.3D MultiJet II 95 CV - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/05\/024.jpg","datePublished":"2010-11-08T16:07:05+00:00","dateModified":"2021-03-31T18:11:47+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/05\/024.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/05\/024.jpg","width":700,"height":248},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-29-fiat-500-1-3d-multijet-ii-95-cv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Curvas Enlazadas","item":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/"},{"@type":"ListItem","position":3,"name":"Prueba de consumo (29): Fiat 500 1.3D MultiJet II 95 CV"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Revista de km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/9528542f10577efe637078df52f3a1ea","name":"A. de A.","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/arturo_andres_curvasenlazadas-150x111.jpg","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/arturo_andres_curvasenlazadas-150x111.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/arturo_andres_curvasenlazadas-150x111.jpg","caption":"A. de A."},"description":"Probablemente el m\u00e1s veterano de los periodistas del motor que sigue \u201cactivamente activo\u201d. Al margen de divulgaci\u00f3n t\u00e9cnica, llevar algunos \u201cConsultorios del lector\u201d y otros temas variados, su especialidad -desde Navidades de 1965- viene siendo las pruebas de coches, centr\u00e1ndose muy espec\u00edficamente en el control del consumo. Para lo cual ha ido dejando \u201cen herencia\u201d en las diversas publicaciones en las que ha colaborado diversos recorridos fijos, que permitan la comparaci\u00f3n de resultados en igualdad de condiciones.","url":"https:\/\/www.km77.com\/revista\/author\/arturoandres\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/35340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=35340"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/35340\/revisions"}],"predecessor-version":[{"id":44531,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/35340\/revisions\/44531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/1299"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=35340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=35340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=35340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}