{"id":30407,"date":"2016-11-14T13:15:40","date_gmt":"2016-11-14T12:15:40","guid":{"rendered":"http:\/\/blogs.km77.com\/engendromecanico\/?p=30407"},"modified":"2021-03-31T19:51:36","modified_gmt":"2021-03-31T17:51:36","slug":"pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/","title":{"rendered":"Pruebas de consumo: Hyundai IONIQ vs KIA Niro vs Toyota Prius"},"content":{"rendered":"<p>Hemos hecho cinco recorridos diferentes\u00a0conduciendo simult\u00e1neamente un <a href=\"https:\/\/www.km77.com\/01\/hyundai\/ioniq\/2016\/informacion-precios-323269-p.html\" target=\"_blank\" rel=\"noopener\">Hyundai IONIQ<\/a>, un <a href=\"https:\/\/www.km77.com\/01\/kia\/niro\/2017\/informacion-precio-323865-p.html\" target=\"_blank\" rel=\"noopener\">KIA Niro<\/a> y un <a href=\"https:\/\/www.km77.com\/01\/toyota\/prius\/2016\/informacion-y-precio-321169-p.html\" target=\"_blank\" rel=\"noopener\">Toyota Prius<\/a>\u00a0(pinchando en los enlaces se accede a la prueba que hay publicada en km77.com de cada modelo). Hemos constatado diferencias significativas de consumo de carburante entre ellos. El Prius fue siempre el modelo m\u00e1s eficiente, seguido del IONIQ y en \u00faltima posici\u00f3n del Niro. El consumo del Niro ha sido, en el mejor de los casos, un 20,5 % superior al del Prius.<br \/>\nHemos comparado estos tres veh\u00edculos porque los tres tienen un sistema h\u00edbrido de impulsi\u00f3n de potencia parecida y compuesto en todos los casos por un motor el\u00e9ctrico y otro de gasolina. El Hyundai y el Toyota son muy parecidos por dimensiones y estilo de carrocer\u00eda. El KIA se diferencia de ellos por tener un aspecto m\u00e1s pr\u00f3ximo al de un peque\u00f1o todoterreno.<br \/>\nLas unidades de IONIQ y de Niro que hemos probado ten\u00edan el nivel de equipamiento m\u00e1s costoso, que incluye de serie unos neum\u00e1ticos de mayor tama\u00f1o y, a consecuencia de ello, su consumo medio homologado es m\u00e1s elevado que el de las versi\u00f3n menos equipadas. En el Prius no hay niveles de equipamiento, Toyota comercializa una \u00fanica versi\u00f3n. Bajo estas l\u00edneas hay una tabla con datos espec\u00edficos de las unidades probadas y con otros de homologaci\u00f3n. Es posible consultar m\u00e1s datos <a href=\"https:\/\/www.km77.com\/precios\/comparador\/comparar\/54343\/54349\/53051\" target=\"_blank\" rel=\"noopener\">esta ficha comparativa<\/a>.<\/p>\n<table width=\"700\">\n<tbody>\n<tr style=\"text-align: center\">\n<td width=\"265\"><\/td>\n<td style=\"text-align: center\" width=\"145\"><strong>Hyundai IONIQ<\/strong><\/td>\n<td width=\"145\"><strong>KIA Niro<\/strong><\/td>\n<td width=\"145\"><strong>Toyota Prius<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Nivel de equipamiento<\/td>\n<td style=\"text-align: center\">Style<\/td>\n<td style=\"text-align: center\">Emotion<\/td>\n<td style=\"text-align: center\">&#8212;<\/td>\n<\/tr>\n<tr>\n<td>Kil\u00f3metros de la unidad<\/td>\n<td style=\"text-align: center\">1600<\/td>\n<td style=\"text-align: center\">3200<\/td>\n<td style=\"text-align: center\">11 400<\/td>\n<\/tr>\n<tr>\n<td>Marca y modelo de neum\u00e1ticos<\/td>\n<td style=\"text-align: center\">Michelin Primacy 3<\/td>\n<td style=\"text-align: center\">Michelin Pilot Sport 4<\/td>\n<td style=\"text-align: center\">Toyo NanoEnergy R41<\/td>\n<\/tr>\n<tr>\n<td>Medidas de neum\u00e1ticos<\/td>\n<td style=\"text-align: center\">225\/45 R17<\/td>\n<td style=\"text-align: center\">225\/45 R18<\/td>\n<td style=\"text-align: center\">215\/45 R17<\/td>\n<\/tr>\n<tr>\n<td>Masa seg\u00fan homologaci\u00f3n (kg)<\/td>\n<td style=\"text-align: center\">1445<\/td>\n<td style=\"text-align: center\">1500<\/td>\n<td style=\"text-align: center\">1450<\/td>\n<\/tr>\n<tr>\n<td>Coeficiente aerodin\u00e1mico (Cx)<\/td>\n<td style=\"text-align: center\">0,24<\/td>\n<td style=\"text-align: center\">0,29<\/td>\n<td style=\"text-align: center\">0,24<\/td>\n<\/tr>\n<tr>\n<td>Potencia m\u00e1xima (CV)<\/td>\n<td style=\"text-align: center\">141<\/td>\n<td style=\"text-align: center\">141<\/td>\n<td style=\"text-align: center\">122<\/td>\n<\/tr>\n<tr>\n<td>Consumo urbano homologado (l\/100 km)<\/td>\n<td style=\"text-align: center\">3,9<\/td>\n<td style=\"text-align: center\">4,4<\/td>\n<td style=\"text-align: center\">3,3<\/td>\n<\/tr>\n<tr>\n<td>Consumo extraurbano homologado (l\/100 km)<\/td>\n<td style=\"text-align: center\">3,9<\/td>\n<td style=\"text-align: center\">4,5<\/td>\n<td style=\"text-align: center\">3,3<\/td>\n<\/tr>\n<tr>\n<td>Consumo medio homologado (l\/100 km)<\/td>\n<td style=\"text-align: center\">3,9<\/td>\n<td style=\"text-align: center\">4,4<\/td>\n<td style=\"text-align: center\">3,3<\/td>\n<\/tr>\n<tr>\n<td>Precio (\u20ac)<\/td>\n<td style=\"text-align: center\">28 100<\/td>\n<td style=\"text-align: center\">26 200<\/td>\n<td style=\"text-align: center\">29 990<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>En todos los recorridos hemos circulado en l\u00ednea, es decir, uno tras otro. En v\u00edas r\u00e1pidas siempre hemos dejado una distancia suficiente para que el que iba delante no favoreciera aerodin\u00e1micamente al que iba detr\u00e1s. Los conductores y la posici\u00f3n de los veh\u00edculos en la l\u00ednea han variado al comienzo de cada recorrido y, en algunos casos, dentro del mismo. Los valores de consumo que exponemos en este texto los hemos obtenido aplicando a cada ordenador de viaje el porcentaje de error que previamente hab\u00edamos calculado para cada veh\u00edculo.<br \/>\n<strong>Recorrido 1<\/strong><br \/>\nEs el recorrido de consumo que hacemos con todos los coches que probamos en km77.com. Es un trayecto de ida y vuelta de 143,3 km por la autov\u00eda\u00a0A1, cubiertos a una velocidad media de 120 km\/h. Los cambios de pendiente son numerosos y el m\u00e1s importante es el puerto de Somosierra. Siempre se hace con el compresor del climatizador desconectado. Bajo estas l\u00edneas hay un gr\u00e1fico con los cambios de nivel.<br \/>\n<img decoding=\"async\" class=\"size-full wp-image-30431 aligncenter\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/grafica2.jpg\" alt=\"grafica2\" width=\"700\" height=\"248\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/grafica2.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/grafica2-480x170.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\nEl Toyota Prius logra el consumo m\u00e1s bajo de todos y uno de los mejores que hemos obtenido nunca en km77.com (el r\u00e9cord lo tiene por el momento el Volkswagen Passat BlueMotion 1.6 TDI 120 CV con 4,5 l\/100 km). El consumo del IONIQ es un 3,8% mayor, mientras que el del Niro es un 22,6% m\u00e1s elevado.<\/p>\n<ul>\n<li>Toyota Prius: 5,3 l\/100 km<\/li>\n<li>Hyundai IONIQ: 5,5 l\/100 km (3,8%)<\/li>\n<li>KIA Niro: 6,5 l\/100 km (22,6%)<\/li>\n<\/ul>\n<p><strong>Recorrido 2<\/strong><br \/>\nEl punto de partida es la gasolinera de Repsol que hay en el kil\u00f3metro 49 de la autov\u00eda A1 (900 metros sobre el nivel del mar) y el punto final es el cruce de la calle Alcalde Henche de la Plata con la avenida de Francisco Pi y Margall (690 m.s.n.m), en Madrid. Es un trayecto de 44 kil\u00f3metros que discurre casi por completo por la autov\u00eda A1 y la autopista de circunvalaci\u00f3n M40. Recorrimos la distancia a una media de 102 km\/h y con el climatizador desconectado. El tr\u00e1fico fue fluido y la temperatura ambiente fue 18 \u00baC.<br \/>\n<img decoding=\"async\" class=\"size-full wp-image-30436 aligncenter\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/recorrido-2.jpg\" alt=\"recorrido-2\" width=\"700\" height=\"450\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/recorrido-2.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/recorrido-2-480x309.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\n<img decoding=\"async\" class=\"size-full wp-image-30441 aligncenter\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/31.jpg\" alt=\"3\" width=\"700\" height=\"190\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/31.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/31-480x130.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\nLa diferencia de consumo del Toyota Prius ha aumentado con respecto a los otros dos modelos, especialmente contra el IONIQ, que ahora es de un 9,1%. El KIA Niro es, otra vez, el menos eficiente.<\/p>\n<ul>\n<li>Toyota Prius: 4,0 l\/100 km<\/li>\n<li>Hyundai IONIQ: 4,4 l\/100 km (+9,1 %)<\/li>\n<li>KIA Niro: 5,0 l\/100 km (+25,0 %)<\/li>\n<\/ul>\n<p><strong>Recorrido 3<\/strong><br \/>\nEste recorrido tiene una longitud de 13 km, comienza donde termina el anterior \u2014cruce de la calle Alcalde Henche de la Plata con la avenida de Francisco Pi y Margall\u2014 y termina en el paseo de Camoens, a 621 m.s.n.m.\u00a0Los primeros 4,5 km transcurren principalmente por la\u00a0autopista de acceso a Madrid M-11. El resto de la ruta es por calles y avenidas amplias de Madrid, como el Paseo de la Castellana, la calle de Bravo Murilo, la calle de Guzm\u00e1n el Bueno y la calle de Alberto Aguilera. El tr\u00e1fico fue medianamente fluido y conseguimos completar el trayecto a una velocidad media de 26 km\/h. Durante todo el recorrido el climatizador de los tres coches estuvo conectado en modo autom\u00e1tico y ajustado a una temperatura de 22\u00baC. La temperatura del ambiente era 20\u00baC.<br \/>\n<img decoding=\"async\" class=\"size-full wp-image-30443 aligncenter\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/recorrido-3.jpg\" alt=\"recorrido-3\" width=\"700\" height=\"450\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/recorrido-3.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/recorrido-3-480x309.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\n<img decoding=\"async\" class=\"size-full wp-image-30444 aligncenter\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/4.jpg\" alt=\"4\" width=\"700\" height=\"190\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/4.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/4-480x130.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\nEl IONIQ y el Niro han gastado, respectivamente, un 24,2 y un 21,2% m\u00e1s que el Prius. Este ha sido el \u00fanico recorrido en el que el Niro ha consumido menos que el IONIQ, aunque por poco.<\/p>\n<ul>\n<li>Toyota Prius: 3,3 l\/100 km<\/li>\n<li>KIA Niro: 4,0 l\/100 km (+21,2 %)<\/li>\n<li>Hyundai IONIQ: 4,1 l\/100 km (+24,2 %)<\/li>\n<\/ul>\n<p><strong>Recorrido 4<\/strong><br \/>\nSon 10 kil\u00f3metros completamente de ciudad. El punto de inicio es el final del recorrido 3 \u2014paseo de Camoens\u2014 y el punto de finalizaci\u00f3n es la\u00a0gasolinera Repsol que hay en el cruce que forman la calle de Bravo Murillo y la calle de R\u00edos Rosas (695 m.s.n.m.). Necesitamos 58 minutos\u00a0para completar la ruta, lo que supone una media lenta, de 10 km\/h.\u00a0Una parte de ella tuvo lugar en la Calle Gran V\u00eda, donde el tr\u00e1fico fue muy denso y tardamos 47 minutos en recorrer 5,5 kil\u00f3metros (una media de 7,0 km\/h). Como en el recorrido 3, el climatizador estuvo conectado en modo autom\u00e1tico a 22\u00baC. La temperatura ambiente era 21\u00baC.<br \/>\n<img decoding=\"async\" class=\"size-full wp-image-30448 aligncenter\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/recorrido-4.jpg\" alt=\"recorrido-4\" width=\"700\" height=\"450\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/recorrido-4.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/recorrido-4-480x309.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\n<img decoding=\"async\" class=\"size-full wp-image-30450 aligncenter\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/6.jpg\" alt=\"6\" width=\"700\" height=\"190\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/6.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/6-480x130.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\nEl perfil de elevaci\u00f3n de la imagen superior corresponde al tramo de la ruta que va desde el Paseo del Rey hasta el cruce de la calle de Alberto Aguilera con la calle de Vallehermoso. No hemos podido obtener el perfil de elevaci\u00f3n del resto. Estos han sido los resultados:<\/p>\n<ul>\n<li>Toyota Prius: 4,7 l\/100 km<\/li>\n<li>Hyundai IONIQ: 5,5 l\/100 km (+14,5 %)<\/li>\n<li>KIA Niro: 6,2 l\/100 km (+32,2 %)<\/li>\n<\/ul>\n<p>Los datos de consumo que se muestran son acumulados con el recorrido 3, es decir, no pusimos a cero los medidores de consumo cuando terminamos el recorrido 3, sino que los dejamos contando. El IONIQ ha conseguido reducir la diferencia de consumo con el Prius, pero en el caso del Niro ha aumentado.<br \/>\n<strong>Recorrido 5<\/strong><br \/>\nEste recorrido de aproximadamente 36 kil\u00f3metros parte de donde termina el recorrido 4 \u2014la Gasolinera en el cruce de la calle de Bravo Murillo y la calle de R\u00edos Rosas\u2014 y concluye en las instalaciones de Iluni\u00f3n, en Brunete (donde hacemos las pruebas de esquiva y de eslalon, <a href=\"https:\/\/www.youtube.com\/playlist?list=PLrt8jdAATECUSFXiGsyO5pW_Nqqgnh3rH\" target=\"_blank\" rel=\"noopener\">v\u00eddeos<\/a>). Comprende, a grandes rasgos, 4 km de ciudad (Madrid y Brunete), 22 km de v\u00edas con m\u00e1s de dos carriles por sentido (A6, M-40, M-50 y M-503) y 10 km por una carretera con\u00a0un carril por sentido (M-501). El tr\u00e1fico era fluido, circulamos con el climatizador desconectado y a la velocidad m\u00e1xima permitida en cada v\u00eda.<br \/>\n<img decoding=\"async\" class=\"size-full wp-image-30455 aligncenter\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/repsol-tepesa-maps.jpg\" alt=\"repsol-tepesa-maps\" width=\"700\" height=\"450\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/repsol-tepesa-maps.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/repsol-tepesa-maps-480x309.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\n<img decoding=\"async\" class=\"size-full wp-image-30456 aligncenter\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/repsol-tepesa.jpg\" alt=\"repsol-tepesa\" width=\"700\" height=\"190\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/repsol-tepesa.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/repsol-tepesa-480x130.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><br \/>\nEl consumo del Hyundai IONIQ es un 11,4% superior al del Prius, que es, como en todos los casos, el modelo m\u00e1s eficiente. Este ha sido el recorrido en el que la diferencia de consumo entre el KIA Niro y el Toyota Prius ha sido menor ya que el consumo del Niro ha sido un 20,5% superior al del Prius.<\/p>\n<ul>\n<li>Toyota Prius: 4,4 l\/100 km<\/li>\n<li>Hyundai IONIQ: 4,9 l\/100 km (+11,4 %)<\/li>\n<li>KIA Niro: 5,3 l\/100 km (+20,5 %)<\/li>\n<\/ul>\n<p><strong>Conclusi\u00f3n<\/strong><br \/>\nEl Toyota Prius ha sido, indiscutiblemente, el modelo m\u00e1s eficiente de esta comparativa, mientras que el KIA Niro ha sido el que m\u00e1s carburante ha consumido. El Hyundai IONIQ\u00a0ha quedado en un punto intermedio, aunque m\u00e1s pr\u00f3ximo al Prius que al Niro. Es posible que las diferencias de consumo hubieran sido menores si tanto el IONIQ\u00a0como el Niro hubieran llevado los neum\u00e1ticos que vienen de serie en los niveles de equipamiento m\u00e1s bajos, pero no creemos que el resultado general hubiera cambiado. Entre el IONIQ y el Niro\u00a0la diferencia de consumo es mayor en carretera que en ciudad; el peor coeficiente aerodin\u00e1mico del Niro puede ser la causa.<br \/>\nLa sensaci\u00f3n compartida de las personas que hemos hecho esta prueba es que el Prius es\u00a0m\u00e1s tendente a circular en modo completamente el\u00e9ctrico que el IONIQ y, sobre todo, que el Niro. Este puede ser el motivo por el que la diferencia de consumo entre el Prius y el IONIQ\u00a0ha sido mayor en los recorridos en los que hab\u00eda m\u00e1s tramo de ciudad que en los que inclu\u00edan una mayor\u00eda de autov\u00eda y v\u00edas r\u00e1pidas.<br \/>\n<img decoding=\"async\" class=\"size-full wp-image-30488 aligncenter\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/blog_2.jpg\" alt=\"blog_2\" width=\"700\" height=\"394\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/blog_2.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/blog_2-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hemos hecho cinco recorridos diferentes\u00a0conduciendo simult\u00e1neamente un Hyundai IONIQ, un KIA Niro y un Toyota Prius\u00a0(pinchando en los enlaces se accede a la prueba que hay publicada en km77.com de cada modelo). Hemos constatado diferencias significativas de consumo de carburante entre ellos. El Prius fue siempre el modelo m\u00e1s eficiente, seguido del IONIQ y en [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":30484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3912],"tags":[7879,7811,7805,7493,7494,7864,7495,7496,7497,7498,7826],"class_list":["post-30407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-engendro-mecanico","tag-ecologia","tag-hibridos","tag-hyundai","tag-hyundai-ioniq-vs-kia-niro-vs-toyota-prius","tag-ioniq-vs-prius","tag-kia-marcas","tag-prueba-de-consumo","tag-prueba-de-consumo-hyundai-ioniq","tag-prueba-de-consumo-kia-niro","tag-prueba-de-consumo-toyota-prius","tag-toyota-marcas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pruebas de consumo: Hyundai IONIQ vs KIA Niro vs Toyota Prius - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pruebas de consumo: Hyundai IONIQ vs KIA Niro vs Toyota Prius - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Hemos hecho cinco recorridos diferentes\u00a0conduciendo simult\u00e1neamente un Hyundai IONIQ, un KIA Niro y un Toyota Prius\u00a0(pinchando en los enlaces se accede a la prueba que hay publicada en km77.com de cada modelo). Hemos constatado diferencias significativas de consumo de carburante entre ellos. El Prius fue siempre el modelo m\u00e1s eficiente, seguido del IONIQ y en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-14T12:15:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T17:51:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/foto-blog-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo David Gonz\u00e1lez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo David Gonz\u00e1lez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/\"},\"author\":{\"name\":\"Pablo David Gonz\u00e1lez\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/7038753b2eaac54d06d774b52178b416\"},\"headline\":\"Pruebas de consumo: Hyundai IONIQ vs KIA Niro vs Toyota Prius\",\"datePublished\":\"2016-11-14T12:15:40+00:00\",\"dateModified\":\"2021-03-31T17:51:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/\"},\"wordCount\":1529,\"commentCount\":148,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/foto-blog-1.jpg\",\"keywords\":[\"Ecolog\u00eda\",\"H\u00edbridos\",\"Hyundai\",\"Hyundai IONIQ vs KIA Niro vs Toyota Prius\",\"ioniq vs prius\",\"KIA\",\"prueba de consumo\",\"prueba de consumo hyundai ioniq\",\"prueba de consumo kia niro\",\"prueba de consumo toyota prius\",\"Toyota\"],\"articleSection\":[\"Engendro Mec\u00e1nico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/\",\"name\":\"Pruebas de consumo: Hyundai IONIQ vs KIA Niro vs Toyota Prius - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/foto-blog-1.jpg\",\"datePublished\":\"2016-11-14T12:15:40+00:00\",\"dateModified\":\"2021-03-31T17:51:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/foto-blog-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/foto-blog-1.jpg\",\"width\":700,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engendro Mec\u00e1nico\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pruebas de consumo: Hyundai IONIQ vs KIA Niro vs Toyota Prius\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Noticias y opiniones en km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/7038753b2eaac54d06d774b52178b416\",\"name\":\"Pablo David Gonz\u00e1lez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/20201213_172342-120x120.jpg\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/20201213_172342-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/20201213_172342-120x120.jpg\",\"caption\":\"Pablo David Gonz\u00e1lez\"},\"description\":\"Llegu\u00e9 en 2012 y aqu\u00ed sigo, disfrutando como un enano. Coches r\u00e1pidos por favor.\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/pablo-gonzalez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pruebas de consumo: Hyundai IONIQ vs KIA Niro vs Toyota Prius - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/","og_locale":"es_ES","og_type":"article","og_title":"Pruebas de consumo: Hyundai IONIQ vs KIA Niro vs Toyota Prius - Revista km77","og_description":"Hemos hecho cinco recorridos diferentes\u00a0conduciendo simult\u00e1neamente un Hyundai IONIQ, un KIA Niro y un Toyota Prius\u00a0(pinchando en los enlaces se accede a la prueba que hay publicada en km77.com de cada modelo). Hemos constatado diferencias significativas de consumo de carburante entre ellos. El Prius fue siempre el modelo m\u00e1s eficiente, seguido del IONIQ y en [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/","og_site_name":"Revista km77","article_published_time":"2016-11-14T12:15:40+00:00","article_modified_time":"2021-03-31T17:51:36+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/foto-blog-1.jpg","type":"image\/jpeg"}],"author":"Pablo David Gonz\u00e1lez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pablo David Gonz\u00e1lez","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/"},"author":{"name":"Pablo David Gonz\u00e1lez","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/7038753b2eaac54d06d774b52178b416"},"headline":"Pruebas de consumo: Hyundai IONIQ vs KIA Niro vs Toyota Prius","datePublished":"2016-11-14T12:15:40+00:00","dateModified":"2021-03-31T17:51:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/"},"wordCount":1529,"commentCount":148,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/foto-blog-1.jpg","keywords":["Ecolog\u00eda","H\u00edbridos","Hyundai","Hyundai IONIQ vs KIA Niro vs Toyota Prius","ioniq vs prius","KIA","prueba de consumo","prueba de consumo hyundai ioniq","prueba de consumo kia niro","prueba de consumo toyota prius","Toyota"],"articleSection":["Engendro Mec\u00e1nico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/","url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/","name":"Pruebas de consumo: Hyundai IONIQ vs KIA Niro vs Toyota Prius - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/foto-blog-1.jpg","datePublished":"2016-11-14T12:15:40+00:00","dateModified":"2021-03-31T17:51:36+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/foto-blog-1.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/foto-blog-1.jpg","width":700,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/pruebas-de-consumo-hyundai-ioniq-vs-kia-niro-vs-toyota-prius\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Engendro Mec\u00e1nico","item":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/"},{"@type":"ListItem","position":3,"name":"Pruebas de consumo: Hyundai IONIQ vs KIA Niro vs Toyota Prius"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Noticias y opiniones en km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/7038753b2eaac54d06d774b52178b416","name":"Pablo David Gonz\u00e1lez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/05\/20201213_172342-120x120.jpg","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/05\/20201213_172342-120x120.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/05\/20201213_172342-120x120.jpg","caption":"Pablo David Gonz\u00e1lez"},"description":"Llegu\u00e9 en 2012 y aqu\u00ed sigo, disfrutando como un enano. Coches r\u00e1pidos por favor.","url":"https:\/\/www.km77.com\/revista\/author\/pablo-gonzalez\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/30407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=30407"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/30407\/revisions"}],"predecessor-version":[{"id":41362,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/30407\/revisions\/41362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/30484"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=30407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=30407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=30407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}