{"id":27355,"date":"2009-04-01T18:41:26","date_gmt":"2009-04-01T16:41:26","guid":{"rendered":"http:\/\/blogs.km77.com\/engendromecanico\/?p=2538"},"modified":"2021-03-31T20:15:24","modified_gmt":"2021-03-31T18:15:24","slug":"las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/","title":{"rendered":"Las ventas de autom\u00f3viles nuevos caen un 38,7 % en marzo de 2009"},"content":{"rendered":"<p>Nuevo batacazo de las ventas de autom\u00f3viles nuevos. Siguendo con la tendencia bajista de 2008 (<a href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/\/1564\/las-ventas-de-automoviles-nuevos-caen-un-28-en-2008-y-un-50-en-diciembre\/\" target=\"_blank\" rel=\"noopener\">ventas de 2008<\/a>) y de febrero de 2009 (<a href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/\/2347\/las-ventas-de-automoviles-nuevos-caen-un-488-en-febrero-de-2009\/\" target=\"_blank\" rel=\"noopener\">m\u00e1s informaci\u00f3n<\/a>), las matriculaciones de autom\u00f3viles nuevos siguen sufriendo un <strong>duro ajuste en marzo de 2009<\/strong>.<br \/>\nSeg\u00fan datos de ANFAC y ANIACAM, en el mes de marzo, las ventas totales de turismos y todoterrenos <strong>bajaron un 38,7 %<\/strong> respecto a marzo de 2008. En marzo de 2009, se han matriculado un total de 73.503 veh\u00edculos (turismos y todoterrenos).<br \/>\nEn marzo de 2008, las ventas ya sufrieron un duro varapalo. <strong>Respecto a marzo de 2007<\/strong> (173.716 unidades), <strong>se han matriculado un 58 % menos de unidades en marzo de 2009<\/strong>.<br \/>\nPara incentivar la compra de veh\u00edculos (nuevos y usados con menos de cinco a\u00f1os) y la retirada de los coches m\u00e1s viejos, el Gobierno ha lanzado una serie de ayudas (<a href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/\/1151\/nuevo-plan-vive-ahora-valido-para-coches-usados-y-comerciales-%c2%bfque-opinas\/\" target=\"_blank\" rel=\"noopener\">Plan VIVE<\/a>).<br \/>\nActualmente ANFAC, GANVAM y los fabricantes, est\u00e1n pidiendo la supresi\u00f3n del Impuesto de Matriculaci\u00f3n, para as\u00ed levantar las ventas (<a href=\"http:\/\/www.europapress.es\/economia\/macroeconomia-00338\/noticia-economia-motor-ganvam-pide-suprimir-impuesto-matriculacion-incentivar-ventas-coches-20090102133848.html\" target=\"_blank\" rel=\"noopener\">m\u00e1s informaci\u00f3n<\/a>) o ayudas directas en la compra de un coche nuevo.<br \/>\nEn la secci\u00f3n <a href=\"https:\/\/www.km77.com\/mercado\/espana\/2008\/pespana.asp\" target=\"_blank\" rel=\"noopener\">Mercado de km77.com<\/a> pueden observarse las ventas de Espa\u00f1a y Europa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevo batacazo de las ventas de autom\u00f3viles nuevos. Siguendo con la tendencia bajista de 2008 (ventas de 2008) y de febrero de 2009 (m\u00e1s informaci\u00f3n), las matriculaciones de autom\u00f3viles nuevos siguen sufriendo un duro ajuste en marzo de 2009. Seg\u00fan datos de ANFAC y ANIACAM, en el mes de marzo, las ventas totales de turismos [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3912],"tags":[340,4139,1748,7801,4141],"class_list":["post-27355","post","type-post","status-publish","format-standard","hentry","category-engendro-mecanico","tag-anfac","tag-aniacam","tag-km77","tag-noticias","tag-ventas-coches-nuevos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las ventas de autom\u00f3viles nuevos caen un 38,7 % en marzo de 2009 - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las ventas de autom\u00f3viles nuevos caen un 38,7 % en marzo de 2009 - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Nuevo batacazo de las ventas de autom\u00f3viles nuevos. Siguendo con la tendencia bajista de 2008 (ventas de 2008) y de febrero de 2009 (m\u00e1s informaci\u00f3n), las matriculaciones de autom\u00f3viles nuevos siguen sufriendo un duro ajuste en marzo de 2009. Seg\u00fan datos de ANFAC y ANIACAM, en el mes de marzo, las ventas totales de turismos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-01T16:41:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T18:15:24+00:00\" \/>\n<meta name=\"author\" content=\"Jose B.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose B.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\\\/\"},\"author\":{\"name\":\"Jose B.\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/12053b16b430aa76be628b78b0db40f1\"},\"headline\":\"Las ventas de autom\u00f3viles nuevos caen un 38,7 % en marzo de 2009\",\"datePublished\":\"2009-04-01T16:41:26+00:00\",\"dateModified\":\"2021-03-31T18:15:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\\\/\"},\"wordCount\":202,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"keywords\":[\"Anfac\",\"ANIACAM\",\"KM77\",\"Noticias\",\"Ventas coches nuevos\"],\"articleSection\":[\"Engendro Mec\u00e1nico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\\\/\",\"name\":\"Las ventas de autom\u00f3viles nuevos caen un 38,7 % en marzo de 2009 - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"datePublished\":\"2009-04-01T16:41:26+00:00\",\"dateModified\":\"2021-03-31T18:15:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engendro Mec\u00e1nico\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Las ventas de autom\u00f3viles nuevos caen un 38,7 % en marzo de 2009\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Revista de km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/12053b16b430aa76be628b78b0db40f1\",\"name\":\"Jose B.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g\",\"caption\":\"Jose B.\"},\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/joseb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las ventas de autom\u00f3viles nuevos caen un 38,7 % en marzo de 2009 - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/","og_locale":"es_ES","og_type":"article","og_title":"Las ventas de autom\u00f3viles nuevos caen un 38,7 % en marzo de 2009 - Revista km77","og_description":"Nuevo batacazo de las ventas de autom\u00f3viles nuevos. Siguendo con la tendencia bajista de 2008 (ventas de 2008) y de febrero de 2009 (m\u00e1s informaci\u00f3n), las matriculaciones de autom\u00f3viles nuevos siguen sufriendo un duro ajuste en marzo de 2009. Seg\u00fan datos de ANFAC y ANIACAM, en el mes de marzo, las ventas totales de turismos [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/","og_site_name":"Revista km77","article_published_time":"2009-04-01T16:41:26+00:00","article_modified_time":"2021-03-31T18:15:24+00:00","author":"Jose B.","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jose B.","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/"},"author":{"name":"Jose B.","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/12053b16b430aa76be628b78b0db40f1"},"headline":"Las ventas de autom\u00f3viles nuevos caen un 38,7 % en marzo de 2009","datePublished":"2009-04-01T16:41:26+00:00","dateModified":"2021-03-31T18:15:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/"},"wordCount":202,"commentCount":2,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"keywords":["Anfac","ANIACAM","KM77","Noticias","Ventas coches nuevos"],"articleSection":["Engendro Mec\u00e1nico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/","url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/","name":"Las ventas de autom\u00f3viles nuevos caen un 38,7 % en marzo de 2009 - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"datePublished":"2009-04-01T16:41:26+00:00","dateModified":"2021-03-31T18:15:24+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/las-ventas-de-automoviles-nuevos-caen-un-387-en-marzo-de-2009\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Engendro Mec\u00e1nico","item":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/"},{"@type":"ListItem","position":3,"name":"Las ventas de autom\u00f3viles nuevos caen un 38,7 % en marzo de 2009"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Revista de km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/12053b16b430aa76be628b78b0db40f1","name":"Jose B.","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3cde1528de7c06feb63aa2ab147d6e1b077afba542246bdaf5d855893aa72732?s=96&d=mm&r=g","caption":"Jose B."},"url":"https:\/\/www.km77.com\/revista\/author\/joseb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/27355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=27355"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/27355\/revisions"}],"predecessor-version":[{"id":45441,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/27355\/revisions\/45441"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=27355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=27355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=27355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}