{"id":26546,"date":"2015-10-10T14:06:31","date_gmt":"2015-10-10T12:06:31","guid":{"rendered":"http:\/\/blogs.km77.com\/engendromecanico\/?p=26546"},"modified":"2021-03-31T19:54:07","modified_gmt":"2021-03-31T17:54:07","slug":"mclaren-650s-spider-can-am-50-unidades-conmemorativas","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/","title":{"rendered":"McLaren 650S Spider Can-Am, 50 unidades conmemorativas"},"content":{"rendered":"<p>La historia de McLaren no est\u00e1 unida \u00fanicamente a su trayectoria en F\u00f3rmula 1. Durante la d\u00e9cada de los 60 y 70 se labr\u00f3 una gran reputaci\u00f3n al otro lado del Atl\u00e1ntico en la exigente competici\u00f3n Can-Am \u2014\u00abCanadian-American Challenge Cup\u00bb\u2014 al lograr cinco campeonatos consecutivos entre el a\u00f1o 1967 y 1971. Ahora se cumplen 50 a\u00f1os del nacimiento de esa m\u00edtica competici\u00f3n y McLaren lo celebra con 50 unidades exclusivas a nivel mundial.<br \/>\n<img decoding=\"async\" class=\"aligncenter wp-image-26551\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2015\/10\/5764650S-Can-Am_01-1024x683.jpg\" alt=\"McLaren 650S Spyder Cam-Am km77-1\" width=\"614\" height=\"409\" \/><br \/>\n<!--more--><br \/>\nEstas unidades desarrolladas por MSO \u2014\u00abMcLaren Special Operations\u00bb\u2014 tienen un precio de 255 850 \u00a3 \u2014al cambio actual: 345 160 \u20ac\u2014 y se empezar\u00e1n a entregar en primavera del 2016. Su dise\u00f1o est\u00e1 basado en los veh\u00edculos de McLaren que disputaron la Can-Am, una competici\u00f3n sin barreras en cuanto a potencia y velocidad que recorr\u00eda los mejores circuitos de Am\u00e9rica del Norte y Canad\u00e1, y que atrajo a los mejores pilotos de la \u00e9poca como Graham Hill, John Surtees, Jackie Stewart y como no, a Bruce McLaren, quien en 1967 fund\u00f3 la \u00abBruce McLaren Motor Racing\u00bb.<br \/>\n<img decoding=\"async\" class=\"aligncenter wp-image-26553\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2015\/10\/5766650S-Can-Am_03-1024x683.jpg\" alt=\"McLaren 650S Spyder Cam-Am km77-2\" width=\"614\" height=\"409\" \/><br \/>\nEstas 50 unidades desarrolladas a partir del <a href=\"https:\/\/www.km77.com\/01\/mclaren\/650s\/2014\/informacion-deportivo-precio-308515-p.html\" target=\"_blank\" rel=\"noopener\">650S Spider<\/a> se pueden elegir en tres tonalidades diferentes. Una de ellas es el rojo denominado \u00abMars Red\u00bb y que est\u00e1 directamente inspirado en el M1B en el que corri\u00f3 Bruce McLaren y su compa\u00f1ero Chris Amon \u2014el que puedes ver en las fotograf\u00edas\u2014, otro un tono anaranjado denominado \u00abPapaya Spark\u00bb que seg\u00fan McLaren es la interpretaci\u00f3n moderna del naranja utilizado en la Can-Am y el tercero un tono negro \u00abOnyx Black\u00bb similar al utilizado por algunos modelos de competici\u00f3n de la marca de Woking.<br \/>\nAdem\u00e1s de por los colores espec\u00edficos de la carrocer\u00eda, el 650S Spider Can-Am se diferencia por tener el techo plegable de dos piezas fabricado en fibra de carbono. Mismo material con el que se han construido elementos como el cap\u00f3 delantero, la estructura de las puertas, el a\u00f1adido inferior del paragolpes delantero, la parte central del paragolpes posterior, los faldones laterales (con logotipo \u00abCan-Am\u00bb) y el aler\u00f3n trasero (denominado por McLaren como \u00abMcLaren Airbrake\u00bb) \u2014este se eleva autom\u00e1ticamente por encima de su posici\u00f3n de reposo para incrementar la resistencia aerodin\u00e1mica y ayudar en las frenadas\u2014.<br \/>\n<img decoding=\"async\" class=\"aligncenter wp-image-26552\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2015\/10\/5767650S-Can-Am_04-1024x683.jpg\" alt=\"5767650S-Can-Am_04\" width=\"614\" height=\"409\" \/><br \/>\nOtras caracter\u00edsticas inspiradas en los veh\u00edculos de la Can-Am son las cuatro salidas de escape fabricadas en acero inoxidable pulido \u2014McLaren las denomina \u00abtipo trompetas\u00bb\u2014, las aletas delanteras con entradas de aire o las llantas de aleaci\u00f3n forjadas de cinco radios en acabado negro brillante con el borde en acabado diamante. Los neum\u00e1ticos son unos Pirelli P Zero Corsa y los frenos son de material carbocer\u00e1mico y tienen pinzas pintadas en negro brillo y con el logo de McLaren.<br \/>\n<span class=\"bws_code\">[print_gllr id=26554]<\/span><br \/>\nEn el interior tambi\u00e9n hay detalles exclusivos como la placa conmemorativa\/identificativa de esta serie especial situada en la puerta del conductor o la tapicer\u00eda de cuero \u2014a juego con el exterior\u2014 en los asientos deportivos fabricados en fibra de carbono.<br \/>\n<span class=\"bws_code\">[print_gllr id=26558]<\/span><br \/>\nDonde no hay cambios es en el motor. Las 50 unidades utilizan el mismo motor de gasolina de ocho cilindros en V, 3,8 litros de cilindrada y sobrealimentaci\u00f3n mediante dos turbocompresores que el 650S y 650S Spider. La potencia es de 650 CV a 7250 rpm y el par motor m\u00e1ximo 678 Nm a 6000 rpm, suficiente para acelerar desde parado hasta 100 kil\u00f3metros por hora en 3,0 segundos y alcanzar una velocidad m\u00e1xima de 330 km\/h (<a href=\"https:\/\/www.km77.com\/precios\/mclaren\/650s\/2014\/650s-spider\" target=\"_blank\" rel=\"noopener\">ficha t\u00e9cnica McLaren 650S Spider<\/a>).<br \/>\n<img decoding=\"async\" class=\"aligncenter wp-image-26562\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2015\/10\/5776650S-Can-Am_13-1024x683.jpg\" alt=\"5776650S-Can-Am_13\" width=\"614\" height=\"409\" \/><br \/>\nA continuaci\u00f3n os dejamos el v\u00eddeo promocional en el que aparece el m\u00edtico M1B con el nuevo 650S Spider Can-Am:<br \/>\n<iframe width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/z2h0jdjMEoU?start=5&#038;feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La historia de McLaren no est\u00e1 unida \u00fanicamente a su trayectoria en F\u00f3rmula 1. Durante la d\u00e9cada de los 60 y 70 se labr\u00f3 una gran reputaci\u00f3n al otro lado del Atl\u00e1ntico en la exigente competici\u00f3n Can-Am \u2014\u00abCanadian-American Challenge Cup\u00bb\u2014 al lograr cinco campeonatos consecutivos entre el a\u00f1o 1967 y 1971. Ahora se cumplen 50 [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":26551,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3912],"tags":[6631,7267,7268,3965,22,1993,7834,7801,7798,7808,7799],"class_list":["post-26546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-engendro-mecanico","tag-650s","tag-650s-spider","tag-650s-spider-can-am","tag-edicion-limitada","tag-general","tag-mclaren","tag-noticias","tag-novedades","tag-nuevos-lanzamientos","tag-videos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>McLaren 650S Spider Can-Am, 50 unidades conmemorativas - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"McLaren 650S Spider Can-Am, 50 unidades conmemorativas - Revista km77\" \/>\n<meta property=\"og:description\" content=\"La historia de McLaren no est\u00e1 unida \u00fanicamente a su trayectoria en F\u00f3rmula 1. Durante la d\u00e9cada de los 60 y 70 se labr\u00f3 una gran reputaci\u00f3n al otro lado del Atl\u00e1ntico en la exigente competici\u00f3n Can-Am \u2014\u00abCanadian-American Challenge Cup\u00bb\u2014 al lograr cinco campeonatos consecutivos entre el a\u00f1o 1967 y 1971. Ahora se cumplen 50 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-10T12:06:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T17:54:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2015\/10\/5764650S-Can-Am_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Loren Serrano (@EnzoNurburg)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Loren Serrano (@EnzoNurburg)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/\"},\"author\":{\"name\":\"Loren Serrano (@EnzoNurburg)\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/d3c1bc483e384e2b2360fa1851eefbc5\"},\"headline\":\"McLaren 650S Spider Can-Am, 50 unidades conmemorativas\",\"datePublished\":\"2015-10-10T12:06:31+00:00\",\"dateModified\":\"2021-03-31T17:54:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/\"},\"wordCount\":622,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/5764650S-Can-Am_01.jpg\",\"keywords\":[\"650S\",\"650S Spider\",\"650S Spider Can-Am\",\"edici\u00f3n limitada\",\"General\",\"McLaren\",\"McLaren\",\"Noticias\",\"Novedades\",\"Nuevos lanzamientos\",\"V\u00eddeos\"],\"articleSection\":[\"Engendro Mec\u00e1nico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/\",\"name\":\"McLaren 650S Spider Can-Am, 50 unidades conmemorativas - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/5764650S-Can-Am_01.jpg\",\"datePublished\":\"2015-10-10T12:06:31+00:00\",\"dateModified\":\"2021-03-31T17:54:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/5764650S-Can-Am_01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/5764650S-Can-Am_01.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engendro Mec\u00e1nico\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"McLaren 650S Spider Can-Am, 50 unidades conmemorativas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Noticias y opiniones en km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/d3c1bc483e384e2b2360fa1851eefbc5\",\"name\":\"Loren Serrano (@EnzoNurburg)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g\",\"caption\":\"Loren Serrano (@EnzoNurburg)\"},\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/lorenzoserrano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"McLaren 650S Spider Can-Am, 50 unidades conmemorativas - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/","og_locale":"es_ES","og_type":"article","og_title":"McLaren 650S Spider Can-Am, 50 unidades conmemorativas - Revista km77","og_description":"La historia de McLaren no est\u00e1 unida \u00fanicamente a su trayectoria en F\u00f3rmula 1. Durante la d\u00e9cada de los 60 y 70 se labr\u00f3 una gran reputaci\u00f3n al otro lado del Atl\u00e1ntico en la exigente competici\u00f3n Can-Am \u2014\u00abCanadian-American Challenge Cup\u00bb\u2014 al lograr cinco campeonatos consecutivos entre el a\u00f1o 1967 y 1971. Ahora se cumplen 50 [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/","og_site_name":"Revista km77","article_published_time":"2015-10-10T12:06:31+00:00","article_modified_time":"2021-03-31T17:54:07+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2015\/10\/5764650S-Can-Am_01.jpg","type":"image\/jpeg"}],"author":"Loren Serrano (@EnzoNurburg)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Loren Serrano (@EnzoNurburg)","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/"},"author":{"name":"Loren Serrano (@EnzoNurburg)","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/d3c1bc483e384e2b2360fa1851eefbc5"},"headline":"McLaren 650S Spider Can-Am, 50 unidades conmemorativas","datePublished":"2015-10-10T12:06:31+00:00","dateModified":"2021-03-31T17:54:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/"},"wordCount":622,"commentCount":0,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2015\/10\/5764650S-Can-Am_01.jpg","keywords":["650S","650S Spider","650S Spider Can-Am","edici\u00f3n limitada","General","McLaren","McLaren","Noticias","Novedades","Nuevos lanzamientos","V\u00eddeos"],"articleSection":["Engendro Mec\u00e1nico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/","url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/","name":"McLaren 650S Spider Can-Am, 50 unidades conmemorativas - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2015\/10\/5764650S-Can-Am_01.jpg","datePublished":"2015-10-10T12:06:31+00:00","dateModified":"2021-03-31T17:54:07+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2015\/10\/5764650S-Can-Am_01.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2015\/10\/5764650S-Can-Am_01.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/mclaren-650s-spider-can-am-50-unidades-conmemorativas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Engendro Mec\u00e1nico","item":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/"},{"@type":"ListItem","position":3,"name":"McLaren 650S Spider Can-Am, 50 unidades conmemorativas"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Noticias y opiniones en km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/d3c1bc483e384e2b2360fa1851eefbc5","name":"Loren Serrano (@EnzoNurburg)","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g","caption":"Loren Serrano (@EnzoNurburg)"},"url":"https:\/\/www.km77.com\/revista\/author\/lorenzoserrano\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/26546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=26546"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/26546\/revisions"}],"predecessor-version":[{"id":41695,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/26546\/revisions\/41695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/26551"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=26546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=26546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=26546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}