{"id":18439,"date":"2020-08-26T12:32:57","date_gmt":"2020-08-26T10:32:57","guid":{"rendered":"https:\/\/blogs.km77.com\/teletransporte\/?p=18439"},"modified":"2021-03-31T19:46:30","modified_gmt":"2021-03-31T17:46:30","slug":"adivinar-un-coche-para-el-futuro-mi-apuesta","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/","title":{"rendered":"Adivinar un coche para el futuro. Mi apuesta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hace m\u00e1s o menos un mes, despu\u00e9s de conducir el Porsche Taycan, pregunt\u00e9 en este blog: <a href=\"https:\/\/www.km77.com\/revista\/teletransporte\/si-tu-fueras-porsche-que-electrico-harias\/\" title=\"\u00bfSi t\u00fa fueras Porsche, qu\u00e9 el\u00e9ctrico har\u00edas?\">\u00bfSi t\u00fa fueras Porsche, qu\u00e9 el\u00e9ctrico har\u00edas?<\/a> <br><br>Lo pregunt\u00e9 porque el Taycan me decepcion\u00f3. Puestos a hacer un coche escaparate, Porsche pod\u00eda elegir entre hacer un coche con prestaciones brutales (m\u00e1s de lo mismo, pero en el\u00e9ctrico) o presentar un coche tecnol\u00f3gicamente rompedor, o un concepto rompedor y diferente.<br><br>He escrito muchas veces que los coches de bater\u00edas grandes son un error de concepto. Porque las bater\u00edas son muy costosas  energ\u00e9ticamente de fabricar y porque durante su fabricaci\u00f3n se emite mucho CO2 y se consumen recursos naturales escasos que luego no se amortizan, porque, salvo los profesionales, nadie hace 300 kil\u00f3metros cada jornada.<br><br>A mi juicio, los coches deben tener bater\u00edas peque\u00f1as, que cubran las necesidades diarias. Y buscar otros sistemas de alimentaci\u00f3n o transporte, quiz\u00e1 menos eficientes, para las excepciones. Un sistema poco eficiente para las excepciones no perjudica, porque se trata de situaciones poco frecuentes, que pueden suponer alrededor de un 10% de los kil\u00f3metros recorridos con el coche. <br><br>A mi juicio, en el futuro, hay una alta probabilidad de que los coches tengan una bater\u00eda enchufable de tama\u00f1o moderado  y que el extensor de autonom\u00eda se realice mediante una pila de combustible alimentada por hidr\u00f3geno.<br><br>De esta forma, evitamos totalmente la emisi\u00f3n de CO2 a la atm\u00f3sfera durante la utilizaci\u00f3n, no fabricamos coches pesad\u00edsimos que arrastran cientos de kilogramos diariamente que no necesitan para nada, optimizamos la fabricaci\u00f3n y el uso de las bater\u00edas, el gasto de materias primas y construimos una econom\u00eda del hidr\u00f3geno que tiene mucho sentido para almacenar la energ\u00eda sobrante que se genera por fuentes limpias cuando no hay consumo y que por tanto normalmente se desaprovecha.<br><br>Un sistema h\u00edbrido de acumuladores peque\u00f1os e hidr\u00f3geno tiene el gran inconveniente, en la actualidad, de que utiliza dos tecnolog\u00edas no amortizadas y que por tanto encarecen mucho el coche. Y quiz\u00e1 haya otros muchos problemas que yo no consigo adivinar.<br><br>Por estos motivos, porque sin duda un coche h\u00edbrido de bater\u00edas enchufables y pila de combustible resultar\u00eda un coche muy caro, es por lo que considero que Porsche pod\u00eda haber elegido esta opci\u00f3n para su escaparate.<br><br>En definitiva. Puedo estar equivocado, pero tengo la sensaci\u00f3n de que la probabilidad de que el coche del futuro sea mixto de bater\u00edas enchufables e hidr\u00f3geno es muy alta. Unas bater\u00edas de tama\u00f1o y peso moderado, y m\u00e1s cuando mejore la teconolog\u00eda, pueden ser muy eficientes. El hidr\u00f3geno, termodin\u00e1micamente menos eficiente en todos los procesos de transformaci\u00f3n, tiene la ventaja de su mayor densidad energ\u00e9tica cuando se almacena a presiones elevadas, por lo que con poco peso se pueden conseguir elevadas autonom\u00edas.<br><br>El hidr\u00f3geno y las bater\u00edas enchufables se complementan a la perfecci\u00f3n y basta con un \u00fanico motor, a diferencia de los h\u00edbridos enchufables actuales, que requieren de dos motores.<br><br>En definitiva. Es muy posible que me pierda algo. Pero si tuviera que apostar mis dineros en una idea de futuro, creo que la combinaci\u00f3n de estas dos tecnolog\u00edas en un coche tendr\u00eda muchas probabilidades de conseguir mi capital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para el futuro, intuyo una alta probabilidad de que los coches tengan una bater\u00eda enchufable y un extensor de autonom\u00eda basado en la pila de hidr\u00f3geno.<\/p>\n","protected":false},"author":72,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3915],"tags":[3847,8156,8,8155,3846,8023,3848,8013],"class_list":["post-18439","post","type-post","status-publish","format-standard","hentry","category-teletransporte","tag-baterias-enchufables-y-pilas-de-hidrogeno","tag-cambio-climatico","tag-coches","tag-efecto-invernadero","tag-hibrido-electrico-electrico","tag-tecnica","tag-un-coche-racional-para-el-futuro","tag-vehiculo-electrico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adivinar un coche para el futuro. Mi apuesta - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adivinar un coche para el futuro. Mi apuesta - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Para el futuro, intuyo una alta probabilidad de que los coches tengan una bater\u00eda enchufable y un extensor de autonom\u00eda basado en la pila de hidr\u00f3geno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-26T10:32:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T17:46:30+00:00\" \/>\n<meta name=\"author\" content=\"Javier Molt\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deportes1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Molt\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/adivinar-un-coche-para-el-futuro-mi-apuesta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/adivinar-un-coche-para-el-futuro-mi-apuesta\\\/\"},\"author\":{\"name\":\"Javier Molt\u00f3\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/2f0611a1b3c7d2a2c81a9428505a25db\"},\"headline\":\"Adivinar un coche para el futuro. Mi apuesta\",\"datePublished\":\"2020-08-26T10:32:57+00:00\",\"dateModified\":\"2021-03-31T17:46:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/adivinar-un-coche-para-el-futuro-mi-apuesta\\\/\"},\"wordCount\":581,\"commentCount\":35,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"keywords\":[\"Bater\u00edas enchufables y pilas de hidr\u00f3geno\",\"Cambio clim\u00e1tico\",\"coches\",\"Efecto invernadero\",\"H\u00edbrido el\u00e9ctrico - el\u00e9ctrico\",\"tecnica\",\"Un coche racional para el futuro\",\"vehiculo electrico\"],\"articleSection\":[\"Teletransporte\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/adivinar-un-coche-para-el-futuro-mi-apuesta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/adivinar-un-coche-para-el-futuro-mi-apuesta\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/adivinar-un-coche-para-el-futuro-mi-apuesta\\\/\",\"name\":\"Adivinar un coche para el futuro. Mi apuesta - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"datePublished\":\"2020-08-26T10:32:57+00:00\",\"dateModified\":\"2021-03-31T17:46:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/adivinar-un-coche-para-el-futuro-mi-apuesta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/adivinar-un-coche-para-el-futuro-mi-apuesta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/adivinar-un-coche-para-el-futuro-mi-apuesta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teletransporte\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adivinar un coche para el futuro. Mi apuesta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Noticias y opiniones en km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/2f0611a1b3c7d2a2c81a9428505a25db\",\"name\":\"Javier Molt\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g\",\"caption\":\"Javier Molt\u00f3\"},\"description\":\"Empec\u00e9 a trabajar como periodista probador de coches en 1985, en la revista AutoHebdo. Despu\u00e9s trabaj\u00e9 en Coche Actual y Motor16. Desde 1994 a 1999 inform\u00e9 de asuntos econ\u00f3micos tanto en Madrid como en Londres, donde trabaj\u00e9 en Bloomberg. En 1999 fund\u00e9 km77.com, empresa con la que sigo empe\u00f1ado en el objetivo de dar la mejor informaci\u00f3n de coches de la que somos capaces.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/Deportes1\"],\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/teletransporte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adivinar un coche para el futuro. Mi apuesta - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/","og_locale":"es_ES","og_type":"article","og_title":"Adivinar un coche para el futuro. Mi apuesta - Revista km77","og_description":"Para el futuro, intuyo una alta probabilidad de que los coches tengan una bater\u00eda enchufable y un extensor de autonom\u00eda basado en la pila de hidr\u00f3geno.","og_url":"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/","og_site_name":"Revista km77","article_published_time":"2020-08-26T10:32:57+00:00","article_modified_time":"2021-03-31T17:46:30+00:00","author":"Javier Molt\u00f3","twitter_card":"summary_large_image","twitter_creator":"@Deportes1","twitter_misc":{"Escrito por":"Javier Molt\u00f3","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/"},"author":{"name":"Javier Molt\u00f3","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/2f0611a1b3c7d2a2c81a9428505a25db"},"headline":"Adivinar un coche para el futuro. Mi apuesta","datePublished":"2020-08-26T10:32:57+00:00","dateModified":"2021-03-31T17:46:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/"},"wordCount":581,"commentCount":35,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"keywords":["Bater\u00edas enchufables y pilas de hidr\u00f3geno","Cambio clim\u00e1tico","coches","Efecto invernadero","H\u00edbrido el\u00e9ctrico - el\u00e9ctrico","tecnica","Un coche racional para el futuro","vehiculo electrico"],"articleSection":["Teletransporte"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/","url":"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/","name":"Adivinar un coche para el futuro. Mi apuesta - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"datePublished":"2020-08-26T10:32:57+00:00","dateModified":"2021-03-31T17:46:30+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/teletransporte\/adivinar-un-coche-para-el-futuro-mi-apuesta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Teletransporte","item":"https:\/\/www.km77.com\/revista\/teletransporte\/"},{"@type":"ListItem","position":3,"name":"Adivinar un coche para el futuro. Mi apuesta"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Noticias y opiniones en km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/2f0611a1b3c7d2a2c81a9428505a25db","name":"Javier Molt\u00f3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g","caption":"Javier Molt\u00f3"},"description":"Empec\u00e9 a trabajar como periodista probador de coches en 1985, en la revista AutoHebdo. Despu\u00e9s trabaj\u00e9 en Coche Actual y Motor16. Desde 1994 a 1999 inform\u00e9 de asuntos econ\u00f3micos tanto en Madrid como en Londres, donde trabaj\u00e9 en Bloomberg. En 1999 fund\u00e9 km77.com, empresa con la que sigo empe\u00f1ado en el objetivo de dar la mejor informaci\u00f3n de coches de la que somos capaces.","sameAs":["https:\/\/x.com\/Deportes1"],"url":"https:\/\/www.km77.com\/revista\/author\/teletransporte\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/18439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=18439"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/18439\/revisions"}],"predecessor-version":[{"id":40746,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/18439\/revisions\/40746"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=18439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=18439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=18439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}