{"id":16364,"date":"2018-02-22T19:05:03","date_gmt":"2018-02-22T18:05:03","guid":{"rendered":"http:\/\/blogs.km77.com\/teletransporte\/?p=16364"},"modified":"2021-03-31T19:48:53","modified_gmt":"2021-03-31T17:48:53","slug":"nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/","title":{"rendered":"Nocturnos. El Mazda 3 5p 2.0 120 CV Zenith (2017) por curvas."},"content":{"rendered":"<p>He conducido el Mazda3, con carrocer\u00eda de 4 puertas (SportSedan) y con carrocer\u00eda de 5 puertas (Mazda3 5p)(<a href=\"https:\/\/www.km77.com\/comparador\/ve:car:mazda:mazda3:2017:5-puertas:zenith:3-5p-20-120-cv-zenith,ve:car:mazda:mazda3:2017:sportsedan:zenith:3-sportsedan-20-120-cv-zenith#\">Ficha t\u00e9cnica comparativa<\/a>). El motor que me interesaba era el de 120 CV, de 4 cilindros y dos litros de cilindrada, que compite por potencia con varios coches con motor de tres cilindros y potencia similar. <a href=\"http:\/\/www.arpem.com\/comparativas\/coches\/comparar-honda-civic-5p-10-turbo-vtec-elegance-2017-mazda-3-5p-20-120-cv-zenith-2017\">Aqu\u00ed en Arpem hemos publicado datos y un texto comparativo entre el Mazda 3 y el Honda Civic<\/a> con estos motores de potencias similares. Pronto hablar\u00e9 del Civic. Hoy me centro en la respuesta en carretera del Mazda3.<\/p>\n<p><!--more-->Este coche tiene un tacto en curva delicioso. No es tan eficaz como el Honda Civic. no entra tan bien ni con tanta rapidez ni de lejos, pero dibuja las curvas con unos apoyos perfectamente definidos, que permiten jugar al conductor con el acelerador en busca de los l\u00edmites de adherencia sin aparente riesgo. Sentir esos apoyos en el cuerpo y sentirse equilibrista dentro del coche, permite dosificar el acelerador con suavidad como acelerando o ralentizando el trapecio, para acercarse al l\u00edmite de adherencia delante o detr\u00e1s en un juego de movimientos suaves y arm\u00f3nicos. El paso por cuerva no tiene por qu\u00e9 ser especialmente r\u00e1pido, pero s\u00ed resulta gratificante.<\/p>\n<p>En este juego desentona el motor que, frente al magn\u00edfico tres cilindros del Civic, que tiene unos bajos llenos de potencia, requiere ser llevado alto de vueltas para lo que es necesario utilizar marchas muy cortas, porque el desarrollo del cambio es largo para obtener buenos consumos. Yo, si tuviera que elegir este coche, me decidir\u00eda por el cambio autom\u00e1tico, que funciona muy muy bien y facilita las tareas. La caja de cambios manual es precisa, pero es m\u00e1s bien lenta. El motor no empuja con contundencia a ning\u00fan r\u00e9gimen. En alta entrega bien la potencia, sin excesivo ruido, aunque no sea un coche particularmente silencioso cuando el motor sube de r\u00e9gimen.\u00a0Los frenos funcionan muy bien tanto por tacto como por aguante.<\/p>\n<p>Antes de mi recorrido, para que los faros est\u00e9n bien limpios, toca la foto con las luces de carretera. <a href=\"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-mazda-cx-3-luxury-2-0-120-cv-aut\/\">En este enlace se puede comparar con el haz del CX-3<\/a>, que ilumina claramente mejor los bordes de la carretera.<\/p>\n<blockquote><p><img decoding=\"async\" class=\"aligncenter size-full wp-image-16533\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/01-Mazda.jpg\" alt=\"01- Nocturnos Mazda 3\" width=\"700\" height=\"467\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/01-Mazda.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/01-Mazda-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><\/p><\/blockquote>\n<p>Tambi\u00e9n con luces de cruce.<\/p>\n<blockquote><p><img decoding=\"async\" class=\"aligncenter size-full wp-image-16534\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/02-Mazda.jpg\" alt=\"02- Nocturnos Mazda 3\" width=\"700\" height=\"467\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/02-Mazda.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/02-Mazda-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><\/p><\/blockquote>\n<p>El color naranja que aparecen en el piloto de la foto est\u00e1 causado por un defecto de la fotograf\u00eda. El ojo humano percibe un rojo intenso.<\/p>\n<blockquote><p><img decoding=\"async\" class=\"aligncenter size-full wp-image-16535\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/03-Mazda.jpg\" alt=\"03- Nocturnos Mazda 3\" width=\"700\" height=\"467\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/03-Mazda.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/03-Mazda-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><\/p><\/blockquote>\n<p>As\u00ed se ven desde fuera las luces de cruce y de carretera, si bien en la foto no se distingue la diferencia.<\/p>\n<blockquote><p><img decoding=\"async\" class=\"aligncenter size-full wp-image-16536\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/04-Mazda.jpg\" alt=\"04- Nocturnos Mazda 3\" width=\"700\" height=\"467\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/04-Mazda.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/04-Mazda-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><\/p><\/blockquote>\n<p>No me atrevo a decir cu\u00e1l es cu\u00e1l.<\/p>\n<blockquote><p><img decoding=\"async\" class=\"aligncenter size-full wp-image-16537\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/05-Mazda.jpg\" alt=\"05- Nocturnos Mazda 3\" width=\"700\" height=\"467\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/05-Mazda.jpg 700w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/05-Mazda-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" \/><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prueba del Mazda 3 5p 2.0 120 CV Zenith (2017) por carretera de curvas. Tacto delicioso. El motor tiene poca fuerza a bajas revoluciones.<\/p>\n","protected":false},"author":72,"featured_media":16533,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3915],"tags":[3496,8055,3497,3495],"class_list":["post-16364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-teletransporte","tag-luces-mazda3","tag-mazda","tag-mazda3","tag-prueba-mazda3-120-cv"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nocturnos. El Mazda 3 5p 2.0 120 CV Zenith (2017) por curvas. - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nocturnos. El Mazda 3 5p 2.0 120 CV Zenith (2017) por curvas. - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Prueba del Mazda 3 5p 2.0 120 CV Zenith (2017) por carretera de curvas. Tacto delicioso. El motor tiene poca fuerza a bajas revoluciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-22T18:05:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T17:48:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/01-Mazda.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Javier Molt\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deportes1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Molt\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/\"},\"author\":{\"name\":\"Javier Molt\u00f3\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/2f0611a1b3c7d2a2c81a9428505a25db\"},\"headline\":\"Nocturnos. El Mazda 3 5p 2.0 120 CV Zenith (2017) por curvas.\",\"datePublished\":\"2018-02-22T18:05:03+00:00\",\"dateModified\":\"2021-03-31T17:48:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/\"},\"wordCount\":451,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/01-Mazda.jpg\",\"keywords\":[\"luces Mazda3\",\"Mazda\",\"Mazda3\",\"Prueba Mazda3 120 CV\"],\"articleSection\":[\"Teletransporte\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/\",\"name\":\"Nocturnos. El Mazda 3 5p 2.0 120 CV Zenith (2017) por curvas. - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/01-Mazda.jpg\",\"datePublished\":\"2018-02-22T18:05:03+00:00\",\"dateModified\":\"2021-03-31T17:48:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/01-Mazda.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/01-Mazda.jpg\",\"width\":700,\"height\":467},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teletransporte\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/teletransporte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nocturnos. El Mazda 3 5p 2.0 120 CV Zenith (2017) por curvas.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Revista de km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/2f0611a1b3c7d2a2c81a9428505a25db\",\"name\":\"Javier Molt\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g\",\"caption\":\"Javier Molt\u00f3\"},\"description\":\"Empec\u00e9 a trabajar como periodista probador de coches en 1985, en la revista AutoHebdo. Despu\u00e9s trabaj\u00e9 en Coche Actual y Motor16. Desde 1994 a 1999 inform\u00e9 de asuntos econ\u00f3micos tanto en Madrid como en Londres, donde trabaj\u00e9 en Bloomberg. En 1999 fund\u00e9 km77.com, empresa con la que sigo empe\u00f1ado en el objetivo de dar la mejor informaci\u00f3n de coches de la que somos capaces.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/Deportes1\"],\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/teletransporte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nocturnos. El Mazda 3 5p 2.0 120 CV Zenith (2017) por curvas. - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/","og_locale":"es_ES","og_type":"article","og_title":"Nocturnos. El Mazda 3 5p 2.0 120 CV Zenith (2017) por curvas. - Revista km77","og_description":"Prueba del Mazda 3 5p 2.0 120 CV Zenith (2017) por carretera de curvas. Tacto delicioso. El motor tiene poca fuerza a bajas revoluciones.","og_url":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/","og_site_name":"Revista km77","article_published_time":"2018-02-22T18:05:03+00:00","article_modified_time":"2021-03-31T17:48:53+00:00","og_image":[{"width":700,"height":467,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/01-Mazda.jpg","type":"image\/jpeg"}],"author":"Javier Molt\u00f3","twitter_card":"summary_large_image","twitter_creator":"@Deportes1","twitter_misc":{"Escrito por":"Javier Molt\u00f3","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/"},"author":{"name":"Javier Molt\u00f3","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/2f0611a1b3c7d2a2c81a9428505a25db"},"headline":"Nocturnos. El Mazda 3 5p 2.0 120 CV Zenith (2017) por curvas.","datePublished":"2018-02-22T18:05:03+00:00","dateModified":"2021-03-31T17:48:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/"},"wordCount":451,"commentCount":7,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/01-Mazda.jpg","keywords":["luces Mazda3","Mazda","Mazda3","Prueba Mazda3 120 CV"],"articleSection":["Teletransporte"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/","url":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/","name":"Nocturnos. El Mazda 3 5p 2.0 120 CV Zenith (2017) por curvas. - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/01-Mazda.jpg","datePublished":"2018-02-22T18:05:03+00:00","dateModified":"2021-03-31T17:48:53+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/01-Mazda.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2018\/01\/01-Mazda.jpg","width":700,"height":467},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/teletransporte\/nocturnos-el-mazda-3-5p-2-0-120-cv-zenith-2017-por-curvas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Teletransporte","item":"https:\/\/www.km77.com\/revista\/teletransporte\/"},{"@type":"ListItem","position":3,"name":"Nocturnos. El Mazda 3 5p 2.0 120 CV Zenith (2017) por curvas."}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Revista de km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/2f0611a1b3c7d2a2c81a9428505a25db","name":"Javier Molt\u00f3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c930880a58b8b56f4abb8c2797bdb266488614621319ddd0ab4ee365b10a72c?s=96&d=mm&r=g","caption":"Javier Molt\u00f3"},"description":"Empec\u00e9 a trabajar como periodista probador de coches en 1985, en la revista AutoHebdo. Despu\u00e9s trabaj\u00e9 en Coche Actual y Motor16. Desde 1994 a 1999 inform\u00e9 de asuntos econ\u00f3micos tanto en Madrid como en Londres, donde trabaj\u00e9 en Bloomberg. En 1999 fund\u00e9 km77.com, empresa con la que sigo empe\u00f1ado en el objetivo de dar la mejor informaci\u00f3n de coches de la que somos capaces.","sameAs":["https:\/\/x.com\/Deportes1"],"url":"https:\/\/www.km77.com\/revista\/author\/teletransporte\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/16364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=16364"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/16364\/revisions"}],"predecessor-version":[{"id":41112,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/16364\/revisions\/41112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/16533"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=16364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=16364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=16364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}