{"id":15037,"date":"2016-11-26T08:30:20","date_gmt":"2016-11-26T07:30:20","guid":{"rendered":"http:\/\/blogs.km77.com\/arturoandres\/?p=15037"},"modified":"2021-03-31T19:51:34","modified_gmt":"2021-03-31T17:51:34","slug":"prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/","title":{"rendered":"Prueba de consumo (223): Mazda-3 Sed\u00e1n 1.5-D 105 CV"},"content":{"rendered":"<p>Por fin, al cabo de muchos meses, hemos conseguido realizar la prueba de este motor sobre un veh\u00edculo algo m\u00e1s representativo que un CX-3. Representativo a efectos comparativos, puesto que comercialmente, los SUV est\u00e1n en el candelero desde hace varios a\u00f1os. Pero en cuanto a consumos, tenemos much\u00edsimos m\u00e1s datos acumulados con carrocer\u00eda de turismo, ya sea de dos vol\u00famenes o sed\u00e1n. Y este retraso se debe a un curioso quiebro en la pol\u00edtica comercial de Mazda Espa\u00f1a, al que ya hicimos referencia en la prueba anterior de este motor, que fue la segunda que realizamos con el CX-3, para tener, al menos, su resultado al nuevo ritmo \u201cecon\u00f3mico\u201d m\u00e1s tranquilo que hemos adoptado m\u00e1s o menos desde inicios de 2015. para ahorrarme repeticiones, procedo a copiar unos p\u00e1rrafos de lo que se escribi\u00f3 a principios del pasado Agosto en este segunda prueba del CX con el motor 1.5D de 105 CV:<\/p>\n<p><!--more--><\/p>\n<p>\u201cEn una primera ocasi\u00f3n, dicho motor lo hab\u00edamos conducido durante la presentaci\u00f3n en Barcelona de la gama Mazda-2, hace bastante m\u00e1s tiempo, y nos hab\u00eda causado muy buena impresi\u00f3n, no ya s\u00f3lo por c\u00f3mo andaba para unos te\u00f3ricos 105 CV (parec\u00edan m\u00e1s), sino por los consumos que indicaba su ordenador. Y por ello, en repetidas ocasiones solicitamos su prueba en dicha carrocer\u00eda del segmento B, pero nos iban dando largas; probamos el motor 1.5-G, pero el 1.5-D no acababa de llegar.<\/p>\n<blockquote>\n<div id=\"attachment_15039\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15039\" class=\"size-full wp-image-15039\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sed\u00e1n_01.jpg\" alt=\"El puesto de conducci\u00f3n de los Mazda es, dentro de la complicaci\u00f3n de casi cualquier coche actual, de los m\u00e1s racionales y ergon\u00f3micos. Los mandos est\u00e1n bastante repartidos entre consolas, volante (botones muy peque\u00f1os, pero no tiene remedio) y puerta. Y el mando giratorio y pulsante situado tras de la palanca de cambios resulta bastante f\u00e1cil de comprender y manejar.\" width=\"700\" height=\"467\" \/><p id=\"caption-attachment-15039\" class=\"wp-caption-text\"><em>El puesto de conducci\u00f3n de los Mazda es, dentro de la complicaci\u00f3n de casi cualquier coche actual, de los m\u00e1s racionales y ergon\u00f3micos. Los mandos est\u00e1n bastante repartidos entre consolas, volante (botones muy peque\u00f1os, pero no tiene remedio) y puerta. Y el mando giratorio y pulsante situado tras de la palanca de cambios resulta bastante f\u00e1cil de comprender y manejar.<\/em><\/p><\/div><\/blockquote>\n<p>Y el que lleg\u00f3 fue el CX-3, y con dicha motorizaci\u00f3n desde el primer momento; y no s\u00f3lo para su comercializaci\u00f3n, sino tambi\u00e9n para el parque de coches de pruebas. Naturalmente lo probamos el oto\u00f1o pasado, como ya se ha dicho; pero de montado en el Mazda-2, ni noticia. Pero es que, a diferencia del CX-3, el Mazda-2 con motor 1.5-D se vend\u00eda ni se vende, como puede comprobarse en el listado de \u201cPrecios y datos\u201d de \u201ckm77\u201d. Y por fin nos confesaron la verdad: el Mazda-2 no se trae, ni se traer\u00e1 con este motor, debido al paulatino retorno hacia la gasolina en el mercado de turismos. En cuyo segmento B Mazda tiene el extraordinario 1.5-G de 90 CV con 5 marchas para los fan\u00e1ticos de la econom\u00eda; y con 115 CV, 6 marchas y muy buenas prestaciones, para quien requiera algo m\u00e1s brillante.<\/p>\n<p>Por el contrario, en los SUV el mercado sigue inclin\u00e1ndose hacia el TD, ya que los consumos son m\u00e1s elevados que en los turismos, y el manejo m\u00e1s f\u00e1cil que con motor de gasolina cuando la carga es elevada, condici\u00f3n m\u00e1s frecuente (aunque no para todos sus usuarios) en el caso de los SUVs. Y por ello, el CX-3 1.5-D se importa incluso en variantes en principio tan minoritarias como la AWD, e incluso con dicha transmisi\u00f3n integral y cambio autom\u00e1tico, que ya es rizar el rizo.\u201d<\/p>\n<blockquote>\n<div id=\"attachment_15040\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15040\" class=\"size-full wp-image-15040\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sed\u00e1n_02.jpg\" alt=\"La carrocer\u00eda Sed\u00e1n del Mazda-3 tiene un sabor casi cl\u00e1sico, especialmente en su zona frontal y tres cuartos delantera. La proporci\u00f3n entre anchura y altura (1,80 para 1,45 m) nos recuerda las berlinas de tipo medio\/grande de hace dos o tres d\u00e9cadas, antes de que empezase la escalada hacia alturas cada vez mayores.\" width=\"700\" height=\"373\" \/><p id=\"caption-attachment-15040\" class=\"wp-caption-text\"><em>La carrocer\u00eda Sed\u00e1n del Mazda-3 tiene un sabor casi cl\u00e1sico, especialmente en su zona frontal y tres cuartos delantera. La proporci\u00f3n entre anchura y altura (1,80 para 1,45 m) nos recuerda las berlinas de tipo medio\/grande de hace dos o tres d\u00e9cadas, antes de que empezase la escalada hacia alturas cada vez mayores.<\/em><\/p><\/div><\/blockquote>\n<p>Pero, por fin, ya hemos conseguido probar este motor impulsando a un turismo; aunque en un Mazda-3, porque est\u00e1 claro que el \u201c2\u201d, como se ha explicado en los p\u00e1rrafos anteriores, no ha llegado ni va a llegar. Al menos, el Sed\u00e1n est\u00e1 igualado en peso (kilo m\u00e1s o menos) con el 5 Puertas, y tiene mejor aerodin\u00e1mica; as\u00ed que su resultado es muy significativo. La causa de todo este aparente sinsentido bien puede ser la expresada respecto al retorno hacia la gasolina en los p\u00e1rrafos de la autocita, o tambi\u00e9n que en Mazda est\u00e1n tan imbuidos (y con motivo) de su posici\u00f3n como adalides del motor de gasolina atmosf\u00e9rico, que se permiten el lujo de despreciar la opci\u00f3n que, si bien en ligero declive, todav\u00eda es la mayoritaria en el mercado, incluso en el segmento B.<\/p>\n<p>Y sobre esta posici\u00f3n del mercado aparecer\u00e1 en este blog, dentro de unas cuantas semanas (a principios o medidos de Diciembre) nuestro comentario sobre una interesante encuesta relativa a la posici\u00f3n que el mercado espa\u00f1ol mantiene en esta competencia entre gasolina y gas\u00f3leo. Pero no adelantemos acontecimientos, y vamos ya con la prueba del Mazda-3 Sed\u00e1n, un coche bien conocido pero que cobra un renovado inter\u00e9s al disponer en su oferta de este interesante motor 1.5-D; combinaci\u00f3n de cuyos datos b\u00e1sicos pasamos a dar cuenta en esta ficha t\u00e9cnica resumida:<\/p>\n<table border=\"1\" width=\"700\">\n<tbody>\n<tr>\n<td>\n<h3><span style=\"text-decoration: underline\"><strong>Mazda-3 Sed\u00e1n 1.5-D:<\/strong><\/span><\/h3>\n<p><strong> Motor: 1.499 cc; 105 CV a 4.000 rpm; 27,5 m.kg de 1.600 a 2.500 rpm. <\/strong><\/p>\n<p><strong>Transmisi\u00f3n: Tracci\u00f3n delantera; caja de seis marchas, con 43,1\/53,3 km\/h a 1.000 rpm en 5\u00aa\/6\u00aa. <\/strong><\/p>\n<p><strong>Neum\u00e1ticos: 215\/45-18 (Michelin Pilot Sport-3). <\/strong><\/p>\n<p><strong>Cotas (longitud\/anchura\/altura): 4,58\/1,80\/1,45 metros. <\/strong><\/p>\n<p><strong>Peso (sin conductor con dep\u00f3sito lleno): 1.265 kg. <\/strong><\/p>\n<p><strong>Velocidad m\u00e1xima: 186 km\/h. <\/strong><\/p>\n<p><strong>Consumo extra-urbano: 3,5 l\/100 km. <\/strong><\/p>\n<p><strong>Emisi\u00f3n ponderada de CO2: 99 g\/km.<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<blockquote>\n<div id=\"attachment_15041\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15041\" class=\"size-full wp-image-15041\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sed\u00e1n_03.jpg\" alt=\"El bastidor de todos los Mazda (MX-5 aparte) con tren trasero independiente est\u00e1 pr\u00e1cticamente calcado de unos modelos a otros; prueba de que la marca est\u00e1 satisfecha con ese dise\u00f1o, y lo mantiene para todos.\" width=\"700\" height=\"407\" \/><p id=\"caption-attachment-15041\" class=\"wp-caption-text\"><em>El bastidor de todos los Mazda (MX-5 aparte) con tren trasero independiente est\u00e1 pr\u00e1cticamente calcado de unos modelos a otros; prueba de que la marca est\u00e1 satisfecha con ese dise\u00f1o, y lo mantiene para todos.<\/em><\/p><\/div><\/blockquote>\n<p>Si no el conjunto del coche, el motor en s\u00ed bien se merece ampliar un poco los datos de esta ficha. Empecemos por decir (casi sobrar\u00eda, puesto que todos los motores de Mazda tienen esta caracter\u00edstica) que el bloque es de aluminio; gracias a lo cual, y a sus menores dimensiones, pesa 50 kilos menos (se dice pronto) que el 2.2-D al que viene a complementar en la oferta turbodiesel de la marca. En cuanto a tecnolog\u00edas, y al margen de lo habitual como inyecci\u00f3n common-rail y turbo de geometr\u00eda variable, el intercooler es del tipo agua\/aire y la limpieza de gases se consigue con catalizador, filtro de part\u00edculas y un EGR doble para baja y alta carga.<\/p>\n<p>Por lo que respecta al rendimiento, nada excepcional en potencia ni en par; bien, sin m\u00e1s, puesto que extrapolando sus resultados a la cilindrada 1.6 -mucho m\u00e1s habitual- dispondr\u00eda de 112 CV y un par de 28,8 m.kg, que viene a ser lo de un 1.6 mono\u00e1rbol de 8 v\u00e1lvulas. Y ya sabemos que estos 1.6, pero con esta estructura doble \u00e1rbol de 16 v\u00e1lvulas del Mazda, est\u00e1n en la horquilla de 120 a 136 CV y 300 a 320 Nm, en su m\u00e1s habitual presentaci\u00f3n; e incluso hay alguna que otra \u201crareza\u201d con 160 CV y 350 Nm. Pero seg\u00fan la curva oficial, nuestro motor ya genera unos buenos 21,4 mkg a 1.300 rpm, que es el r\u00e9gimen al que los TD suelen empezar a disponer de un soplado un poco por encima de la presi\u00f3n atmosf\u00e9rica. Lo que resulta un tanto in\u00fatil es que luego suba hasta 5.200 rpm antes de cortar, pues se consigue m\u00e1s aceleraci\u00f3n cambiando antes; puede servir si se trata de rematar un adelantamiento apurado, que mejor ser\u00eda no haber iniciado.<\/p>\n<blockquote>\n<div id=\"attachment_15042\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15042\" class=\"size-full wp-image-15042\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sed\u00e1n_04.jpg\" alt=\"Bajo ese enfoque es cuando el Mazda-3 cobra aires de modernidad, con ese dise\u00f1o de dos vol\u00famenes y medio y luneta muy tendida, que ofrece una excelente aerodin\u00e1mica, aunque se separe ya del cl\u00e1sico dise\u00f1o de berlina de tres vol\u00famenes bien diferenciados, al precio de una tapa de maletero de dimensiones algo m\u00e1s restringidas, aunque con mayor rigidez.\" width=\"700\" height=\"467\" \/><p id=\"caption-attachment-15042\" class=\"wp-caption-text\"><em>Bajo ese enfoque es cuando el Mazda-3 cobra aires de modernidad, con ese dise\u00f1o de dos vol\u00famenes y medio y luneta muy tendida, que ofrece una excelente aerodin\u00e1mica, aunque se separe ya del cl\u00e1sico dise\u00f1o de berlina de tres vol\u00famenes bien diferenciados, al precio de una tapa de maletero de dimensiones algo m\u00e1s restringidas, aunque con mayor rigidez.<\/em><\/p><\/div><\/blockquote>\n<p>La transmisi\u00f3n de seis marchas tiene unos desarrollos bien elegidos, con la 6\u00aa justo al l\u00edmite de tener todav\u00eda un aceptable empuje, a la par que garantiza unos cruceros desahogados y unos consumos econ\u00f3micos; m\u00e1s sobre esto a continuaci\u00f3n. Su manejo, como en todos los Mazda, muy suave y agradable, de los que incitan a utilizar el cambio incluso no es preciso en absoluto. La punta te\u00f3rica se puede lograr o bien \u201cechando las muelas\u201d a 4.300 rpm en 5\u00aa, o bien mucho m\u00e1s tranquilamente, a 3.600 rpm en 6\u00aa; en ambos casos, la potencia debe estar ligeramente por encima de los 100 CV.<\/p>\n<p>De lo que va sobrado el coche es de frenos, con unos discos delanteros de 295 mm; aunque el tama\u00f1o roce los 4,6 metros de longitud, el peso (que es lo que importa) apenas si sobrepasa la tonelada y cuarto en vac\u00edo; en cualquier caso, y por mucho que carguemos el coche (5 plazas y 420 litros de maletero), tenemos garantizada con total tranquilidad la bajada de puerto, por largo que sea. Y tanto m\u00e1s cuanto que la combinaci\u00f3n de una carrocer\u00eda sed\u00e1n con una mec\u00e1nica de poco m\u00e1s de 100 CV, no ser\u00eda la opci\u00f3n habitual para un conductor de los que gusten ir por ah\u00ed \u201cdesempedrando\u201d, con la familia dentro del coche.<\/p>\n<blockquote>\n<div id=\"attachment_15043\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15043\" class=\"size-full wp-image-15043\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sed\u00e1n_05.jpg\" alt=\"La tapicer\u00eda bi-color es uno de los signos t\u00edpicos de los acabados m\u00e1s lujosos de Mazda; cuando la elecci\u00f3n de tonos es adecuada, le da cierta alegr\u00eda al interior del habit\u00e1culo.\" width=\"700\" height=\"467\" \/><p id=\"caption-attachment-15043\" class=\"wp-caption-text\"><em>La tapicer\u00eda bi-color es uno de los signos t\u00edpicos de los acabados m\u00e1s lujosos de Mazda; cuando la elecci\u00f3n de tonos es adecuada, le da cierta alegr\u00eda al interior del habit\u00e1culo.<\/em><\/p><\/div><\/blockquote>\n<p>Pero no ser\u00e1 porque, en cuanto a bastidor, este Mazda-3 no se preste a ello; de los frenos ya hemos hablado. En cuanto a suspensi\u00f3n, la tercera ilustraci\u00f3n gr\u00e1fica que acompa\u00f1a a este texto ya deja bien claro que el esquema es el mismo que tan buen resultado viene dando no ya s\u00f3lo en la berlina Mazda-6 (un referente al respecto en el segmento D), sino tambi\u00e9n en el SUV CX-5. El eje trasero torsional (que tambi\u00e9n va muy bien, dentro de dicho dise\u00f1o) queda limitado al Mazda-2 y al CX-3. Y por lo que toca a la direcci\u00f3n, es de relaci\u00f3n francamente r\u00e1pida (14:1), por lo que con 2,5 vueltas de volante (con llanta 18\u201d, como en nuestro caso concreto), se consigue un di\u00e1metro de giro entre bordillos de 10,6 metros, que no est\u00e1 nada mal para una generosa batalla de 2,70 metros.<\/p>\n<p>Y cerramos con el equipamiento de neum\u00e1ticos, que en la unidad de pruebas era, tal y como se rese\u00f1a en la ficha, nada menos que unos Michelin Pilot Sport-3 de perfil 45; lo dicho, como matar moscas a ca\u00f1onazos, entre lo de los frenos, la buena suspensi\u00f3n y la direcci\u00f3n r\u00e1pida. Pero como dice el cl\u00e1sico aforismo, \u201cm\u00e1s vale que sobre\u2026\u201d. En fin, que nuestro SportSedan, haciendo honor a su denominaci\u00f3n, era casi \u201cde carreras\u201d (motor aparte), con unos l\u00edmites de frenada y paso por curva muy por encima de lo que le corresponder\u00eda por tipo de carrocer\u00eda y mec\u00e1nica.<\/p>\n<blockquote>\n<div id=\"attachment_15044\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15044\" class=\"size-full wp-image-15044\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sed\u00e1n_06.jpg\" alt=\"Las tomas de aire delanteras tienen un dimensionamiento algo distinto del habitual: la superior es grande, con el radiador principal detr\u00e1s suyo; mientras que la inferior es m\u00e1s peque\u00f1a, para el radiador del climatizador. Atenci\u00f3n a los dos peque\u00f1os deflectores aerodin\u00e1micos que asoman bajo el fald\u00f3n, debajo de los antinieblas.\" width=\"700\" height=\"467\" \/><p id=\"caption-attachment-15044\" class=\"wp-caption-text\"><em>Las tomas de aire delanteras tienen un dimensionamiento algo distinto del habitual: la superior es grande, con el radiador principal detr\u00e1s suyo; mientras que la inferior es m\u00e1s peque\u00f1a, para el radiador del climatizador. Atenci\u00f3n a los dos peque\u00f1os deflectores aerodin\u00e1micos que asoman bajo el fald\u00f3n, debajo de los antinieblas.<\/em><\/p><\/div><\/blockquote>\n<p>Otro detalle: la distancia libre al suelo es francamente buena, de 155 mm; y eso con el conductor a bordo, ya que el dato corresponde (y lo dicen expl\u00edcitamente) a la serie de cotas con los 75 kilos del hipot\u00e9tico conductor a bordo. Y por cierto, llevo m\u00e1s de un a\u00f1o observando que el dato del peso, entre el documento azul y el verde (Ficha de Homologaci\u00f3n y Permiso de Circulaci\u00f3n) viene ya coincidiendo en casi la totalidad de los coches que pruebo, a diferencia de lo que ocurr\u00eda a\u00f1os atr\u00e1s. Lo que no acaba de estar claro es si el dato corresponde a repostado pero vac\u00edo, o con el incremento de los dichosos 75 kilos; pero al menos, en los dos pone lo mismo. \u00bfNos habr\u00e1n le\u00eddo? Y perd\u00f3n por la presunci\u00f3n; pero puesto que parece que aqu\u00ed \u00e9ramos los \u00fanicos que nos hab\u00edamos fijado y lo denunciamos, pues a lo mejor podr\u00eda deberse a ello. A falta de otra raz\u00f3n, buena es esa.<\/p>\n<p>Y otro detalle m\u00e1s: la versi\u00f3n 5 Puertas de este Mazda-3 1.5-D tiene una velocidad punta de 185 km\/h, un km\/h menos que el Sed\u00e1n, fruto de la diferencia en aerodin\u00e1mica. Y poco me parece como diferencia, ya que el 5P tiene un Cx de 0,275, mientras que el Sed\u00e1n baja a 0,26, lo que supone que el 5P tiene un 6% m\u00e1s de resistencia aerodin\u00e1mica. Con una secci\u00f3n frontal de 2,19 m2, nuestro coche tiene un factor S.Cx total de 0,57, que es francamente muy favorable para un turismo de este tama\u00f1o. Y es que el dise\u00f1o de dos vol\u00famenes y medio, unido a optimizaciones tales como parrilla frontal activa, bajos carenados y deflectores ante las ruedas, acaba dando sus frutos.<\/p>\n<blockquote>\n<div id=\"attachment_15045\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15045\" class=\"size-full wp-image-15045\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sed\u00e1n_07.jpg\" alt=\"El HUD (Head-Up Display) es un buen colaborador para el conductor, una vez que se ha afinado a la perfecci\u00f3n el \u00e1ngulo en el que no molesta la visi\u00f3n de la carretera, pero permite consultarlo sin apenas desviar hacia abajo la mirada.\" width=\"700\" height=\"373\" \/><p id=\"caption-attachment-15045\" class=\"wp-caption-text\"><em>El HUD (Head-Up Display) es un buen colaborador para el conductor, una vez que se ha afinado a la perfecci\u00f3n el \u00e1ngulo en el que no molesta la visi\u00f3n de la carretera, pero permite consultarlo sin apenas desviar hacia abajo la mirada.<\/em><\/p><\/div><\/blockquote>\n<p>Y as\u00ed es como salen los buenos resultados del consumo, que es lo siguiente que pasamos a comentar a continuaci\u00f3n:<\/p>\n<table border=\"1\" width=\"700\">\n<tbody>\n<tr>\n<td><strong>Resultados del Mazda-3 Sport Sed\u00e1n Luxury en el circuito habitual:<\/strong><\/p>\n<p><strong>Ritmo econ\u00f3mico NUEVO: Consumo: 4,76 l\/100 km. Promedio: 96,9 km\/h.<\/strong><\/p>\n<p><strong>Al econ\u00f3mico ANTIGUO: Consumo: 5,36 l\/100 km. Promedio: 106,9 km\/h.<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Vaya por delante que el recorrido al ritmo econ\u00f3mico nuevo se realiz\u00f3 un par de veces, con tres d\u00edas de separaci\u00f3n, en cuyo hueco se llev\u00f3 a cabo la pasada a ritmo antiguo. Y es que al retorno de la primera pasada y, aunque menos, todav\u00eda algo en la intermedia a ritmo m\u00e1s r\u00e1pido, tuvimos un viento de cara que por la madrugada m\u00e1s temprano no hab\u00eda soplado de cola, y por lo tanto falseaba algo el resultado. Para intentar una segunda pasada a ritmo r\u00e1pido ya no nos quedaba tiempo, pues ten\u00edamos que devolver el coche. No obstante, los resultados definitivos y publicados son muy expl\u00edcitos respecto a la econom\u00eda del coche.<\/p>\n<p>Digamos, en primer lugar, que el motor aguanta ir en 6\u00aa a partir de 70 km\/h de veloc\u00edmetro, que son 68 reales (justo un soplo menos de 1.300 rpm). En el primer intento nos sali\u00f3 un consumo de 4,96 y un tiempo de 5h 13m, quiz\u00e1s demasiado lento, por intentar aguantar demasiado la 6\u00aa. As\u00ed que en la segunda pasada, ya sin viento contrario, manejamos algo m\u00e1s el cambio, con el resultado de rebajar 0,2 l\/100 km el consumo y tambi\u00e9n un minuto el tiempo. Efecto combinado de no tener viento de cara y de conducir con un poco m\u00e1s de br\u00edo, pero sin perjudicar el consumo.<\/p>\n<blockquote>\n<div id=\"attachment_15046\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15046\" class=\"size-full wp-image-15046\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sed\u00e1n_08.jpg\" alt=\"Perfecto enfoque lateral, que permite comprender de donde sale ese coeficiente aerodin\u00e1mico Cx de 0,26.\" width=\"700\" height=\"373\" \/><p id=\"caption-attachment-15046\" class=\"wp-caption-text\"><em>Perfecto enfoque lateral, que permite comprender de donde sale ese coeficiente aerodin\u00e1mico Cx de 0,26.<\/em><\/p><\/div><\/blockquote>\n<p>Comparativamente, el resultado de esta segunda pasada empata con el conseguido por el Astra 1.6 de 136 CV (4,74 y 5.10), que es el mejor que tenemos por ahora en turbodiesel del segmento C. Y tambi\u00e9n queda ligeramente mejor que el Fiat Tipo Sed\u00e1n 1.6 de 120 CV, que sube un poco m\u00e1s, a 4,82. El resto de lo que tenemos probado ya est\u00e1 por encima de los 5 litros.<\/p>\n<p>En cuanto al consumo a ritmo antiguo, el tiempo (4h 43m) es de tipo medio, tirando a bueno. Y de nuevo con ligero viento contrario al retorno, como ya se ha dicho. En dichas condiciones, queda por detr\u00e1s de todos los modelos optimizados, que est\u00e1n entre los 5,02 del Golf VII BlueMotion de 110 CV y los 5,26 del Le\u00f3n III de similar mec\u00e1nica, pero peor aerodin\u00e1mica. Y ya en modelos \u201cnormales\u201d, sin optimizaci\u00f3n espec\u00edfica como versi\u00f3n, el listado del segmento C empieza con el Golf VII de 105 CV de 2013 (5,27 l\/100 km) y luego viene el Honda Civic 1.6 de 120 CV, con 5,30. Nuestro Mazda empata a 5,36 con el Volvo V-40 D-2 1.6 de 115 CV, y de nuevo le mejora un poco al Tipo Sed\u00e1n, que est\u00e1 en 5,43. Resultados muy apretados todos ellos, que indican por donde anda, poco m\u00e1s o menos, el l\u00edmite de econom\u00eda de los actuales segmento C. Y si le damos el beneficio de la mitad de mejora que tuvo al pasar de un d\u00eda con algo m\u00e1s de viento a uno tranquilo (o sea, simplemente 0,1 menos) el consumo hubiese sido del orden de 5,26, justo en la frontera entre los optimizados y los que no lo son.<\/p>\n<blockquote>\n<div id=\"attachment_15047\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15047\" class=\"size-full wp-image-15047\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sed\u00e1n_09.jpg\" alt=\"El asiento posterior, muy plano en banqueta y respaldo, est\u00e1 pensado para tres plazas, en detrimento del confort de cuando viajan en \u00e9l s\u00f3lo dos ocupantes (que suele ser lo m\u00e1s frecuente).\" width=\"700\" height=\"467\" \/><p id=\"caption-attachment-15047\" class=\"wp-caption-text\"><em>El asiento posterior, muy plano en banqueta y respaldo, est\u00e1 pensado para tres plazas, en detrimento del confort de cuando viajan en \u00e9l s\u00f3lo dos ocupantes (que suele ser lo m\u00e1s frecuente).<\/em><\/p><\/div><\/blockquote>\n<p>Este coche ten\u00eda un peligro para realizar las pruebas, y de nuevo nos referimos a la descompensaci\u00f3n entre unas prestaciones relativamente modestas y un bastidor que permite circular muy r\u00e1pido. As\u00ed pues, hab\u00eda que frenarse un poco en la conducci\u00f3n para no intentar compensar lo uno con lo otro; y especialmente al circular al ritmo antiguo, algo m\u00e1s din\u00e1mico. Hubiese sido relativamente f\u00e1cil conseguir un tiempo algo m\u00e1s brillante, pero aplicando una conducci\u00f3n m\u00e1s del estilo \u201cinteresante\u201d, que no hubiese tenido sentido en un coche de estas caracter\u00edsticas. Y probablemente, ello no habr\u00eda repercutido sensiblemente en los consumos, pero s\u00ed habr\u00eda desvirtuado el esp\u00edritu de la prueba.<\/p>\n<p>Las luces van muy bien, aunque no llegan a ser de las que giran con la acci\u00f3n del volante. Por su parte, los antinieblas son perfectamente in\u00fatiles en cuanto a abrir la iluminaci\u00f3n lateralmente respecto a lo que ya hacen las luces de cruce. En caso de niebla no hemos tenido ocasi\u00f3n de comprobarlo, pero a tenor de lo poco que se nota su iluminaci\u00f3n a corta distancia sobre la que ya proyectan las de cruce, parece que tampoco en este caso tienen mucho que ofrecer. La verdad es que, muy de vez en cuando, s\u00ed encontramos coches en los que estos proyectores auxiliares cumplen muy bien su misi\u00f3n, ya sea de frente o lateralmente; lo cual indica que sus fabricantes s\u00ed son capaces de ofrecer un producto v\u00e1lido. Pero sea por cuesti\u00f3n de dise\u00f1o y encajarlas de la forma m\u00e1s est\u00e9tica en el frontal, o por ser m\u00e1s caras, parece que los fabricantes del coche no se preocupan demasiado de pedir este tipo de antinieblas que realmente s\u00ed funcionan.<\/p>\n<blockquote>\n<div id=\"attachment_15048\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15048\" class=\"size-full wp-image-15048\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sed\u00e1n_10.jpg\" alt=\"La l\u00ednea de cintura tiene cierto dise\u00f1o en cu\u00f1a, pero este enfoque (y un objetivo un tanto \u201cgran angular\u201d) exagera dicha caracter\u00edstica.\" width=\"700\" height=\"373\" \/><p id=\"caption-attachment-15048\" class=\"wp-caption-text\"><em>La l\u00ednea de cintura tiene cierto dise\u00f1o en cu\u00f1a, pero este enfoque (y un objetivo un tanto \u201cgran angular\u201d) exagera dicha caracter\u00edstica.<\/em><\/p><\/div><\/blockquote>\n<p>Resumiendo las impresiones sobre este Mazda-3 Sed\u00e1n 1.5-D: es un coche el\u00e1stico en cuanto a su utilizaci\u00f3n, con un consumo muy econ\u00f3mico pero con cinco plazas y un razonable maletero, aunque ya empieza ser de un tama\u00f1o notable; por poner un l\u00edmite, digamos que todo lo que pasa de 4,5 metros de longitud ya es un coche grande de por s\u00ed, al margen de lo que vayan imponiendo las modas. Pero las calles, las plazas de aparcamiento y no digamos los accesos a muchos garajes y parkings, no han evolucionado apenas con el paso del tiempo; y eso para los que se construyen nuevos.<\/p>\n<p>Pero sigo penando en lo que podr\u00eda ser (bueno, ya lo es, pero en otros mercados) el Mazda-2 equipado con este motor, a juzgar tanto por las impresiones y datos de consumo de ordenador durante su presentaci\u00f3n, como por la comparaci\u00f3n que se puede hacer entre su carrocer\u00eda y la del Mazda-3 con motores comunes. Pero no creo que a km77 le compense la maniobra de buscar uno en Francia, o m\u00e1s all\u00e1, para traerlo y darnos el gustazo de comprobar si bate r\u00e9cords o no; cuando en el fondo dar\u00eda igual, pues en Mazda no van a cambiar su pol\u00edtica comercial, sumamente respetable, hagamos lo que hagamos y digamos lo que digamos.<\/p>\n<blockquote>\n<div id=\"attachment_15049\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15049\" class=\"size-full wp-image-15049\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sed\u00e1n_11.jpg\" alt=\"El maletero no tiene una capacidad (420 litros) proporcionada a los casi 4,6 metros de longitud, pero es bastante c\u00fabico y dispone de unos tiradores en las esquinas laterales superiores para poder abatir las mitades asim\u00e9tricas del respaldo cuando se est\u00e1 introduciendo una carga voluminosa y nos hemos olvidado de hacerlo previamente por laspuertas laterales.\" width=\"700\" height=\"467\" \/><p id=\"caption-attachment-15049\" class=\"wp-caption-text\"><em>El maletero no tiene una capacidad (420 litros) proporcionada a los casi 4,6 metros de longitud, pero es bastante c\u00fabico y dispone de unos tiradores en las esquinas laterales superiores para poder abatir las mitades asim\u00e9tricas del respaldo cuando se est\u00e1 introduciendo una carga voluminosa y nos hemos olvidado de hacerlo previamente por laspuertas laterales.<\/em><\/p><\/div><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Por fin, al cabo de muchos meses, hemos conseguido realizar la prueba de este motor sobre un veh\u00edculo algo m\u00e1s representativo que un CX-3. Representativo a efectos comparativos, puesto que comercialmente, los SUV est\u00e1n en el candelero desde hace varios a\u00f1os. Pero en cuanto a consumos, tenemos much\u00edsimos m\u00e1s datos acumulados con carrocer\u00eda de turismo, [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":15040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3910],"tags":[],"class_list":["post-15037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curvas-enlazadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prueba de consumo (223): Mazda-3 Sed\u00e1n 1.5-D 105 CV - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prueba de consumo (223): Mazda-3 Sed\u00e1n 1.5-D 105 CV - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Por fin, al cabo de muchos meses, hemos conseguido realizar la prueba de este motor sobre un veh\u00edculo algo m\u00e1s representativo que un CX-3. Representativo a efectos comparativos, puesto que comercialmente, los SUV est\u00e1n en el candelero desde hace varios a\u00f1os. Pero en cuanto a consumos, tenemos much\u00edsimos m\u00e1s datos acumulados con carrocer\u00eda de turismo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-26T07:30:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T17:51:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sedan_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"373\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A. de A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"A. de A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/\"},\"author\":{\"name\":\"A. de A.\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/9528542f10577efe637078df52f3a1ea\"},\"headline\":\"Prueba de consumo (223): Mazda-3 Sed\u00e1n 1.5-D 105 CV\",\"datePublished\":\"2016-11-26T07:30:20+00:00\",\"dateModified\":\"2021-03-31T17:51:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/\"},\"wordCount\":3582,\"commentCount\":31,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Mazda3-Sedan_02.jpg\",\"articleSection\":[\"Curvas Enlazadas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/\",\"name\":\"Prueba de consumo (223): Mazda-3 Sed\u00e1n 1.5-D 105 CV - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Mazda3-Sedan_02.jpg\",\"datePublished\":\"2016-11-26T07:30:20+00:00\",\"dateModified\":\"2021-03-31T17:51:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Mazda3-Sedan_02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Mazda3-Sedan_02.jpg\",\"width\":700,\"height\":373,\"caption\":\"La carrocer\u00eda Sed\u00e1n del Mazda-3 tiene un sabor casi cl\u00e1sico, especialmente en su zona frontal y tres cuartos delantera. La proporci\u00f3n entre anchura y altura (1,80 para 1,45 m) nos recuerda las berlinas de tipo medio\\\/grande de hace dos o tres d\u00e9cadas, antes de que empezase la escalada hacia alturas cada vez mayores.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curvas Enlazadas\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/curvas-enlazadas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prueba de consumo (223): Mazda-3 Sed\u00e1n 1.5-D 105 CV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Noticias y opiniones en km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/9528542f10577efe637078df52f3a1ea\",\"name\":\"A. de A.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/arturo_andres_curvasenlazadas-150x111.jpg\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/arturo_andres_curvasenlazadas-150x111.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/arturo_andres_curvasenlazadas-150x111.jpg\",\"caption\":\"A. de A.\"},\"description\":\"Probablemente el m\u00e1s veterano de los periodistas del motor que sigue \u201cactivamente activo\u201d. Al margen de divulgaci\u00f3n t\u00e9cnica, llevar algunos \u201cConsultorios del lector\u201d y otros temas variados, su especialidad -desde Navidades de 1965- viene siendo las pruebas de coches, centr\u00e1ndose muy espec\u00edficamente en el control del consumo. Para lo cual ha ido dejando \u201cen herencia\u201d en las diversas publicaciones en las que ha colaborado diversos recorridos fijos, que permitan la comparaci\u00f3n de resultados en igualdad de condiciones.\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/arturoandres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prueba de consumo (223): Mazda-3 Sed\u00e1n 1.5-D 105 CV - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/","og_locale":"es_ES","og_type":"article","og_title":"Prueba de consumo (223): Mazda-3 Sed\u00e1n 1.5-D 105 CV - Revista km77","og_description":"Por fin, al cabo de muchos meses, hemos conseguido realizar la prueba de este motor sobre un veh\u00edculo algo m\u00e1s representativo que un CX-3. Representativo a efectos comparativos, puesto que comercialmente, los SUV est\u00e1n en el candelero desde hace varios a\u00f1os. Pero en cuanto a consumos, tenemos much\u00edsimos m\u00e1s datos acumulados con carrocer\u00eda de turismo, [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/","og_site_name":"Revista km77","article_published_time":"2016-11-26T07:30:20+00:00","article_modified_time":"2021-03-31T17:51:34+00:00","og_image":[{"width":700,"height":373,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sedan_02.jpg","type":"image\/jpeg"}],"author":"A. de A.","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"A. de A.","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/"},"author":{"name":"A. de A.","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/9528542f10577efe637078df52f3a1ea"},"headline":"Prueba de consumo (223): Mazda-3 Sed\u00e1n 1.5-D 105 CV","datePublished":"2016-11-26T07:30:20+00:00","dateModified":"2021-03-31T17:51:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/"},"wordCount":3582,"commentCount":31,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sedan_02.jpg","articleSection":["Curvas Enlazadas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/","url":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/","name":"Prueba de consumo (223): Mazda-3 Sed\u00e1n 1.5-D 105 CV - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sedan_02.jpg","datePublished":"2016-11-26T07:30:20+00:00","dateModified":"2021-03-31T17:51:34+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sedan_02.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2016\/11\/Mazda3-Sedan_02.jpg","width":700,"height":373,"caption":"La carrocer\u00eda Sed\u00e1n del Mazda-3 tiene un sabor casi cl\u00e1sico, especialmente en su zona frontal y tres cuartos delantera. La proporci\u00f3n entre anchura y altura (1,80 para 1,45 m) nos recuerda las berlinas de tipo medio\/grande de hace dos o tres d\u00e9cadas, antes de que empezase la escalada hacia alturas cada vez mayores."},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/prueba-de-consumo-223-mazda-3-sedan-1-5-d-105-cv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Curvas Enlazadas","item":"https:\/\/www.km77.com\/revista\/curvas-enlazadas\/"},{"@type":"ListItem","position":3,"name":"Prueba de consumo (223): Mazda-3 Sed\u00e1n 1.5-D 105 CV"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Noticias y opiniones en km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/9528542f10577efe637078df52f3a1ea","name":"A. de A.","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/arturo_andres_curvasenlazadas-150x111.jpg","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/arturo_andres_curvasenlazadas-150x111.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/03\/arturo_andres_curvasenlazadas-150x111.jpg","caption":"A. de A."},"description":"Probablemente el m\u00e1s veterano de los periodistas del motor que sigue \u201cactivamente activo\u201d. Al margen de divulgaci\u00f3n t\u00e9cnica, llevar algunos \u201cConsultorios del lector\u201d y otros temas variados, su especialidad -desde Navidades de 1965- viene siendo las pruebas de coches, centr\u00e1ndose muy espec\u00edficamente en el control del consumo. Para lo cual ha ido dejando \u201cen herencia\u201d en las diversas publicaciones en las que ha colaborado diversos recorridos fijos, que permitan la comparaci\u00f3n de resultados en igualdad de condiciones.","url":"https:\/\/www.km77.com\/revista\/author\/arturoandres\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/15037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=15037"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/15037\/revisions"}],"predecessor-version":[{"id":41357,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/15037\/revisions\/41357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/15040"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=15037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=15037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=15037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}