{"id":14298,"date":"2014-01-06T22:16:57","date_gmt":"2014-01-06T21:16:57","guid":{"rendered":"http:\/\/lucascruz.es\/?p=467"},"modified":"2021-03-31T20:00:35","modified_gmt":"2021-03-31T18:00:35","slug":"sin-ruedas-se-sufre-mucho","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/","title":{"rendered":"Sin ruedas se sufre mucho"},"content":{"rendered":"<p>Hoy hab\u00eda un tramo cronometrado bastante largo, 433 km, que a nosotros se nos ha hecho largu\u00edsimo. Pero comencemos por el principio. La especial era rapid\u00edsima, con l\u00edneas rectas interminables en las que hab\u00eda much\u00edsimo polvo, lo que dificultaba la visibilidad. Pero para nosotros los problemas han comenzado en el kil\u00f3metro 60, cuando hemos pinchado dos ruedas a la vez. Las hemos cambiado bastante r\u00e1pido y hemos vuelto a coger ritmo hasta que en el kil\u00f3metro 160 hemos vuelto a pinchar otra rueda.<br \/>\n<img decoding=\"async\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/01\/etapa2_dakar_2014.jpg\" alt=\"etapa2_dakar_2014\" width=\"700\" height=\"467\" class=\"aligncenter size-full wp-image-469\" \/><br \/>\n<!--more--><br \/>\nEntonces las cosas no han sido tan f\u00e1ciles, ya que la rueda estaba deformada y no cab\u00eda en el hueco. Hemos tardado un buen rato en conseguirlo. Por reglamento no se pueden abandonar los neum\u00e1ticos pinchados\u2026<br \/>\nAdem\u00e1s del tiempo perdido, para nosotros comenzaba una carrera bien diferente, ya que todav\u00eda ten\u00edamos 270 km por delante y ya no nos quedaban m\u00e1s neum\u00e1ticos de repuesto. Se ha hecho largo.<br \/>\nQuitando este susto, la etapa ha ido bastante bien. En las partes sinuosas conseguimos recuperar tiempo a los dem\u00e1s, lo que es un buen s\u00edntoma de que nos vamos amoldando perfectamente al nuevo coche.<br \/>\nPara hacer la etapa m\u00e1s completa, en un punto hab\u00eda un peque\u00f1o l\u00edo de navegaci\u00f3n. Hab\u00eda una nota cuyo dise\u00f1o no estaba muy bien y lo interpretamos bien, pero el rumbo era para otro lado del dibujo.<br \/>\nLlegando a las dunas hemos disfrutado de un peque\u00f1o duelo con Carlos Sainz, que en cuanto nos ha visto llegar ha apretado el ritmo. Hemos tirado detr\u00e1s de \u00e9l y se nos ha escapado porque la presi\u00f3n de las ruedas era alt\u00edsima y \u00e9l lleva auto hinchado. Pero en la \u201cpelea\u201d Carlos ha doblado un trapecio trasero.<br \/>\nLa parte final era dentro de un r\u00edo, con 35 km muy rotos en los que hemos optado por rodar a un ritmo tranquilo por miedo a pinchar otra vez.<br \/>\nOtra de las caracter\u00edsticas del d\u00eda es que ha hecho mucho calor, pero con la nueva ropa ignifuga que nos ha hecho Galuppo, que reduce la temperatura corporal, todo ha ido muuuuy bien.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy hab\u00eda un tramo cronometrado bastante largo, 433 km, que a nosotros se nos ha hecho largu\u00edsimo. Pero comencemos por el principio. La especial era rapid\u00edsima, con l\u00edneas rectas interminables en las que hab\u00eda much\u00edsimo polvo, lo que dificultaba la visibilidad. Pero para nosotros los problemas han comenzado en el kil\u00f3metro 60, cuando hemos pinchado [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3912],"tags":[6563,7932,22,1870,5779,6565],"class_list":{"0":"post-14298","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"hentry","6":"category-engendro-mecanico","7":"tag-dakar-2014","9":"tag-general","10":"tag-lucas-cruz","11":"tag-nasser-al-attiyah","12":"tag-x-raid"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sin ruedas se sufre mucho - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sin ruedas se sufre mucho - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Hoy hab\u00eda un tramo cronometrado bastante largo, 433 km, que a nosotros se nos ha hecho largu\u00edsimo. Pero comencemos por el principio. La especial era rapid\u00edsima, con l\u00edneas rectas interminables en las que hab\u00eda much\u00edsimo polvo, lo que dificultaba la visibilidad. Pero para nosotros los problemas han comenzado en el kil\u00f3metro 60, cuando hemos pinchado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-06T21:16:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T18:00:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/01\/etapa2_dakar_2014.jpg\" \/>\n<meta name=\"author\" content=\"Lucas Cruz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Cruz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/\"},\"author\":{\"name\":\"Lucas Cruz\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/036b9784aba37c21fa447fba0e018662\"},\"headline\":\"Sin ruedas se sufre mucho\",\"datePublished\":\"2014-01-06T21:16:57+00:00\",\"dateModified\":\"2021-03-31T18:00:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/\"},\"wordCount\":375,\"commentCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/etapa2_dakar_2014.jpg\",\"keywords\":[\"Dakar 2014\",\"Dakar 2014\",\"General\",\"Lucas Cruz\",\"Nasser Al-Attiyah\",\"X-Raid\"],\"articleSection\":[\"Engendro Mec\u00e1nico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/\",\"name\":\"Sin ruedas se sufre mucho - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/etapa2_dakar_2014.jpg\",\"datePublished\":\"2014-01-06T21:16:57+00:00\",\"dateModified\":\"2021-03-31T18:00:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/etapa2_dakar_2014.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/etapa2_dakar_2014.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/sin-ruedas-se-sufre-mucho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engendro Mec\u00e1nico\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sin ruedas se sufre mucho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Revista de km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/036b9784aba37c21fa447fba0e018662\",\"name\":\"Lucas Cruz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/715dc398c6e006faa6a503d0cb8c173c6d3b318ecdc639d507b2ba363c67ab13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/715dc398c6e006faa6a503d0cb8c173c6d3b318ecdc639d507b2ba363c67ab13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/715dc398c6e006faa6a503d0cb8c173c6d3b318ecdc639d507b2ba363c67ab13?s=96&d=mm&r=g\",\"caption\":\"Lucas Cruz\"},\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/lucascruz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sin ruedas se sufre mucho - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/","og_locale":"es_ES","og_type":"article","og_title":"Sin ruedas se sufre mucho - Revista km77","og_description":"Hoy hab\u00eda un tramo cronometrado bastante largo, 433 km, que a nosotros se nos ha hecho largu\u00edsimo. Pero comencemos por el principio. La especial era rapid\u00edsima, con l\u00edneas rectas interminables en las que hab\u00eda much\u00edsimo polvo, lo que dificultaba la visibilidad. Pero para nosotros los problemas han comenzado en el kil\u00f3metro 60, cuando hemos pinchado [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/","og_site_name":"Revista km77","article_published_time":"2014-01-06T21:16:57+00:00","article_modified_time":"2021-03-31T18:00:35+00:00","og_image":[{"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/01\/etapa2_dakar_2014.jpg","type":"","width":"","height":""}],"author":"Lucas Cruz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Cruz","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/"},"author":{"name":"Lucas Cruz","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/036b9784aba37c21fa447fba0e018662"},"headline":"Sin ruedas se sufre mucho","datePublished":"2014-01-06T21:16:57+00:00","dateModified":"2021-03-31T18:00:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/"},"wordCount":375,"commentCount":14,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/01\/etapa2_dakar_2014.jpg","keywords":["Dakar 2014","Dakar 2014","General","Lucas Cruz","Nasser Al-Attiyah","X-Raid"],"articleSection":["Engendro Mec\u00e1nico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/","url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/","name":"Sin ruedas se sufre mucho - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/01\/etapa2_dakar_2014.jpg","datePublished":"2014-01-06T21:16:57+00:00","dateModified":"2021-03-31T18:00:35+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/01\/etapa2_dakar_2014.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2014\/01\/etapa2_dakar_2014.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/sin-ruedas-se-sufre-mucho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Engendro Mec\u00e1nico","item":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/"},{"@type":"ListItem","position":3,"name":"Sin ruedas se sufre mucho"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Revista de km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/036b9784aba37c21fa447fba0e018662","name":"Lucas Cruz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/715dc398c6e006faa6a503d0cb8c173c6d3b318ecdc639d507b2ba363c67ab13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/715dc398c6e006faa6a503d0cb8c173c6d3b318ecdc639d507b2ba363c67ab13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/715dc398c6e006faa6a503d0cb8c173c6d3b318ecdc639d507b2ba363c67ab13?s=96&d=mm&r=g","caption":"Lucas Cruz"},"url":"https:\/\/www.km77.com\/revista\/author\/lucascruz\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/14298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=14298"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/14298\/revisions"}],"predecessor-version":[{"id":42550,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/14298\/revisions\/42550"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=14298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=14298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=14298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}