{"id":13419,"date":"2013-01-15T15:40:47","date_gmt":"2013-01-15T14:40:47","guid":{"rendered":"http:\/\/blogs.km77.com\/engendromecanico\/?p=13419"},"modified":"2021-03-31T20:05:29","modified_gmt":"2021-03-31T18:05:29","slug":"lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/","title":{"rendered":"Lexus GS 250, nueva versi\u00f3n gasolina. Precio de venta: 59 600 \u20ac"},"content":{"rendered":"<p><strong>Lexus presenta la versi\u00f3n GS 250<\/strong>. Un modelo con motor<strong> V6 de gasolina de 209 CV con tracci\u00f3n trasera y cambio autom\u00e1tico de 6 velocidades<\/strong> \u2014con levas en el volante para funcionamiento secuencial\u2014 que se pondr\u00e1 a la venta por un precio de 59 600 \u20ac.<br \/>\nEl motor \u00ab<strong>4GR-FSE<\/strong>\u00bb V6 2,5 con inyecci\u00f3n directa D-4, desarrolla una potencia m\u00e1xima de <strong>209 CV a 6400 rpm<\/strong>, y un par m\u00e1ximo de <strong>253 Nm\/4800rpm<\/strong>. Es el motor que actualmente monta el <a title=\"info IS\" href=\"https:\/\/www.km77.com\/00\/lexus\/is\/2011\/restyling-precio.asp\" target=\"_blank\" rel=\"noopener\">IS 250<\/a>, con optimizaci\u00f3n de la admisi\u00f3n (caudal\u00edmetro, v\u00e1lvulas y conducto de admisi\u00f3n), y el escape (nuevo catalizador para reducir las emisiones, en l\u00ednea con la normativa Euro5).<br \/>\nEl GS 250 tiene un consumo medio de <strong>8,9 litros\/100km<\/strong>\u00a0 y emite <strong>207 g\/km<\/strong> de part\u00edculas de CO2.<br \/>\n<strong>Im\u00e1genes:<\/strong><br \/>\n[nggallery id=135]<br \/>\n<!--more--><br \/>\nEl equipo que desarroll\u00f3 el sonido del motor V10 del <a title=\"info LFA\" href=\"https:\/\/www.km77.com\/00\/lexus\/lfa\/2010\/t01.asp\" target=\"_blank\" rel=\"noopener\">LFA<\/a>, ha desarrollado un dispositivo denominado <strong>\u00abIntake Sound Creator\u00bb<\/strong>. Es un sistema que aumenta la presi\u00f3n ac\u00fastica de las frecuencias que son agradables de escuchar para al o\u00eddo humano. El sonido que se produce durante la aceleraci\u00f3n a medio r\u00e9gimen es ligero y relajado, y m\u00e1s deportivo a alto r\u00e9gimen.<br \/>\n<strong>En el interior, las principales diferencias<\/strong> con el <a title=\"info GS\" href=\"https:\/\/www.km77.com\/00\/lexus\/gs\/2012\/lexus-gs-precios.asp\" target=\"_blank\" rel=\"noopener\">GS 450h<\/a> son la palanca de cambios forrada en cuero, el bot\u00f3n de arranque, el display (sin potenci\u00f3metro h\u00edbrido), y los asientos de tela (disponible en elacabado GS 250 Drive). La versi\u00f3n GS 250 est\u00e1 disponible con tres niveles de equipamiento:<\/p>\n<ul>\n<li><strong>GS 250 Drive<\/strong>: \u2014<strong>desde\u00a0 59 600<\/strong> <strong>\u20ac<\/strong>\u2014 es el modelo b\u00e1sico, incluye entre otros elementos de navegador con pantalla de 12,3 pulgadas, conexi\u00f3n USB y AUX-In, c\u00e1mara de marcha atr\u00e1s, faros de doble xen\u00f3n, sistema de entrada y arranque sin llave \u00abSmart Entry\u00bb, alarma, asientos tapizados en tela con regulaci\u00f3n el\u00e9ctrica y llantas de aleaci\u00f3n de 17 pulgadas.<\/li>\n<\/ul>\n<ul>\n<li><strong> GS 250 Plus<\/strong>: \u2014<strong>desde 64 600 \u20ac<\/strong>\u2014 a\u00f1ade respecto al nivel Drive asientos el\u00e9ctricos tapizados en cuero, llantas de aleaci\u00f3n ligera de 18 pulgadas y sensores de ayuda al aparcamiento.<\/li>\n<\/ul>\n<ul>\n<li><strong>GS 250 F Sport: \u2014desde 72 000 \u20ac\u2014 <\/strong>incluye el paquete deportivo \u00abF Sport\u00bb, con llantas de aleaci\u00f3n de 19 pulgadas dise\u00f1o \u00abF Sport\u00bb, asientos deportivos con regulaci\u00f3n el\u00e9ctrica \u201416 ajustes con soporte lumbar y p\u00e9lvico\u00bb, sistema de accionamiento autom\u00e1tico de luces de carretera (\u00abAHB\u00bb), techo solar el\u00e9ctrico y suspensi\u00f3n \u00abAVS\u00bb con modo de conducci\u00f3n \u00abSport S+\u00bb.<\/li>\n<\/ul>\n<p>Hasta la fecha, en Espa\u00f1a se comercializaba \u00fanicamente la variante h\u00edbrida del GS, denominada 450h (en otros mercados existe la versi\u00f3n GS 350, con motor de gasolina de 310 CV). Con esta nueva versi\u00f3n, la berlina GS intentar\u00e1 hacerse un hueco en el mercado dominado por los modelos <a title=\"info A6\" href=\"https:\/\/www.km77.com\/00\/audi\/a6\/2011\/audi-a6-precios.asp\" target=\"_blank\" rel=\"noopener\">Audi A6<\/a>, <a title=\"info Serie 5\" href=\"https:\/\/www.km77.com\/00\/bmw\/5\/2010\/t01.asp\" target=\"_blank\" rel=\"noopener\">BMW Serie 5<\/a> o <a title=\"info Clase E\" href=\"https:\/\/www.km77.com\/00\/mercedes-benz\/clase-e\/2013\/mb-clase-e-precio.asp\" target=\"_blank\" rel=\"noopener\">Mercedes-Benz Clase E<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lexus presenta la versi\u00f3n GS 250. Un modelo con motor V6 de gasolina de 209 CV con tracci\u00f3n trasera y cambio autom\u00e1tico de 6 velocidades \u2014con levas en el volante para funcionamiento secuencial\u2014 que se pondr\u00e1 a la venta por un precio de 59 600 \u20ac. El motor \u00ab4GR-FSE\u00bb V6 2,5 con inyecci\u00f3n directa D-4, [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3912],"tags":[414,4086,5,3940,22,5863,5864,5479,5480,1815,7837,2023,7801,7798,7808,3951],"class_list":{"0":"post-13419","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"hentry","6":"category-engendro-mecanico","7":"tag-audi-a6","8":"tag-berlina-de-lujo","9":"tag-bmw","10":"tag-clase-e","11":"tag-general","12":"tag-gs-250","13":"tag-gs-250-f-sport","14":"tag-gs-450h","15":"tag-gs-f-sport","16":"tag-lexus","18":"tag-mercedes-benz","19":"tag-noticias","20":"tag-novedades","21":"tag-nuevos-lanzamientos","22":"tag-serie-5"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lexus GS 250, nueva versi\u00f3n gasolina. Precio de venta: 59 600 \u20ac - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lexus GS 250, nueva versi\u00f3n gasolina. Precio de venta: 59 600 \u20ac - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Lexus presenta la versi\u00f3n GS 250. Un modelo con motor V6 de gasolina de 209 CV con tracci\u00f3n trasera y cambio autom\u00e1tico de 6 velocidades \u2014con levas en el volante para funcionamiento secuencial\u2014 que se pondr\u00e1 a la venta por un precio de 59 600 \u20ac. El motor \u00ab4GR-FSE\u00bb V6 2,5 con inyecci\u00f3n directa D-4, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-15T14:40:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T18:05:29+00:00\" \/>\n<meta name=\"author\" content=\"Loren Serrano (@EnzoNurburg)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Loren Serrano (@EnzoNurburg)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\\\/\"},\"author\":{\"name\":\"Loren Serrano (@EnzoNurburg)\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/d3c1bc483e384e2b2360fa1851eefbc5\"},\"headline\":\"Lexus GS 250, nueva versi\u00f3n gasolina. Precio de venta: 59 600 \u20ac\",\"datePublished\":\"2013-01-15T14:40:47+00:00\",\"dateModified\":\"2021-03-31T18:05:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\\\/\"},\"wordCount\":464,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"keywords\":[\"Audi A6\",\"berlina de lujo\",\"BMW\",\"Clase E\",\"General\",\"GS 250\",\"GS 250 F-Sport\",\"GS 450h\",\"GS F-Sport\",\"Lexus\",\"Lexus\",\"Mercedes-Benz\",\"Noticias\",\"Novedades\",\"Nuevos lanzamientos\",\"Serie 5\"],\"articleSection\":[\"Engendro Mec\u00e1nico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\\\/\",\"name\":\"Lexus GS 250, nueva versi\u00f3n gasolina. Precio de venta: 59 600 \u20ac - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"datePublished\":\"2013-01-15T14:40:47+00:00\",\"dateModified\":\"2021-03-31T18:05:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engendro Mec\u00e1nico\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lexus GS 250, nueva versi\u00f3n gasolina. Precio de venta: 59 600 \u20ac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Revista de km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/d3c1bc483e384e2b2360fa1851eefbc5\",\"name\":\"Loren Serrano (@EnzoNurburg)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g\",\"caption\":\"Loren Serrano (@EnzoNurburg)\"},\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/lorenzoserrano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lexus GS 250, nueva versi\u00f3n gasolina. Precio de venta: 59 600 \u20ac - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/","og_locale":"es_ES","og_type":"article","og_title":"Lexus GS 250, nueva versi\u00f3n gasolina. Precio de venta: 59 600 \u20ac - Revista km77","og_description":"Lexus presenta la versi\u00f3n GS 250. Un modelo con motor V6 de gasolina de 209 CV con tracci\u00f3n trasera y cambio autom\u00e1tico de 6 velocidades \u2014con levas en el volante para funcionamiento secuencial\u2014 que se pondr\u00e1 a la venta por un precio de 59 600 \u20ac. El motor \u00ab4GR-FSE\u00bb V6 2,5 con inyecci\u00f3n directa D-4, [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/","og_site_name":"Revista km77","article_published_time":"2013-01-15T14:40:47+00:00","article_modified_time":"2021-03-31T18:05:29+00:00","author":"Loren Serrano (@EnzoNurburg)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Loren Serrano (@EnzoNurburg)","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/"},"author":{"name":"Loren Serrano (@EnzoNurburg)","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/d3c1bc483e384e2b2360fa1851eefbc5"},"headline":"Lexus GS 250, nueva versi\u00f3n gasolina. Precio de venta: 59 600 \u20ac","datePublished":"2013-01-15T14:40:47+00:00","dateModified":"2021-03-31T18:05:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/"},"wordCount":464,"commentCount":0,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"keywords":["Audi A6","berlina de lujo","BMW","Clase E","General","GS 250","GS 250 F-Sport","GS 450h","GS F-Sport","Lexus","Lexus","Mercedes-Benz","Noticias","Novedades","Nuevos lanzamientos","Serie 5"],"articleSection":["Engendro Mec\u00e1nico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/","url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/","name":"Lexus GS 250, nueva versi\u00f3n gasolina. Precio de venta: 59 600 \u20ac - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"datePublished":"2013-01-15T14:40:47+00:00","dateModified":"2021-03-31T18:05:29+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/lexus-gs-250-nueva-version-gasolina-precio-de-venta-59-600-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Engendro Mec\u00e1nico","item":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/"},{"@type":"ListItem","position":3,"name":"Lexus GS 250, nueva versi\u00f3n gasolina. Precio de venta: 59 600 \u20ac"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Revista de km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/d3c1bc483e384e2b2360fa1851eefbc5","name":"Loren Serrano (@EnzoNurburg)","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97a404168206b85c6f86ca89682724291cda73b780eb640de54a3d93f76ec500?s=96&d=mm&r=g","caption":"Loren Serrano (@EnzoNurburg)"},"url":"https:\/\/www.km77.com\/revista\/author\/lorenzoserrano\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/13419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=13419"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/13419\/revisions"}],"predecessor-version":[{"id":43281,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/13419\/revisions\/43281"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=13419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=13419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=13419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}