{"id":1052,"date":"2011-02-03T15:19:21","date_gmt":"2011-02-03T14:19:21","guid":{"rendered":"http:\/\/blogs.km77.com\/engendromecanico\/?p=1052"},"modified":"2021-03-31T20:11:11","modified_gmt":"2021-03-31T18:11:11","slug":"slalom-2011-ya-llega-la-primera-carrera","status":"publish","type":"post","link":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/","title":{"rendered":"Slalom 2011. Ya llega la primera carrera&#8230;"},"content":{"rendered":"<p>Atr\u00e1s quedan las prisas por dejar a \u00faltima hora los tramites de la licencia y la inscripci\u00f3n en la carrera. Pero parece ser que no he sido el m\u00e1s perezoso porque por primera vez (o eso creo) en estos dos a\u00f1os que llevo participando en el Campeonato, hay gente que se ha quedado fuera porque la inscripci\u00f3n est\u00e1 cubierta y <strong>las cuarenta plazas ocupadas<\/strong>. Quedan cinco participantes en la reserva. Esperemos que al final se les pueda hacer un hueco.<br \/>\nLa carrera es este s\u00e1bado (cinco de febrero), en el Autodrome, que es el nombre de la pista que se monta en la zona\u00a0 del aparcamiento sur de la Feria de Muestras de Zaragoza durante el Motor Show Festival. Los <strong>entrenamientos comienzan a las 10:00, la primera manga a las 11:00 y la segunda a las 12:30<\/strong>. Entre las dos mangas saldr\u00e1n alguno de los Ferraris de competici\u00f3n expuestos a pista.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-full wp-image-1054 aligncenter\" title=\"plano\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/02\/plano.jpg\" alt=\"plano\" width=\"650\" height=\"491\" srcset=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/02\/plano.jpg 650w, https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/02\/plano-480x363.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 650px, 100vw\" \/><\/p>\n<p>Este a\u00f1o hay novedades importantes en la lista de \u00abenemigos\u00bb. De mi categor\u00eda se ha ido Francho Echegoyen y su <a href=\"https:\/\/www.km77.com\/00\/abarth\/500c\/2010\/descapotable_motor.asp\" target=\"_blank\" rel=\"noopener\">Abarth 500C<\/a>, que se pasa a competici\u00f3n (supongo que habr\u00e1 montado el kit esseesse). Tambi\u00e9n hay un cambio a la inversa: el campe\u00f3n de la categor\u00eda de compeci\u00f3n, <strong>Pablo Fortu\u00f1o<\/strong>,\u00a0 viene a hacerme la pu\u00f1eta a la de serie con un <a href=\"https:\/\/www.km77.com\/marcas\/renault\/clio_04\/sport\/texto.asp\" target=\"_blank\" rel=\"noopener\">Clio RS<\/a>. Adem\u00e1s, Themis, <a href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/\/2010\/11\/29\/slalom-2010-ultima-carrera-estrategia-suerte-y-themis\/\" target=\"_blank\" rel=\"noopener\">famoso ya en este blog por cederme su b\u00f3lido<\/a> (<a href=\"https:\/\/www.km77.com\/00\/alfa\/mito\/t01.asp\" target=\"_blank\" rel=\"noopener\">Alfa Romeo MiTo<\/a>) en la \u00faltima carrera, ser\u00e1 otro rival dif\u00edcil al que batir durante toda la temporada. Y novedosa es la aparici\u00f3n de dos nuevos participantes con un MINI Cooper S. Vamos, que cada vez hay mejores coches y la victoria se complica. Y esto sin contar a los habituales que repiten este a\u00f1o&#8230;<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-full wp-image-1053 aligncenter\" title=\"inscripcion\" src=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/02\/inscripcion.jpg\" alt=\"inscripcion\" width=\"433\" height=\"641\" \/><\/p>\n<p>En la lista, como pod\u00e9is ver, hay aparatos como un M3, un Mustang y cuatro car-cross&#8230;\u00a1y tambi\u00e9n un Renault 5 1.1!. As\u00ed que, de una forma u otra, el espect\u00e1culo est\u00e1 asegurado.<\/p>\n<p style=\"text-align: right;\"><em><strong>Alfonso Herrero<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atr\u00e1s quedan las prisas por dejar a \u00faltima hora los tramites de la licencia y la inscripci\u00f3n en la carrera. Pero parece ser que no he sido el m\u00e1s perezoso porque por primera vez (o eso creo) en estos dos a\u00f1os que llevo participando en el Campeonato, hay gente que se ha quedado fuera porque [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":33666,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3912],"tags":[3300,4651,641,4989,4654,4107,4843,22,4604,4696,4602,4884,2975,3178],"class_list":["post-1052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-engendro-mecanico","tag-alfonso-herrero","tag-aragon","tag-campeonato","tag-car-cross","tag-carrera","tag-fada","tag-feria-de-muestras","tag-general","tag-msf","tag-pablo-fortuno","tag-slalom","tag-themis","tag-toyota-yaris","tag-zaragoza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Slalom 2011. Ya llega la primera carrera... - Revista km77<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slalom 2011. Ya llega la primera carrera... - Revista km77\" \/>\n<meta property=\"og:description\" content=\"Atr\u00e1s quedan las prisas por dejar a \u00faltima hora los tramites de la licencia y la inscripci\u00f3n en la carrera. Pero parece ser que no he sido el m\u00e1s perezoso porque por primera vez (o eso creo) en estos dos a\u00f1os que llevo participando en el Campeonato, hay gente que se ha quedado fuera porque [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista km77\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-03T14:19:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T18:11:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/02\/inscripcion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"433\" \/>\n\t<meta property=\"og:image:height\" content=\"641\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Celedonio y Cogolludo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Celedonio y Cogolludo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/\"},\"author\":{\"name\":\"Celedonio y Cogolludo\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/a7115fd8d0381d5ef55688376f7fbfe2\"},\"headline\":\"Slalom 2011. Ya llega la primera carrera&#8230;\",\"datePublished\":\"2011-02-03T14:19:21+00:00\",\"dateModified\":\"2021-03-31T18:11:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/\"},\"wordCount\":341,\"commentCount\":8,\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/inscripcion.jpg\",\"keywords\":[\"Alfonso Herrero\",\"aragon\",\"Campeonato\",\"car cross\",\"carrera\",\"FADA\",\"Feria de Muestras\",\"General\",\"MSF\",\"Pablo Fortu\u00f1o\",\"Slalom\",\"themis\",\"Toyota Yaris\",\"Zaragoza\"],\"articleSection\":[\"Engendro Mec\u00e1nico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/\",\"name\":\"Slalom 2011. Ya llega la primera carrera... - Revista km77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/inscripcion.jpg\",\"datePublished\":\"2011-02-03T14:19:21+00:00\",\"dateModified\":\"2021-03-31T18:11:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/inscripcion.jpg\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/inscripcion.jpg\",\"width\":433,\"height\":641},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/slalom-2011-ya-llega-la-primera-carrera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Revista km77\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engendro Mec\u00e1nico\",\"item\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/engendro-mecanico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Slalom 2011. Ya llega la primera carrera&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"name\":\"Revista km77\",\"description\":\"Revista de km77\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#organization\",\"name\":\"KM77\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"contentUrl\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-km77.png\",\"width\":100,\"height\":34,\"caption\":\"KM77\"},\"image\":{\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/#\\\/schema\\\/person\\\/a7115fd8d0381d5ef55688376f7fbfe2\",\"name\":\"Celedonio y Cogolludo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g\",\"caption\":\"Celedonio y Cogolludo\"},\"url\":\"https:\\\/\\\/www.km77.com\\\/revista\\\/author\\\/celedoniycogolludo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Slalom 2011. Ya llega la primera carrera... - Revista km77","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/","og_locale":"es_ES","og_type":"article","og_title":"Slalom 2011. Ya llega la primera carrera... - Revista km77","og_description":"Atr\u00e1s quedan las prisas por dejar a \u00faltima hora los tramites de la licencia y la inscripci\u00f3n en la carrera. Pero parece ser que no he sido el m\u00e1s perezoso porque por primera vez (o eso creo) en estos dos a\u00f1os que llevo participando en el Campeonato, hay gente que se ha quedado fuera porque [&hellip;]","og_url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/","og_site_name":"Revista km77","article_published_time":"2011-02-03T14:19:21+00:00","article_modified_time":"2021-03-31T18:11:11+00:00","og_image":[{"width":433,"height":641,"url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/02\/inscripcion.jpg","type":"image\/jpeg"}],"author":"Celedonio y Cogolludo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Celedonio y Cogolludo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/#article","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/"},"author":{"name":"Celedonio y Cogolludo","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/a7115fd8d0381d5ef55688376f7fbfe2"},"headline":"Slalom 2011. Ya llega la primera carrera&#8230;","datePublished":"2011-02-03T14:19:21+00:00","dateModified":"2021-03-31T18:11:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/"},"wordCount":341,"commentCount":8,"publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/02\/inscripcion.jpg","keywords":["Alfonso Herrero","aragon","Campeonato","car cross","carrera","FADA","Feria de Muestras","General","MSF","Pablo Fortu\u00f1o","Slalom","themis","Toyota Yaris","Zaragoza"],"articleSection":["Engendro Mec\u00e1nico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/","url":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/","name":"Slalom 2011. Ya llega la primera carrera... - Revista km77","isPartOf":{"@id":"https:\/\/www.km77.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/#primaryimage"},"image":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/02\/inscripcion.jpg","datePublished":"2011-02-03T14:19:21+00:00","dateModified":"2021-03-31T18:11:11+00:00","breadcrumb":{"@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/#primaryimage","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/02\/inscripcion.jpg","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2011\/02\/inscripcion.jpg","width":433,"height":641},{"@type":"BreadcrumbList","@id":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/slalom-2011-ya-llega-la-primera-carrera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Revista km77","item":"https:\/\/www.km77.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Engendro Mec\u00e1nico","item":"https:\/\/www.km77.com\/revista\/engendro-mecanico\/"},{"@type":"ListItem","position":3,"name":"Slalom 2011. Ya llega la primera carrera&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.km77.com\/revista\/#website","url":"https:\/\/www.km77.com\/revista\/","name":"Revista km77","description":"Revista de km77","publisher":{"@id":"https:\/\/www.km77.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.km77.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.km77.com\/revista\/#organization","name":"KM77","url":"https:\/\/www.km77.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","contentUrl":"https:\/\/www.km77.com\/revista\/wp-content\/uploads\/2021\/02\/logo-km77.png","width":100,"height":34,"caption":"KM77"},"image":{"@id":"https:\/\/www.km77.com\/revista\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.km77.com\/revista\/#\/schema\/person\/a7115fd8d0381d5ef55688376f7fbfe2","name":"Celedonio y Cogolludo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/22289de263ee01b669543fa145009f723be21768109356ab573a3d80b0368f6c?s=96&d=mm&r=g","caption":"Celedonio y Cogolludo"},"url":"https:\/\/www.km77.com\/revista\/author\/celedoniycogolludo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/1052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/comments?post=1052"}],"version-history":[{"count":1,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/1052\/revisions"}],"predecessor-version":[{"id":44369,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/posts\/1052\/revisions\/44369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media\/33666"}],"wp:attachment":[{"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/media?parent=1052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/categories?post=1052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.km77.com\/revista\/wp-json\/wp\/v2\/tags?post=1052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}